{"id":12363,"date":"2017-06-05T09:55:04","date_gmt":"2017-06-05T09:55:04","guid":{"rendered":"http:\/\/feda.org\/feda2k16\/?p=12363"},"modified":"2017-06-05T09:55:04","modified_gmt":"2017-06-05T09:55:04","slug":"campeonato-del-mundo-rapido-y-relampago-sub-8-a-sub-12","status":"publish","type":"post","link":"https:\/\/feda.org\/feda2k16\/campeonato-del-mundo-rapido-y-relampago-sub-8-a-sub-12\/","title":{"rendered":"Campeonato del Mundo R\u00e1pido y Rel\u00e1mpago Sub-8 a Sub-12"},"content":{"rendered":"<p style=\"text-align: justify;\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-12369\" src=\"http:\/\/feda.org\/feda2k16\/wp-content\/uploads\/IMG-20170605-WA0000.jpg\" alt=\"\" width=\"600\" height=\"450\" srcset=\"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/IMG-20170605-WA0000.jpg 1024w, https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/IMG-20170605-WA0000-768x576.jpg 768w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/p>\n<p style=\"text-align: justify;\">Durante los d\u00edas 1 y 5 de junio se ha celebrado en Minsk, Bielorrusia, el primer Campeonato del Mundo R\u00e1pido y Rel\u00e1mpago para las categor\u00edas sub-8, sub-10 y sub-12. El jugador espa\u00f1ol Javier Habans ha participado en\u00a0la categor\u00eda sub-10 en los Campeonatos R\u00e1pido y Blitz.<\/p>\n<p style=\"text-align: justify;\">En el Campeonato del Mundo Blitz Sub-10, Javier finaliz\u00f3 und\u00e9cimo con 7 puntos. Empezaba el torneo desde la decimocuarta posici\u00f3n y \u00a0finaliz\u00f3 con los mismos puntos que el tercer clasificado, perdiendo solamente una partida en este campeonato.<\/p>\n<p style=\"text-align: justify;\">En el Campeonato del Mundo R\u00e1pido Sub-10, Javier termin\u00f3 en la cuadrag\u00e9sima posici\u00f3n con 5,5 puntos.<\/p>\n<p><a href=\"http:\/\/chess-school.by\/\">P\u00e1gina Web Oficial<\/a>.<\/p>\n<p>R\u00e1pido:\u00a0<a href=\"https:\/\/chess24.com\/es\/watch\/live-tournaments\/fide-world-cadet-championship-2017-rapid\/8\/1\/47\">Partidas en Chess24<\/a>.<\/p>\n<p>R\u00e1pido:\u00a0<a href=\"http:\/\/www.chess-results.com\/tnr281547.aspx?lan=2&amp;art=1&amp;rd=9&amp;fedb=ESP&amp;turdet=YES&amp;flag=30&amp;wi=984\">Clasificaci\u00f3n en Chess-Results<\/a>.<\/p>\n<p>Rel\u00e1mpago: <a href=\"https:\/\/chess24.com\/es\/watch\/live-tournaments\/fide-world-cadet-championship-2017-blitz\/9\/1\/45\">Partidas en Chess24<\/a>.<\/p>\n<p>Rel\u00e1mpago: <a href=\"http:\/\/www.chess-results.com\/tnr281553.aspx?lan=2&amp;art=1&amp;rd=9&amp;fedb=ESP&amp;turdet=YES&amp;flag=30&amp;wi=984\">Clasificaci\u00f3n en Chess-Results<\/a>.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-12367\" src=\"http:\/\/feda.org\/feda2k16\/wp-content\/uploads\/zakrytie_kadety5.jpg\" alt=\"\" width=\"600\" height=\"400\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 10pt;\">Ceremonia de Clausura.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante los d\u00edas 1 y 5 de junio se ha celebrado en Minsk, Bielorrusia, el primer Campeonato del Mundo R\u00e1pido y Rel\u00e1mpago para las categor\u00edas sub-8, sub-10 y sub-12. El jugador espa\u00f1ol Javier Habans ha participado en\u00a0la categor\u00eda sub-10 en los Campeonatos R\u00e1pido y Blitz. En el Campeonato del Mundo Blitz Sub-10, Javier finaliz\u00f3 und\u00e9cimo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-12363","post","type-post","status-publish","format-standard","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Campeonato del Mundo R\u00e1pido y Rel\u00e1mpago Sub-8 a Sub-12 - FEDA<\/title>\n<meta name=\"description\" content=\"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/feda.org\/feda2k16\/campeonato-del-mundo-rapido-y-relampago-sub-8-a-sub-12\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Campeonato del Mundo R\u00e1pido y Rel\u00e1mpago Sub-8 a Sub-12 - FEDA\" \/>\n<meta property=\"og:description\" content=\"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez\" \/>\n<meta property=\"og:url\" content=\"https:\/\/feda.org\/feda2k16\/campeonato-del-mundo-rapido-y-relampago-sub-8-a-sub-12\/\" \/>\n<meta property=\"og:site_name\" content=\"FEDA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/federacionespanoladeajedrez\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-05T09:55:04+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/feda.org\/feda2k16\/wp-content\/uploads\/IMG-20170605-WA0000.jpg\" \/>\n<meta name=\"author\" content=\"Nacho\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AjedrezEspanola\" \/>\n<meta name=\"twitter:site\" content=\"@AjedrezEspanola\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nacho\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-del-mundo-rapido-y-relampago-sub-8-a-sub-12\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-del-mundo-rapido-y-relampago-sub-8-a-sub-12\\\/\"},\"author\":{\"name\":\"Nacho\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/person\\\/6f81e48d83f6f1503890fdb658f2ff4e\"},\"headline\":\"Campeonato del Mundo R\u00e1pido y Rel\u00e1mpago Sub-8 a Sub-12\",\"datePublished\":\"2017-06-05T09:55:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-del-mundo-rapido-y-relampago-sub-8-a-sub-12\\\/\"},\"wordCount\":147,\"publisher\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-del-mundo-rapido-y-relampago-sub-8-a-sub-12\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/IMG-20170605-WA0000.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-del-mundo-rapido-y-relampago-sub-8-a-sub-12\\\/\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-del-mundo-rapido-y-relampago-sub-8-a-sub-12\\\/\",\"name\":\"Campeonato del Mundo R\u00e1pido y Rel\u00e1mpago Sub-8 a Sub-12 - FEDA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-del-mundo-rapido-y-relampago-sub-8-a-sub-12\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-del-mundo-rapido-y-relampago-sub-8-a-sub-12\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/IMG-20170605-WA0000.jpg\",\"datePublished\":\"2017-06-05T09:55:04+00:00\",\"description\":\"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-del-mundo-rapido-y-relampago-sub-8-a-sub-12\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-del-mundo-rapido-y-relampago-sub-8-a-sub-12\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-del-mundo-rapido-y-relampago-sub-8-a-sub-12\\\/#primaryimage\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/IMG-20170605-WA0000.jpg\",\"contentUrl\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/IMG-20170605-WA0000.jpg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-del-mundo-rapido-y-relampago-sub-8-a-sub-12\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Campeonato del Mundo R\u00e1pido y Rel\u00e1mpago Sub-8 a Sub-12\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#website\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/\",\"name\":\"FEDA\",\"description\":\"Federaci\u00f3n Espa\u00f1ola de Ajedrez\",\"publisher\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#organization\"},\"alternateName\":\"Federaci\u00f3n Espa\u00f1ola de Ajedrez\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#organization\",\"name\":\"FEDA\",\"alternateName\":\"Federaci\u00f3n Espa\u00f1ola de Ajedrez\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/NuevoLogo_FEDA_2016.png\",\"contentUrl\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/NuevoLogo_FEDA_2016.png\",\"width\":600,\"height\":600,\"caption\":\"FEDA\"},\"image\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/federacionespanoladeajedrez\\\/\",\"https:\\\/\\\/x.com\\\/AjedrezEspanola\",\"https:\\\/\\\/www.instagram.com\\\/federacionespanolaajedrez\\\/?hl=es\",\"https:\\\/\\\/www.youtube.com\\\/@FederacionEspanoladeAjedrezFED\\\/featured\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/person\\\/6f81e48d83f6f1503890fdb658f2ff4e\",\"name\":\"Nacho\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/author\\\/nacho\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Campeonato del Mundo R\u00e1pido y Rel\u00e1mpago Sub-8 a Sub-12 - FEDA","description":"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/feda.org\/feda2k16\/campeonato-del-mundo-rapido-y-relampago-sub-8-a-sub-12\/","og_locale":"es_ES","og_type":"article","og_title":"Campeonato del Mundo R\u00e1pido y Rel\u00e1mpago Sub-8 a Sub-12 - FEDA","og_description":"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez","og_url":"https:\/\/feda.org\/feda2k16\/campeonato-del-mundo-rapido-y-relampago-sub-8-a-sub-12\/","og_site_name":"FEDA","article_publisher":"https:\/\/www.facebook.com\/federacionespanoladeajedrez\/","article_published_time":"2017-06-05T09:55:04+00:00","og_image":[{"url":"http:\/\/feda.org\/feda2k16\/wp-content\/uploads\/IMG-20170605-WA0000.jpg","type":"","width":"","height":""}],"author":"Nacho","twitter_card":"summary_large_image","twitter_creator":"@AjedrezEspanola","twitter_site":"@AjedrezEspanola","twitter_misc":{"Escrito por":"Nacho","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/feda.org\/feda2k16\/campeonato-del-mundo-rapido-y-relampago-sub-8-a-sub-12\/#article","isPartOf":{"@id":"https:\/\/feda.org\/feda2k16\/campeonato-del-mundo-rapido-y-relampago-sub-8-a-sub-12\/"},"author":{"name":"Nacho","@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/person\/6f81e48d83f6f1503890fdb658f2ff4e"},"headline":"Campeonato del Mundo R\u00e1pido y Rel\u00e1mpago Sub-8 a Sub-12","datePublished":"2017-06-05T09:55:04+00:00","mainEntityOfPage":{"@id":"https:\/\/feda.org\/feda2k16\/campeonato-del-mundo-rapido-y-relampago-sub-8-a-sub-12\/"},"wordCount":147,"publisher":{"@id":"https:\/\/feda.org\/feda2k16\/#organization"},"image":{"@id":"https:\/\/feda.org\/feda2k16\/campeonato-del-mundo-rapido-y-relampago-sub-8-a-sub-12\/#primaryimage"},"thumbnailUrl":"http:\/\/feda.org\/feda2k16\/wp-content\/uploads\/IMG-20170605-WA0000.jpg","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/feda.org\/feda2k16\/campeonato-del-mundo-rapido-y-relampago-sub-8-a-sub-12\/","url":"https:\/\/feda.org\/feda2k16\/campeonato-del-mundo-rapido-y-relampago-sub-8-a-sub-12\/","name":"Campeonato del Mundo R\u00e1pido y Rel\u00e1mpago Sub-8 a Sub-12 - FEDA","isPartOf":{"@id":"https:\/\/feda.org\/feda2k16\/#website"},"primaryImageOfPage":{"@id":"https:\/\/feda.org\/feda2k16\/campeonato-del-mundo-rapido-y-relampago-sub-8-a-sub-12\/#primaryimage"},"image":{"@id":"https:\/\/feda.org\/feda2k16\/campeonato-del-mundo-rapido-y-relampago-sub-8-a-sub-12\/#primaryimage"},"thumbnailUrl":"http:\/\/feda.org\/feda2k16\/wp-content\/uploads\/IMG-20170605-WA0000.jpg","datePublished":"2017-06-05T09:55:04+00:00","description":"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez","breadcrumb":{"@id":"https:\/\/feda.org\/feda2k16\/campeonato-del-mundo-rapido-y-relampago-sub-8-a-sub-12\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/feda.org\/feda2k16\/campeonato-del-mundo-rapido-y-relampago-sub-8-a-sub-12\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/feda.org\/feda2k16\/campeonato-del-mundo-rapido-y-relampago-sub-8-a-sub-12\/#primaryimage","url":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/IMG-20170605-WA0000.jpg","contentUrl":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/IMG-20170605-WA0000.jpg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/feda.org\/feda2k16\/campeonato-del-mundo-rapido-y-relampago-sub-8-a-sub-12\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/feda.org\/feda2k16\/"},{"@type":"ListItem","position":2,"name":"Campeonato del Mundo R\u00e1pido y Rel\u00e1mpago Sub-8 a Sub-12"}]},{"@type":"WebSite","@id":"https:\/\/feda.org\/feda2k16\/#website","url":"https:\/\/feda.org\/feda2k16\/","name":"FEDA","description":"Federaci\u00f3n Espa\u00f1ola de Ajedrez","publisher":{"@id":"https:\/\/feda.org\/feda2k16\/#organization"},"alternateName":"Federaci\u00f3n Espa\u00f1ola de Ajedrez","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/feda.org\/feda2k16\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/feda.org\/feda2k16\/#organization","name":"FEDA","alternateName":"Federaci\u00f3n Espa\u00f1ola de Ajedrez","url":"https:\/\/feda.org\/feda2k16\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/logo\/image\/","url":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/NuevoLogo_FEDA_2016.png","contentUrl":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/NuevoLogo_FEDA_2016.png","width":600,"height":600,"caption":"FEDA"},"image":{"@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/federacionespanoladeajedrez\/","https:\/\/x.com\/AjedrezEspanola","https:\/\/www.instagram.com\/federacionespanolaajedrez\/?hl=es","https:\/\/www.youtube.com\/@FederacionEspanoladeAjedrezFED\/featured"]},{"@type":"Person","@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/person\/6f81e48d83f6f1503890fdb658f2ff4e","name":"Nacho","url":"https:\/\/feda.org\/feda2k16\/author\/nacho\/"}]}},"_links":{"self":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts\/12363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/comments?post=12363"}],"version-history":[{"count":1,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts\/12363\/revisions"}],"predecessor-version":[{"id":12370,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts\/12363\/revisions\/12370"}],"wp:attachment":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/media?parent=12363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/categories?post=12363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/tags?post=12363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}