{"id":13431,"date":"2018-03-02T08:16:00","date_gmt":"2018-03-02T08:16:00","guid":{"rendered":"http:\/\/feda.org\/feda2k16\/?p=13431"},"modified":"2018-03-02T12:45:43","modified_gmt":"2018-03-02T12:45:43","slug":"circular-06-2018-convocatoria-curso-nivel-i-galicia-01-2018","status":"publish","type":"post","link":"https:\/\/feda.org\/feda2k16\/circular-06-2018-convocatoria-curso-nivel-i-galicia-01-2018\/","title":{"rendered":"Circular 06\/2018 \u2013 Convocatoria Curso Nivel I Galicia 01\/2018"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>CONVOCATORIA CURSO DE MONITOR DE AJEDREZ NIVEL I.<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Promoci\u00f3n 1\/2018. Galicia.<\/strong><\/p>\n<p><a href=\"http:\/\/feda.org\/feda2k16\/wp-content\/uploads\/C06-Conv_Curso_Nivel-I-Galicia-01-2018..pdf\">Descargar en PDF<\/a>.<\/p>\n<p><a href=\"http:\/\/feda.org\/feda2k16\/wp-content\/uploads\/C-04_05_06_ANEXO-1_SOLICITUD-CONVALIDACION-CSD.pdf\">Anexo 1 &#8211; Solicitud Convalidaci\u00f3n CSD<\/a><\/p>\n<p><a href=\"http:\/\/feda.org\/feda2k16\/wp-content\/uploads\/C-04_05_06_ANEXO-2_FORMULARIO-DE-INSCRIPCI\u00d3N.xls\">Anexo 2 &#8211; Formulario de Inscripci\u00f3n<\/a><\/p>\n<p><a href=\"http:\/\/feda.org\/feda2k16\/wp-content\/uploads\/C-04_05_06_ANEXO-3_MODELO-TA.1.pdf\">Anexo 3 &#8211; Modelo TA.1<\/a><\/p>\n<p style=\"text-align: justify;\">La Federaci\u00f3n Espa\u00f1ola de Ajedrez, con la colaboraci\u00f3n de la Federaci\u00f3n Gallega de Ajedrez y del Centro Superior de Ense\u00f1anzas Deportivas del C.S.D., convoca la formaci\u00f3n de <strong>MONITOR DE AJEDREZ NIVEL I.<\/strong><\/p>\n<p style=\"text-align: justify;\">El curso est\u00e1 desarrollado al amparo de lo establecido en la Disposici\u00f3n Transitoria Primera en el Real Decreto 1363\/2007, de 24 de octubre, por el que se establece la ordenaci\u00f3n general de las ense\u00f1anzas deportivas de r\u00e9gimen especial y en la Orden ECD\/158\/2014, de 5 de febrero, por la que se regulan los aspectos curriculares, los requisitos generales y los efectos de las actividades de formaci\u00f3n deportiva a los que se refiere la mencionada Disposici\u00f3n Transitoria y la Resoluci\u00f3n de 18 de enero de 2013, de la Presidencia del Consejo Superior de Deportes, por la que se publica el Plan Formativo de la modalidad deportiva de Ajedrez.<\/p>\n<p style=\"text-align: justify;\">Dicho curso tendr\u00e1 el reconocimiento por parte de la Secretar\u00eda Xeral para o Deporte de la Xunta de Galicia, condicionado al cumplimiento de los requisitos establecidos en la mencionada Orden ECD\/158\/2014, de 5 de febrero, asumiendo la Federaci\u00f3n Espa\u00f1ola de Ajedrez (FEDA) la responsabilidad derivada por el incumplimiento de los mismos.<\/p>\n<p style=\"text-align: justify;\">Esta formaci\u00f3n est\u00e1 destinada a obtener el reconocimiento a efectos de correspondencia formativa una vez se publique el T\u00edtulo Oficial, seg\u00fan la norma que establezca el Ministerio de Educaci\u00f3n, Cultura y Deporte.<\/p>\n<p style=\"text-align: justify;\">El formato del curso ser\u00e1 \u201ca distancia\u201d, tanto para el Bloque Com\u00fan como para el Bloque Espec\u00edfico, salvo los ex\u00e1menes presenciales previstos para el final del curso.<\/p>\n<p style=\"text-align: justify;\">El Bloque Com\u00fan ser\u00e1 impartido por el Centro Superior de Ense\u00f1anzas Deportivas, a trav\u00e9s del Consejo Superior de Deportes, como organismo aut\u00f3nomo adscrito al Ministerio de Educaci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<ol>\n<li style=\"text-align: justify;\"><strong><u>Fechas y Lugares:<\/u><\/strong><\/li>\n<\/ol>\n<p style=\"text-align: justify;\"><u>\u00c1reas impartidas a distancia:<\/u><\/p>\n<ul style=\"text-align: justify;\">\n<li>Bloque Espec\u00edfico: del 02 de abril de 2018 al 24 de mayo de 2018.<\/li>\n<li>Bloque Com\u00fan: del 17 de septiembre de 2018 al 18 de noviembre de 2018.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><u>Ex\u00e1menes:<\/u><\/p>\n<p style=\"text-align: justify;\">En <strong>HOTEL SCALA PAZOS-PADR\u00d3N<\/strong> Ctra. N-550, S\/N, 15917 Padr\u00f3n, La Coru\u00f1a.<\/p>\n<ul style=\"text-align: justify;\">\n<li>Ex\u00e1menes ordinarios Bloque Espec\u00edfico: 26 de mayo de 2018 de 17:00 a 19:00 horas.<\/li>\n<li>Ex\u00e1menes Extraordinarios Bloque Espec\u00edfico: 30 de junio de 2018 de 17:00 a 19:00 horas.<\/li>\n<li>Ex\u00e1menes ordinarios Bloque Com\u00fan: 24 de noviembre de 2018 de 16:00 a 20:00 horas.<\/li>\n<li>Ex\u00e1menes Extraordinarios Bloque Com\u00fan: 15 de diciembre de 2018 de 16:00 a 20:00 horas<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<ol style=\"text-align: justify;\" start=\"2\">\n<li><strong><u>N\u00famero de Plazas y Selecci\u00f3n de Alumnos<\/u><\/strong><\/li>\n<\/ol>\n<p style=\"text-align: justify;\">El n\u00famero m\u00e1ximo de alumnos es de <strong>30<\/strong>.<\/p>\n<p style=\"text-align: justify;\">La selecci\u00f3n de los alumnos se realizar\u00e1 observando el orden siguiente:<\/p>\n<ol style=\"text-align: justify;\">\n<li>Diplomados como Monitores Superiores FEDA federados.<\/li>\n<li>Diplomados como Monitores Base FEDA federados.<\/li>\n<li>Monitores Auton\u00f3micos federados en su Federaci\u00f3n Auton\u00f3mica.<\/li>\n<li>Deportistas federados FEDA.<\/li>\n<\/ol>\n<p style=\"text-align: justify;\">Dentro de cada apartado, se seguir\u00e1 rigurosamente el orden de inscripci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">En su caso, se crear\u00e1 una lista de espera siguiendo el orden, para la cobertura de las posibles vacantes y que se tendr\u00e1 en cuenta como primer criterio de selecci\u00f3n en pr\u00f3ximas convocatorias.<\/p>\n<p style=\"text-align: justify;\">La FEDA se reserva el derecho de anular el curso en caso de no tener suficientes inscripciones.<\/p>\n<p>&nbsp;<\/p>\n<ol start=\"3\">\n<li style=\"text-align: justify;\"><strong><u>Requisitos de Acceso<\/u><\/strong><\/li>\n<\/ol>\n<ul style=\"text-align: justify;\">\n<li>T\u00edtulo de Graduado en ESO, equivalente (2\u00ba de BUP) o superior. En su defecto, ser\u00e1 v\u00e1lida tambi\u00e9n la Prueba de Madurez (convocada anualmente por el Servicio de Educaci\u00f3n correspondiente de cada Comunidad Aut\u00f3noma).<\/li>\n<li>Estar federado en la FEDA y tener al menos 1600 puntos de Elo FIDE en el momento de inicio del curso, o haberlos tenido en los dos a\u00f1os anteriores a la celebraci\u00f3n del mismo.<\/li>\n<li>Tener m\u00e1s de 16 a\u00f1os, o cumplirlos antes de la finalizaci\u00f3n del curso<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/p>\n<ol style=\"text-align: justify;\" start=\"4\">\n<li><strong><u>Inscripci\u00f3n y Cuotas<\/u><\/strong><\/li>\n<\/ol>\n<p style=\"text-align: justify;\">Plazo de Inscripci\u00f3n: Hasta el d\u00eda 30 de marzo.<\/p>\n<p style=\"text-align: justify;\">Las cutas de inscripci\u00f3n ser\u00e1n las siguientes:<\/p>\n<table class=\"mtr-table mtr-tr-td\">\n<tbody>\n<tr>\n<td width=\"229\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p><strong>\u00a0<\/strong><\/p>\n<\/div><\/td>\n<td width=\"229\" data-mtr-content=\"\nBloque Com\u00fan\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p><strong>Bloque Com\u00fan<\/strong><\/p>\n<\/div><\/td>\n<td width=\"231\" data-mtr-content=\"\nBloque Espec\u00edfico\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p><strong>Bloque Espec\u00edfico<\/strong><\/p>\n<\/div><\/td>\n<td width=\"229\" data-mtr-content=\"\nTotal\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p><strong>Total<\/strong><\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td width=\"229\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>Monitores FEDA Base o Superior con licencia en vigor<\/p>\n<\/div><\/td>\n<td width=\"229\" data-mtr-content=\"\nBloque Com\u00fan\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>180,00 \u20ac<\/p>\n<\/div><\/td>\n<td width=\"231\" data-mtr-content=\"\nBloque Espec\u00edfico\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>50,00 \u20ac<\/p>\n<\/div><\/td>\n<td width=\"229\" data-mtr-content=\"\nTotal\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>230,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td width=\"229\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>Resto de Alumnos<\/p>\n<\/div><\/td>\n<td width=\"229\" data-mtr-content=\"\nBloque Com\u00fan\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>180,00 \u20ac<\/p>\n<\/div><\/td>\n<td width=\"231\" data-mtr-content=\"\nBloque Espec\u00edfico\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>150,00 \u20ac<\/p>\n<\/div><\/td>\n<td width=\"229\" data-mtr-content=\"\nTotal\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>330,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify;\">La inscripci\u00f3n deber\u00e1 formalizarse en la FEDA, aportando la documentaci\u00f3n que se indica en el punto 9 y la copia del ingreso efectuado en la siguiente cuenta de la FEDA:<\/p>\n<p style=\"text-align: justify;\">IBERCAJA. IBAN: <strong>ES50 2085 8024 9503 0002 5965<\/strong><\/p>\n<p><strong>\u00a0<\/strong><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong><\/p>\n<p style=\"text-align: justify;\"><strong><u>Per\u00edodo de Pr\u00e1cticas<\/u><\/strong><\/p>\n<p style=\"text-align: justify;\">El per\u00edodo de pr\u00e1cticas ser\u00e1 de <strong>150 horas<\/strong> y se realizar\u00e1 en un plazo no superior a doce meses desde la publicaci\u00f3n de las notas del Bloque Espec\u00edfico. Se acreditar\u00e1 mediante la presentaci\u00f3n de un Certificado de Pr\u00e1cticas. Durante el periodo de realizaci\u00f3n de las pr\u00e1cticas los alumnos deber\u00e1n tener la licencia FEDA correspondiente a su situaci\u00f3n federativa, (Monitor Superior, de Base, o deportista), en vigor.<\/p>\n<p style=\"text-align: justify;\">El certificado ser\u00e1 expedido por las entidades de titularidad p\u00fablica o privada, o por las asociaciones deportivas en que se haya realizado el periodo de pr\u00e1cticas y firmado por el tutor y con el visto bueno de la FEDA.<\/p>\n<p style=\"text-align: justify;\">El tutor de pr\u00e1cticas deber\u00e1 ser Entrenador FEDA o FIDE Senior Trainer, debidamente federado durante el per\u00edodo de duraci\u00f3n de las pr\u00e1cticas que supervise.<\/p>\n<p>&nbsp;<\/p>\n<ol start=\"5\">\n<li style=\"text-align: justify;\"><strong><u>Compensaci\u00f3n de \u00c1reas del Bloque Com\u00fan<\/u><\/strong><\/li>\n<\/ol>\n<p style=\"text-align: justify;\">El Consejo Superior de Deportes reconoce las siguientes convalidaciones de las asignaturas del Bloque Com\u00fan LOE de T\u00e9cnicos Deportivos dependiendo de la formaci\u00f3n acad\u00e9mica que posea el alumno*:<\/p>\n<p style=\"text-align: justify;\"><strong>CCAFYD: <\/strong>Todo convalidado (Dependiendo del plan de estudios es posible que no convalide Primeros Auxilios).<\/p>\n<p style=\"text-align: justify;\"><strong>TAFAD: <\/strong>Todo convalidado.<\/p>\n<p style=\"text-align: justify;\"><strong>MAGISTERIO DE EDUCACI\u00d3N F\u00cdSICA: <\/strong>Actividad f\u00edsica adaptada y discapacidad; Bases del comportamiento deportivo. (Dependiendo del plan de estudios es posible que si convalide Primeros Auxilios).<\/p>\n<p style=\"text-align: justify;\"><strong>CONDUCCI\u00d3N DE ACTIVIDADES F\u00cdSICO-DEPORTIVAS EN EL MEDIO NATURAL: <\/strong>Actividad f\u00edsica adaptada y discapacidad; Bases del comportamiento deportivo; Primeros Auxilios. <strong><u>\u00a0<\/u><\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a0*La titulaci\u00f3n debe estar acabada, el CSD no reconoce a efectos de convalidaci\u00f3n del Bloque Com\u00fan LOE certificados de notas de estudios sin concluir. El alumno que no tenga acabados los estudios correspondientes, tendr\u00e1 que cursar todo el Bloque Com\u00fan.<\/p>\n<p style=\"text-align: justify;\">Ver Documento <strong>Anexo 1<\/strong> con la solicitud de convalidaci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<ol start=\"6\">\n<li style=\"text-align: justify;\"><strong><u>Exenci\u00f3n de Pr\u00e1cticas<\/u><\/strong><\/li>\n<\/ol>\n<p style=\"text-align: justify;\">El certificado de pr\u00e1cticas tambi\u00e9n podr\u00e1 ser expedido por la Administraci\u00f3n Deportiva competente para el reconocimiento de las actividades de formaci\u00f3n deportiva, siempre que la experiencia laboral o deportiva acredite <u>todas y cada una de las siguientes condiciones<\/u> est\u00e9 vinculada a los objetivos formativos y actividades; <u>sea superior a 300 horas; y se haya realizado, en su totalidad, antes del comienzo del bloque espec\u00edfico<\/u>, d\u00eda 2 de abril de 2018:<\/p>\n<ol>\n<li style=\"text-align: justify;\">La experiencia laboral se acreditar\u00e1 mediante la certificaci\u00f3n de la empresa donde haya adquirido dicha experiencia en la que conste espec\u00edficamente la duraci\u00f3n del contrato, la actividad desarrollada y el periodo de tiempo en el que se ha realizado la actividad (siempre con el alta correspondiente en la Seguridad Social por todo el per\u00edodo que se certifique).<\/li>\n<li style=\"text-align: justify;\">En el caso de trabajadores por cuenta propia, se exigir\u00e1 la certificaci\u00f3n de alta en el censo de obligados tributarios, con una antig\u00fcedad m\u00ednima de un a\u00f1o, as\u00ed como una declaraci\u00f3n del interesado de las actividades m\u00e1s representativas.<\/li>\n<li style=\"text-align: justify;\">Siempre que se acredite formaci\u00f3n, experiencia laboral o deportiva vinculada con el deporte escolar organizado y certificado por entidades locales, o Comunidades Aut\u00f3nomas, la duraci\u00f3n m\u00ednima exigida ser\u00e1 de 150 horas.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<ol start=\"7\">\n<li style=\"text-align: justify;\"><strong><u>Instrucciones de Matr\u00edcula e Inscripci\u00f3n<\/u><\/strong><\/li>\n<\/ol>\n<p style=\"text-align: justify;\">Los interesados en el Curso deber\u00e1n aportar la siguiente documentaci\u00f3n:<\/p>\n<p style=\"text-align: justify;\">&#8211; <strong>2 FORMULARIOS DE INSCRIPCI\u00d3N <\/strong>completados con todos los datos y <strong>FIRMADOS <\/strong>(se adjunta modelo de formulario de inscripci\u00f3n: <strong>Anexo 2<\/strong>).<\/p>\n<p style=\"text-align: justify;\">&#8211; <strong>2 COPIAS DEL DNI <u>EN VIGOR<\/u> <\/strong><\/p>\n<p style=\"text-align: justify;\">&#8211; <strong>2 COPIAS COMPULSADAS DEL T\u00cdTULO <\/strong>de ESO, equivalente (2\u00ba de BUP) o superior. En caso de no tener los estudios m\u00ednimos, ser\u00e1 v\u00e1lida tambi\u00e9n la Prueba de Madurez.<\/p>\n<p style=\"text-align: justify;\">&#8211; <strong>Si el alumno solicita la convalidaci\u00f3n <\/strong>total o parcial del bloque com\u00fan, en lugar de lo anterior, deber\u00e1 presentar 3 <strong>COPIAS COMPULSADAS <\/strong>del t\u00edtulo por el cual solicita dicha convalidaci\u00f3n: CCAFYD, TAFAD, MAGISTERIO DE EDUCACI\u00d3N F\u00cdSICA. La copia adicional es para el CSD. Y <strong>2 COPIAS <\/strong>del modelo de <strong>solicitud de convalidaci\u00f3n del CSD<\/strong>, completas, con todos los datos y firmadas.<\/p>\n<p style=\"text-align: justify;\"><strong>&#8211; S\u00d3LO PARA MENORES de 28 a\u00f1os<\/strong>: <strong>1 FOTOCOPIA del n\u00famero PROPIO DE AFILIACI\u00d3N A LA SEGURIDAD SOCIAL<\/strong>.<\/p>\n<p style=\"text-align: justify;\">En caso de que no hayan trabajado nunca por cuenta ajena, pueden obtenerlo en el momento en cualquier oficina de la S. Social. Para solicitarlo s\u00f3lo tienen que llevar el DNI y rellenar el modelo TA1 (se adjunta modelo de formulario de inscripci\u00f3n: <strong>Anexo 3<\/strong>).<\/p>\n<p style=\"text-align: justify;\">Este n\u00famero es para tramitar el seguro escolar y el tener n\u00ba propio no implica la p\u00e9rdida de derechos como beneficiario de la Seguridad Social de los padres o mutua sanitaria.<\/p>\n<p style=\"text-align: justify;\"><strong>-Si el alumno solicita la convalidaci\u00f3n <\/strong>del bloque espec\u00edfico, deber\u00e1 presentar 3 <strong>COPIAS COMPULSADAS <\/strong>del t\u00edtulo con los requisitos establecidos en el Punto 6.<\/p>\n<p style=\"text-align: justify;\"><strong>-Si el alumno solicita la exenci\u00f3n <\/strong>de las pr\u00e1cticas, deber\u00e1 presentar 3 <strong>COPIAS COMPULSADAS <\/strong>de la certificaci\u00f3n detallada en el Punto 8.<\/p>\n<p style=\"text-align: justify;\"><strong>-2 Fotograf\u00edas tama\u00f1o carnet <\/strong>(pueden ser enviadas digitalmente al correo <a href=\"mailto:formaci\u00f3n@feda.org\">formaci\u00f3n@feda.org<\/a> )<\/p>\n<p style=\"text-align: justify;\">En el momento de la inscripci\u00f3n se adjuntar\u00e1 una copia escaneada en formato pdf de la documentaci\u00f3n requerida, por e-mail a <a href=\"mailto:formacion@feda.org\"><strong>formacion@feda.org<\/strong><\/a><strong>. <\/strong>Una vez realizada la inscripci\u00f3n el alumno la enviar\u00e1 o entregar\u00e1 en mano en papel, en una de las siguientes direcciones y antes del 30 de marzo de 2018.<\/p>\n<table class=\" aligncenter\">\n<tbody>\n<tr>\n<td width=\"475\">\n<p>Federaci\u00f3n Espa\u00f1ola de Ajedrez<\/p>\n<p>C\/ Coslada, 10; 4\u00ba Interior<\/p>\n<p>28028 Madrid<\/p>\n<\/td>\n<td width=\"475\">\n<p>Federaci\u00f3n Gallega de Ajedrez<\/p>\n<p>C\/ Luis Ksado, N\u00ba 17 &#8211; Oficina 13<\/p>\n<p>36209 Vigo<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify;\">Los datos personales recogidos para la tramitaci\u00f3n de la Actividad de Formaci\u00f3n Deportiva (AFD), ser\u00e1n tratados conforme a la Ley Org\u00e1nica 15\/1999, de 13 de diciembre, de Protecci\u00f3n de Datos de Car\u00e1cter Personal. Su finalidad es la tramitaci\u00f3n de su solicitud y sus datos no ser\u00e1n cedidos ni usados para otro fin.<\/p>\n<p style=\"text-align: justify;\">El responsable de este fichero es: Federaci\u00f3n Espa\u00f1ola de Ajedrez, ante la cual podr\u00e1 ejercer, debidamente acreditado, los derechos de acceso, rectificaci\u00f3n, cancelaci\u00f3n y oposici\u00f3n de sus datos personales, dirigiendo su petici\u00f3n a C\/ Coslada, 10, 4\u00ba Dcha. 28028, Madrid e-mail <a href=\"mailto:ajedrez@feda.org\">ajedrez@feda.org<\/a><\/p>\n<p>&nbsp;<\/p>\n<ol start=\"8\">\n<li><strong><u>Certificaci\u00f3n y Titulaciones<\/u><\/strong><\/li>\n<\/ol>\n<p style=\"text-align: justify;\">A quienes superen con \u00e9xito la formaci\u00f3n del bloque com\u00fan, bloque espec\u00edfico y formaci\u00f3n pr\u00e1ctica, la Federaci\u00f3n Espa\u00f1ola de Ajedrez les expedir\u00e1 el DIPLOMA DE MONITOR DE AJEDREZ NIVEL I, figurando en el reverso del mismo la acreditaci\u00f3n diligenciada oportunamente por la Secretar\u00eda Xeral para o Deporte de la Xunta de Galicia, que ha autorizado la formaci\u00f3n y ser\u00e1n incluidos autom\u00e1ticamente en la base de datos de entrenadores de la FEDA.<\/p>\n<p style=\"text-align: justify;\">Este Diploma certifica el reconocimiento a efectos de correspondencia formativa una vez se publique el T\u00edtulo Deportivo oficial de Nivel I, mediante Real Decreto y seg\u00fan la normativa que establezca el Ministerio de Educaci\u00f3n, Cultura y Deporte.<\/p>\n<p style=\"text-align: justify;\">Toda la documentaci\u00f3n mencionada en la presente convocatoria se puede encontrar en:<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.feda.org\/web\/index.php\/comite-de-monitores\/convocatorias-de-cursos\">http:\/\/www.feda.org\/web\/index.php\/comite-de-monitores\/convocatorias-de-cursos<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>En Madrid, a 01 de marzo de 2018.<\/p>\n<p>&nbsp;<\/p>\n<p>Ram\u00f3n Padull\u00e9s Argerich<\/p>\n<p>Secretario General<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CONVOCATORIA CURSO DE MONITOR DE AJEDREZ NIVEL I. Promoci\u00f3n 1\/2018. Galicia. Descargar en PDF. Anexo 1 &#8211; Solicitud Convalidaci\u00f3n CSD Anexo 2 &#8211; Formulario de Inscripci\u00f3n Anexo 3 &#8211; Modelo TA.1 La Federaci\u00f3n Espa\u00f1ola de Ajedrez, con la colaboraci\u00f3n de la Federaci\u00f3n Gallega de Ajedrez y del Centro Superior de Ense\u00f1anzas Deportivas del C.S.D., convoca [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[169],"tags":[],"class_list":["post-13431","post","type-post","status-publish","format-standard","hentry","category-169"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Circular 06\/2018 \u2013 Convocatoria Curso Nivel I Galicia 01\/2018 - FEDA<\/title>\n<meta name=\"description\" content=\"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/feda.org\/feda2k16\/circular-06-2018-convocatoria-curso-nivel-i-galicia-01-2018\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Circular 06\/2018 \u2013 Convocatoria Curso Nivel I Galicia 01\/2018 - FEDA\" \/>\n<meta property=\"og:description\" content=\"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez\" \/>\n<meta property=\"og:url\" content=\"https:\/\/feda.org\/feda2k16\/circular-06-2018-convocatoria-curso-nivel-i-galicia-01-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"FEDA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/federacionespanoladeajedrez\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-02T08:16:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-03-02T12:45:43+00:00\" \/>\n<meta name=\"author\" content=\"Nacho\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AjedrezEspanola\" \/>\n<meta name=\"twitter:site\" content=\"@AjedrezEspanola\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nacho\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/circular-06-2018-convocatoria-curso-nivel-i-galicia-01-2018\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/circular-06-2018-convocatoria-curso-nivel-i-galicia-01-2018\\\/\"},\"author\":{\"name\":\"Nacho\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/person\\\/6f81e48d83f6f1503890fdb658f2ff4e\"},\"headline\":\"Circular 06\\\/2018 \u2013 Convocatoria Curso Nivel I Galicia 01\\\/2018\",\"datePublished\":\"2018-03-02T08:16:00+00:00\",\"dateModified\":\"2018-03-02T12:45:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/circular-06-2018-convocatoria-curso-nivel-i-galicia-01-2018\\\/\"},\"wordCount\":1900,\"publisher\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#organization\"},\"articleSection\":[\"2018\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/circular-06-2018-convocatoria-curso-nivel-i-galicia-01-2018\\\/\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/circular-06-2018-convocatoria-curso-nivel-i-galicia-01-2018\\\/\",\"name\":\"Circular 06\\\/2018 \u2013 Convocatoria Curso Nivel I Galicia 01\\\/2018 - FEDA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#website\"},\"datePublished\":\"2018-03-02T08:16:00+00:00\",\"dateModified\":\"2018-03-02T12:45:43+00:00\",\"description\":\"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/circular-06-2018-convocatoria-curso-nivel-i-galicia-01-2018\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/feda.org\\\/feda2k16\\\/circular-06-2018-convocatoria-curso-nivel-i-galicia-01-2018\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/circular-06-2018-convocatoria-curso-nivel-i-galicia-01-2018\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Circular 06\\\/2018 \u2013 Convocatoria Curso Nivel I Galicia 01\\\/2018\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#website\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/\",\"name\":\"FEDA\",\"description\":\"Federaci\u00f3n Espa\u00f1ola de Ajedrez\",\"publisher\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#organization\"},\"alternateName\":\"Federaci\u00f3n Espa\u00f1ola de Ajedrez\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#organization\",\"name\":\"FEDA\",\"alternateName\":\"Federaci\u00f3n Espa\u00f1ola de Ajedrez\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/NuevoLogo_FEDA_2016.png\",\"contentUrl\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/NuevoLogo_FEDA_2016.png\",\"width\":600,\"height\":600,\"caption\":\"FEDA\"},\"image\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/federacionespanoladeajedrez\\\/\",\"https:\\\/\\\/x.com\\\/AjedrezEspanola\",\"https:\\\/\\\/www.instagram.com\\\/federacionespanolaajedrez\\\/?hl=es\",\"https:\\\/\\\/www.youtube.com\\\/@FederacionEspanoladeAjedrezFED\\\/featured\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/person\\\/6f81e48d83f6f1503890fdb658f2ff4e\",\"name\":\"Nacho\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/author\\\/nacho\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Circular 06\/2018 \u2013 Convocatoria Curso Nivel I Galicia 01\/2018 - FEDA","description":"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/feda.org\/feda2k16\/circular-06-2018-convocatoria-curso-nivel-i-galicia-01-2018\/","og_locale":"es_ES","og_type":"article","og_title":"Circular 06\/2018 \u2013 Convocatoria Curso Nivel I Galicia 01\/2018 - FEDA","og_description":"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez","og_url":"https:\/\/feda.org\/feda2k16\/circular-06-2018-convocatoria-curso-nivel-i-galicia-01-2018\/","og_site_name":"FEDA","article_publisher":"https:\/\/www.facebook.com\/federacionespanoladeajedrez\/","article_published_time":"2018-03-02T08:16:00+00:00","article_modified_time":"2018-03-02T12:45:43+00:00","author":"Nacho","twitter_card":"summary_large_image","twitter_creator":"@AjedrezEspanola","twitter_site":"@AjedrezEspanola","twitter_misc":{"Escrito por":"Nacho","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/feda.org\/feda2k16\/circular-06-2018-convocatoria-curso-nivel-i-galicia-01-2018\/#article","isPartOf":{"@id":"https:\/\/feda.org\/feda2k16\/circular-06-2018-convocatoria-curso-nivel-i-galicia-01-2018\/"},"author":{"name":"Nacho","@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/person\/6f81e48d83f6f1503890fdb658f2ff4e"},"headline":"Circular 06\/2018 \u2013 Convocatoria Curso Nivel I Galicia 01\/2018","datePublished":"2018-03-02T08:16:00+00:00","dateModified":"2018-03-02T12:45:43+00:00","mainEntityOfPage":{"@id":"https:\/\/feda.org\/feda2k16\/circular-06-2018-convocatoria-curso-nivel-i-galicia-01-2018\/"},"wordCount":1900,"publisher":{"@id":"https:\/\/feda.org\/feda2k16\/#organization"},"articleSection":["2018"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/feda.org\/feda2k16\/circular-06-2018-convocatoria-curso-nivel-i-galicia-01-2018\/","url":"https:\/\/feda.org\/feda2k16\/circular-06-2018-convocatoria-curso-nivel-i-galicia-01-2018\/","name":"Circular 06\/2018 \u2013 Convocatoria Curso Nivel I Galicia 01\/2018 - FEDA","isPartOf":{"@id":"https:\/\/feda.org\/feda2k16\/#website"},"datePublished":"2018-03-02T08:16:00+00:00","dateModified":"2018-03-02T12:45:43+00:00","description":"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez","breadcrumb":{"@id":"https:\/\/feda.org\/feda2k16\/circular-06-2018-convocatoria-curso-nivel-i-galicia-01-2018\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/feda.org\/feda2k16\/circular-06-2018-convocatoria-curso-nivel-i-galicia-01-2018\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/feda.org\/feda2k16\/circular-06-2018-convocatoria-curso-nivel-i-galicia-01-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/feda.org\/feda2k16\/"},{"@type":"ListItem","position":2,"name":"Circular 06\/2018 \u2013 Convocatoria Curso Nivel I Galicia 01\/2018"}]},{"@type":"WebSite","@id":"https:\/\/feda.org\/feda2k16\/#website","url":"https:\/\/feda.org\/feda2k16\/","name":"FEDA","description":"Federaci\u00f3n Espa\u00f1ola de Ajedrez","publisher":{"@id":"https:\/\/feda.org\/feda2k16\/#organization"},"alternateName":"Federaci\u00f3n Espa\u00f1ola de Ajedrez","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/feda.org\/feda2k16\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/feda.org\/feda2k16\/#organization","name":"FEDA","alternateName":"Federaci\u00f3n Espa\u00f1ola de Ajedrez","url":"https:\/\/feda.org\/feda2k16\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/logo\/image\/","url":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/NuevoLogo_FEDA_2016.png","contentUrl":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/NuevoLogo_FEDA_2016.png","width":600,"height":600,"caption":"FEDA"},"image":{"@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/federacionespanoladeajedrez\/","https:\/\/x.com\/AjedrezEspanola","https:\/\/www.instagram.com\/federacionespanolaajedrez\/?hl=es","https:\/\/www.youtube.com\/@FederacionEspanoladeAjedrezFED\/featured"]},{"@type":"Person","@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/person\/6f81e48d83f6f1503890fdb658f2ff4e","name":"Nacho","url":"https:\/\/feda.org\/feda2k16\/author\/nacho\/"}]}},"_links":{"self":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts\/13431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/comments?post=13431"}],"version-history":[{"count":5,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts\/13431\/revisions"}],"predecessor-version":[{"id":13452,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts\/13431\/revisions\/13452"}],"wp:attachment":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/media?parent=13431"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/categories?post=13431"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/tags?post=13431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}