{"id":13634,"date":"2018-05-04T08:33:58","date_gmt":"2018-05-04T08:33:58","guid":{"rendered":"http:\/\/feda.org\/feda2k16\/?p=13634"},"modified":"2018-05-04T08:33:58","modified_gmt":"2018-05-04T08:33:58","slug":"v-campeonato-de-espana-por-equipos-de-colegios-sub-12","status":"publish","type":"post","link":"https:\/\/feda.org\/feda2k16\/v-campeonato-de-espana-por-equipos-de-colegios-sub-12\/","title":{"rendered":"V Campeonato de Espa\u00f1a por Equipos de Colegios Sub-12"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-13635\" src=\"http:\/\/feda.org\/feda2k16\/wp-content\/uploads\/31676602_1949703838673979_7126323640055889920_n.jpg\" alt=\"\" width=\"700\" height=\"344\" srcset=\"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/31676602_1949703838673979_7126323640055889920_n.jpg 960w, https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/31676602_1949703838673979_7126323640055889920_n-768x378.jpg 768w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/p>\n<p style=\"text-align: justify;\">Entre los d\u00edas 28 y 30 de abril se ha celebrado el V Campeonato de Espa\u00f1a por equipos de Colegios en Buitrago del Lozoya. El torneo, organizado conjuntamente por la Federaci\u00f3n Espa\u00f1ola de Ajedrez y la Federaci\u00f3n Madrile\u00f1a de Ajedrez, con la colaboraci\u00f3n del colegio Gredos San Diego y las empresas Ajedrez Con Cabeza y M\u00fasica con Cabeza, ha contado con 39 equipos de colegios procedentes de toda Espa\u00f1a. El colegio Marcos Frech\u00edn de Zaragoza se ha proclamado campe\u00f3n con 11 puntos. Mientras que los colegios Gredos San Diego de Madrid y Pedro I de Huesca, con 10 puntos, han ocupado la segunda y la tercera plaza respectivamente.<\/p>\n<p><a href=\"https:\/\/info64.org\/team\/iv-campeonato-de-espana-por-equipos-de-colegios-1\/standings\">Clasificaci\u00f3n en Info64<\/a><\/p>\n<p><a href=\"https:\/\/www.facebook.com\/pg\/federacionespanoladeajedrez\/photos\/?tab=album&amp;album_id=1948684022109294\">Galer\u00eda de Fotos<\/a><\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-13636\" src=\"http:\/\/feda.org\/feda2k16\/wp-content\/uploads\/1\u00ba-MARCOS-FRECHIN.jpg\" alt=\"\" width=\"700\" height=\"440\" srcset=\"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/1\u00ba-MARCOS-FRECHIN.jpg 960w, https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/1\u00ba-MARCOS-FRECHIN-768x483.jpg 768w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-13637\" src=\"http:\/\/feda.org\/feda2k16\/wp-content\/uploads\/2\u00ba-GREDOS-SAN-DIEGO-A.jpg\" alt=\"\" width=\"700\" height=\"416\" srcset=\"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/2\u00ba-GREDOS-SAN-DIEGO-A.jpg 960w, https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/2\u00ba-GREDOS-SAN-DIEGO-A-768x456.jpg 768w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-13638\" src=\"http:\/\/feda.org\/feda2k16\/wp-content\/uploads\/3\u00ba-PEDRO-I-A.jpg\" alt=\"\" width=\"700\" height=\"400\" srcset=\"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/3\u00ba-PEDRO-I-A.jpg 960w, https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/3\u00ba-PEDRO-I-A-768x438.jpg 768w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entre los d\u00edas 28 y 30 de abril se ha celebrado el V Campeonato de Espa\u00f1a por equipos de Colegios en Buitrago del Lozoya. El torneo, organizado conjuntamente por la Federaci\u00f3n Espa\u00f1ola de Ajedrez y la Federaci\u00f3n Madrile\u00f1a de Ajedrez, con la colaboraci\u00f3n del colegio Gredos San Diego y las empresas Ajedrez Con Cabeza y [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-13634","post","type-post","status-publish","format-standard","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>V Campeonato de Espa\u00f1a por Equipos de Colegios Sub-12 - FEDA<\/title>\n<meta name=\"description\" content=\"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/feda.org\/feda2k16\/v-campeonato-de-espana-por-equipos-de-colegios-sub-12\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"V Campeonato de Espa\u00f1a por Equipos de Colegios Sub-12 - FEDA\" \/>\n<meta property=\"og:description\" content=\"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez\" \/>\n<meta property=\"og:url\" content=\"https:\/\/feda.org\/feda2k16\/v-campeonato-de-espana-por-equipos-de-colegios-sub-12\/\" \/>\n<meta property=\"og:site_name\" content=\"FEDA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/federacionespanoladeajedrez\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-04T08:33:58+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/feda.org\/feda2k16\/wp-content\/uploads\/31676602_1949703838673979_7126323640055889920_n.jpg\" \/>\n<meta name=\"author\" content=\"Nacho\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AjedrezEspanola\" \/>\n<meta name=\"twitter:site\" content=\"@AjedrezEspanola\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nacho\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/v-campeonato-de-espana-por-equipos-de-colegios-sub-12\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/v-campeonato-de-espana-por-equipos-de-colegios-sub-12\\\/\"},\"author\":{\"name\":\"Nacho\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/person\\\/6f81e48d83f6f1503890fdb658f2ff4e\"},\"headline\":\"V Campeonato de Espa\u00f1a por Equipos de Colegios Sub-12\",\"datePublished\":\"2018-05-04T08:33:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/v-campeonato-de-espana-por-equipos-de-colegios-sub-12\\\/\"},\"wordCount\":132,\"publisher\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/v-campeonato-de-espana-por-equipos-de-colegios-sub-12\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/31676602_1949703838673979_7126323640055889920_n.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/v-campeonato-de-espana-por-equipos-de-colegios-sub-12\\\/\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/v-campeonato-de-espana-por-equipos-de-colegios-sub-12\\\/\",\"name\":\"V Campeonato de Espa\u00f1a por Equipos de Colegios Sub-12 - FEDA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/v-campeonato-de-espana-por-equipos-de-colegios-sub-12\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/v-campeonato-de-espana-por-equipos-de-colegios-sub-12\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/31676602_1949703838673979_7126323640055889920_n.jpg\",\"datePublished\":\"2018-05-04T08:33:58+00:00\",\"description\":\"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/v-campeonato-de-espana-por-equipos-de-colegios-sub-12\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/feda.org\\\/feda2k16\\\/v-campeonato-de-espana-por-equipos-de-colegios-sub-12\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/v-campeonato-de-espana-por-equipos-de-colegios-sub-12\\\/#primaryimage\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/31676602_1949703838673979_7126323640055889920_n.jpg\",\"contentUrl\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/31676602_1949703838673979_7126323640055889920_n.jpg\",\"width\":960,\"height\":472},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/v-campeonato-de-espana-por-equipos-de-colegios-sub-12\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"V Campeonato de Espa\u00f1a por Equipos de Colegios Sub-12\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#website\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/\",\"name\":\"FEDA\",\"description\":\"Federaci\u00f3n Espa\u00f1ola de Ajedrez\",\"publisher\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#organization\"},\"alternateName\":\"Federaci\u00f3n Espa\u00f1ola de Ajedrez\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#organization\",\"name\":\"FEDA\",\"alternateName\":\"Federaci\u00f3n Espa\u00f1ola de Ajedrez\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/NuevoLogo_FEDA_2016.png\",\"contentUrl\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/NuevoLogo_FEDA_2016.png\",\"width\":600,\"height\":600,\"caption\":\"FEDA\"},\"image\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/federacionespanoladeajedrez\\\/\",\"https:\\\/\\\/x.com\\\/AjedrezEspanola\",\"https:\\\/\\\/www.instagram.com\\\/federacionespanolaajedrez\\\/?hl=es\",\"https:\\\/\\\/www.youtube.com\\\/@FederacionEspanoladeAjedrezFED\\\/featured\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/person\\\/6f81e48d83f6f1503890fdb658f2ff4e\",\"name\":\"Nacho\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/author\\\/nacho\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"V Campeonato de Espa\u00f1a por Equipos de Colegios Sub-12 - FEDA","description":"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/feda.org\/feda2k16\/v-campeonato-de-espana-por-equipos-de-colegios-sub-12\/","og_locale":"es_ES","og_type":"article","og_title":"V Campeonato de Espa\u00f1a por Equipos de Colegios Sub-12 - FEDA","og_description":"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez","og_url":"https:\/\/feda.org\/feda2k16\/v-campeonato-de-espana-por-equipos-de-colegios-sub-12\/","og_site_name":"FEDA","article_publisher":"https:\/\/www.facebook.com\/federacionespanoladeajedrez\/","article_published_time":"2018-05-04T08:33:58+00:00","og_image":[{"url":"http:\/\/feda.org\/feda2k16\/wp-content\/uploads\/31676602_1949703838673979_7126323640055889920_n.jpg","type":"","width":"","height":""}],"author":"Nacho","twitter_card":"summary_large_image","twitter_creator":"@AjedrezEspanola","twitter_site":"@AjedrezEspanola","twitter_misc":{"Escrito por":"Nacho","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/feda.org\/feda2k16\/v-campeonato-de-espana-por-equipos-de-colegios-sub-12\/#article","isPartOf":{"@id":"https:\/\/feda.org\/feda2k16\/v-campeonato-de-espana-por-equipos-de-colegios-sub-12\/"},"author":{"name":"Nacho","@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/person\/6f81e48d83f6f1503890fdb658f2ff4e"},"headline":"V Campeonato de Espa\u00f1a por Equipos de Colegios Sub-12","datePublished":"2018-05-04T08:33:58+00:00","mainEntityOfPage":{"@id":"https:\/\/feda.org\/feda2k16\/v-campeonato-de-espana-por-equipos-de-colegios-sub-12\/"},"wordCount":132,"publisher":{"@id":"https:\/\/feda.org\/feda2k16\/#organization"},"image":{"@id":"https:\/\/feda.org\/feda2k16\/v-campeonato-de-espana-por-equipos-de-colegios-sub-12\/#primaryimage"},"thumbnailUrl":"http:\/\/feda.org\/feda2k16\/wp-content\/uploads\/31676602_1949703838673979_7126323640055889920_n.jpg","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/feda.org\/feda2k16\/v-campeonato-de-espana-por-equipos-de-colegios-sub-12\/","url":"https:\/\/feda.org\/feda2k16\/v-campeonato-de-espana-por-equipos-de-colegios-sub-12\/","name":"V Campeonato de Espa\u00f1a por Equipos de Colegios Sub-12 - FEDA","isPartOf":{"@id":"https:\/\/feda.org\/feda2k16\/#website"},"primaryImageOfPage":{"@id":"https:\/\/feda.org\/feda2k16\/v-campeonato-de-espana-por-equipos-de-colegios-sub-12\/#primaryimage"},"image":{"@id":"https:\/\/feda.org\/feda2k16\/v-campeonato-de-espana-por-equipos-de-colegios-sub-12\/#primaryimage"},"thumbnailUrl":"http:\/\/feda.org\/feda2k16\/wp-content\/uploads\/31676602_1949703838673979_7126323640055889920_n.jpg","datePublished":"2018-05-04T08:33:58+00:00","description":"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez","breadcrumb":{"@id":"https:\/\/feda.org\/feda2k16\/v-campeonato-de-espana-por-equipos-de-colegios-sub-12\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/feda.org\/feda2k16\/v-campeonato-de-espana-por-equipos-de-colegios-sub-12\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/feda.org\/feda2k16\/v-campeonato-de-espana-por-equipos-de-colegios-sub-12\/#primaryimage","url":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/31676602_1949703838673979_7126323640055889920_n.jpg","contentUrl":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/31676602_1949703838673979_7126323640055889920_n.jpg","width":960,"height":472},{"@type":"BreadcrumbList","@id":"https:\/\/feda.org\/feda2k16\/v-campeonato-de-espana-por-equipos-de-colegios-sub-12\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/feda.org\/feda2k16\/"},{"@type":"ListItem","position":2,"name":"V Campeonato de Espa\u00f1a por Equipos de Colegios Sub-12"}]},{"@type":"WebSite","@id":"https:\/\/feda.org\/feda2k16\/#website","url":"https:\/\/feda.org\/feda2k16\/","name":"FEDA","description":"Federaci\u00f3n Espa\u00f1ola de Ajedrez","publisher":{"@id":"https:\/\/feda.org\/feda2k16\/#organization"},"alternateName":"Federaci\u00f3n Espa\u00f1ola de Ajedrez","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/feda.org\/feda2k16\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/feda.org\/feda2k16\/#organization","name":"FEDA","alternateName":"Federaci\u00f3n Espa\u00f1ola de Ajedrez","url":"https:\/\/feda.org\/feda2k16\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/logo\/image\/","url":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/NuevoLogo_FEDA_2016.png","contentUrl":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/NuevoLogo_FEDA_2016.png","width":600,"height":600,"caption":"FEDA"},"image":{"@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/federacionespanoladeajedrez\/","https:\/\/x.com\/AjedrezEspanola","https:\/\/www.instagram.com\/federacionespanolaajedrez\/?hl=es","https:\/\/www.youtube.com\/@FederacionEspanoladeAjedrezFED\/featured"]},{"@type":"Person","@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/person\/6f81e48d83f6f1503890fdb658f2ff4e","name":"Nacho","url":"https:\/\/feda.org\/feda2k16\/author\/nacho\/"}]}},"_links":{"self":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts\/13634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/comments?post=13634"}],"version-history":[{"count":1,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts\/13634\/revisions"}],"predecessor-version":[{"id":13639,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts\/13634\/revisions\/13639"}],"wp:attachment":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/media?parent=13634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/categories?post=13634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/tags?post=13634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}