{"id":14423,"date":"2018-12-09T07:57:11","date_gmt":"2018-12-09T07:57:11","guid":{"rendered":"http:\/\/feda.org\/feda2k16\/?p=14423"},"modified":"2018-12-09T08:00:49","modified_gmt":"2018-12-09T08:00:49","slug":"campeonato-de-europa-relampago-y-rapido","status":"publish","type":"post","link":"https:\/\/feda.org\/feda2k16\/campeonato-de-europa-relampago-y-rapido\/","title":{"rendered":"Campeonato de Europa Rel\u00e1mpago y R\u00e1pido"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-14424\" src=\"http:\/\/feda.org\/feda2k16\/wp-content\/uploads\/47684954_10217895940570855_5997883294417420288_o.jpg\" alt=\"\" width=\"700\" height=\"467\" srcset=\"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/47684954_10217895940570855_5997883294417420288_o.jpg 2048w, https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/47684954_10217895940570855_5997883294417420288_o-768x512.jpg 768w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/p>\n<p style=\"text-align: justify;\">Iv\u00e1n Salgado ha finalizado octavo en el Campeonato de Europa Rel\u00e1mpago celebrado en Skopje, Macedonia, durante los d\u00edas 6 y 7 de diciembre. Iv\u00e1n ha sumado 15,5 puntos con un performance de 2663 y una subida de 97,2 puntos de ELO rel\u00e1mpago.<\/p>\n<p style=\"text-align: justify;\">En el Campeonato de Europa R\u00e1pido, David Ant\u00f3n se encuentra clasificado en segunda posici\u00f3n, con 6 puntos, tras haber perdido una sola partida ante el azer\u00ed Rauf Mamedov.<\/p>\n<p style=\"text-align: justify;\">A partir de las 11:00h, las \u00faltimas 6 partidas del Campeonato de Europa R\u00e1pido se pueden seguir en directo a trav\u00e9s de chess24 en el siguiente <a href=\"https:\/\/chess24.com\/es\/watch\/live-tournaments\/european-rapid-2018#live\">enlace<\/a>.<\/p>\n<p><a href=\"https:\/\/eirbcc2018.com.mk\/\">P\u00e1gina Oficial del Torneo<\/a><\/p>\n<p><a href=\"https:\/\/chess24.com\/es\/watch\/live-tournaments\/european-rapid-2018#live\">Partidas en Chess24<\/a><\/p>\n<p><a href=\"http:\/\/chess-results.com\/tnr395945.aspx?lan=2&amp;art=1&amp;flag=30\">Clasificaci\u00f3n<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Iv\u00e1n Salgado ha finalizado octavo en el Campeonato de Europa Rel\u00e1mpago celebrado en Skopje, Macedonia, durante los d\u00edas 6 y 7 de diciembre. Iv\u00e1n ha sumado 15,5 puntos con un performance de 2663 y una subida de 97,2 puntos de ELO rel\u00e1mpago. En el Campeonato de Europa R\u00e1pido, David Ant\u00f3n se encuentra clasificado en segunda [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-14423","post","type-post","status-publish","format-standard","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Campeonato de Europa Rel\u00e1mpago y R\u00e1pido - FEDA<\/title>\n<meta name=\"description\" content=\"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/feda.org\/feda2k16\/campeonato-de-europa-relampago-y-rapido\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Campeonato de Europa Rel\u00e1mpago y R\u00e1pido - FEDA\" \/>\n<meta property=\"og:description\" content=\"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez\" \/>\n<meta property=\"og:url\" content=\"https:\/\/feda.org\/feda2k16\/campeonato-de-europa-relampago-y-rapido\/\" \/>\n<meta property=\"og:site_name\" content=\"FEDA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/federacionespanoladeajedrez\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-09T07:57:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-09T08:00:49+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/feda.org\/feda2k16\/wp-content\/uploads\/47684954_10217895940570855_5997883294417420288_o.jpg\" \/>\n<meta name=\"author\" content=\"Nacho\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AjedrezEspanola\" \/>\n<meta name=\"twitter:site\" content=\"@AjedrezEspanola\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nacho\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-de-europa-relampago-y-rapido\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-de-europa-relampago-y-rapido\\\/\"},\"author\":{\"name\":\"Nacho\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/person\\\/6f81e48d83f6f1503890fdb658f2ff4e\"},\"headline\":\"Campeonato de Europa Rel\u00e1mpago y R\u00e1pido\",\"datePublished\":\"2018-12-09T07:57:11+00:00\",\"dateModified\":\"2018-12-09T08:00:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-de-europa-relampago-y-rapido\\\/\"},\"wordCount\":118,\"publisher\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-de-europa-relampago-y-rapido\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/47684954_10217895940570855_5997883294417420288_o.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-de-europa-relampago-y-rapido\\\/\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-de-europa-relampago-y-rapido\\\/\",\"name\":\"Campeonato de Europa Rel\u00e1mpago y R\u00e1pido - FEDA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-de-europa-relampago-y-rapido\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-de-europa-relampago-y-rapido\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/47684954_10217895940570855_5997883294417420288_o.jpg\",\"datePublished\":\"2018-12-09T07:57:11+00:00\",\"dateModified\":\"2018-12-09T08:00:49+00:00\",\"description\":\"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-de-europa-relampago-y-rapido\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-de-europa-relampago-y-rapido\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-de-europa-relampago-y-rapido\\\/#primaryimage\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/47684954_10217895940570855_5997883294417420288_o.jpg\",\"contentUrl\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/47684954_10217895940570855_5997883294417420288_o.jpg\",\"width\":2048,\"height\":1365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-de-europa-relampago-y-rapido\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Campeonato de Europa Rel\u00e1mpago y R\u00e1pido\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#website\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/\",\"name\":\"FEDA\",\"description\":\"Federaci\u00f3n Espa\u00f1ola de Ajedrez\",\"publisher\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#organization\"},\"alternateName\":\"Federaci\u00f3n Espa\u00f1ola de Ajedrez\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#organization\",\"name\":\"FEDA\",\"alternateName\":\"Federaci\u00f3n Espa\u00f1ola de Ajedrez\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/NuevoLogo_FEDA_2016.png\",\"contentUrl\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/NuevoLogo_FEDA_2016.png\",\"width\":600,\"height\":600,\"caption\":\"FEDA\"},\"image\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/federacionespanoladeajedrez\\\/\",\"https:\\\/\\\/x.com\\\/AjedrezEspanola\",\"https:\\\/\\\/www.instagram.com\\\/federacionespanolaajedrez\\\/?hl=es\",\"https:\\\/\\\/www.youtube.com\\\/@FederacionEspanoladeAjedrezFED\\\/featured\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/person\\\/6f81e48d83f6f1503890fdb658f2ff4e\",\"name\":\"Nacho\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/author\\\/nacho\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Campeonato de Europa Rel\u00e1mpago y R\u00e1pido - FEDA","description":"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/feda.org\/feda2k16\/campeonato-de-europa-relampago-y-rapido\/","og_locale":"es_ES","og_type":"article","og_title":"Campeonato de Europa Rel\u00e1mpago y R\u00e1pido - FEDA","og_description":"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez","og_url":"https:\/\/feda.org\/feda2k16\/campeonato-de-europa-relampago-y-rapido\/","og_site_name":"FEDA","article_publisher":"https:\/\/www.facebook.com\/federacionespanoladeajedrez\/","article_published_time":"2018-12-09T07:57:11+00:00","article_modified_time":"2018-12-09T08:00:49+00:00","og_image":[{"url":"http:\/\/feda.org\/feda2k16\/wp-content\/uploads\/47684954_10217895940570855_5997883294417420288_o.jpg","type":"","width":"","height":""}],"author":"Nacho","twitter_card":"summary_large_image","twitter_creator":"@AjedrezEspanola","twitter_site":"@AjedrezEspanola","twitter_misc":{"Escrito por":"Nacho","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/feda.org\/feda2k16\/campeonato-de-europa-relampago-y-rapido\/#article","isPartOf":{"@id":"https:\/\/feda.org\/feda2k16\/campeonato-de-europa-relampago-y-rapido\/"},"author":{"name":"Nacho","@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/person\/6f81e48d83f6f1503890fdb658f2ff4e"},"headline":"Campeonato de Europa Rel\u00e1mpago y R\u00e1pido","datePublished":"2018-12-09T07:57:11+00:00","dateModified":"2018-12-09T08:00:49+00:00","mainEntityOfPage":{"@id":"https:\/\/feda.org\/feda2k16\/campeonato-de-europa-relampago-y-rapido\/"},"wordCount":118,"publisher":{"@id":"https:\/\/feda.org\/feda2k16\/#organization"},"image":{"@id":"https:\/\/feda.org\/feda2k16\/campeonato-de-europa-relampago-y-rapido\/#primaryimage"},"thumbnailUrl":"http:\/\/feda.org\/feda2k16\/wp-content\/uploads\/47684954_10217895940570855_5997883294417420288_o.jpg","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/feda.org\/feda2k16\/campeonato-de-europa-relampago-y-rapido\/","url":"https:\/\/feda.org\/feda2k16\/campeonato-de-europa-relampago-y-rapido\/","name":"Campeonato de Europa Rel\u00e1mpago y R\u00e1pido - FEDA","isPartOf":{"@id":"https:\/\/feda.org\/feda2k16\/#website"},"primaryImageOfPage":{"@id":"https:\/\/feda.org\/feda2k16\/campeonato-de-europa-relampago-y-rapido\/#primaryimage"},"image":{"@id":"https:\/\/feda.org\/feda2k16\/campeonato-de-europa-relampago-y-rapido\/#primaryimage"},"thumbnailUrl":"http:\/\/feda.org\/feda2k16\/wp-content\/uploads\/47684954_10217895940570855_5997883294417420288_o.jpg","datePublished":"2018-12-09T07:57:11+00:00","dateModified":"2018-12-09T08:00:49+00:00","description":"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez","breadcrumb":{"@id":"https:\/\/feda.org\/feda2k16\/campeonato-de-europa-relampago-y-rapido\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/feda.org\/feda2k16\/campeonato-de-europa-relampago-y-rapido\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/feda.org\/feda2k16\/campeonato-de-europa-relampago-y-rapido\/#primaryimage","url":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/47684954_10217895940570855_5997883294417420288_o.jpg","contentUrl":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/47684954_10217895940570855_5997883294417420288_o.jpg","width":2048,"height":1365},{"@type":"BreadcrumbList","@id":"https:\/\/feda.org\/feda2k16\/campeonato-de-europa-relampago-y-rapido\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/feda.org\/feda2k16\/"},{"@type":"ListItem","position":2,"name":"Campeonato de Europa Rel\u00e1mpago y R\u00e1pido"}]},{"@type":"WebSite","@id":"https:\/\/feda.org\/feda2k16\/#website","url":"https:\/\/feda.org\/feda2k16\/","name":"FEDA","description":"Federaci\u00f3n Espa\u00f1ola de Ajedrez","publisher":{"@id":"https:\/\/feda.org\/feda2k16\/#organization"},"alternateName":"Federaci\u00f3n Espa\u00f1ola de Ajedrez","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/feda.org\/feda2k16\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/feda.org\/feda2k16\/#organization","name":"FEDA","alternateName":"Federaci\u00f3n Espa\u00f1ola de Ajedrez","url":"https:\/\/feda.org\/feda2k16\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/logo\/image\/","url":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/NuevoLogo_FEDA_2016.png","contentUrl":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/NuevoLogo_FEDA_2016.png","width":600,"height":600,"caption":"FEDA"},"image":{"@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/federacionespanoladeajedrez\/","https:\/\/x.com\/AjedrezEspanola","https:\/\/www.instagram.com\/federacionespanolaajedrez\/?hl=es","https:\/\/www.youtube.com\/@FederacionEspanoladeAjedrezFED\/featured"]},{"@type":"Person","@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/person\/6f81e48d83f6f1503890fdb658f2ff4e","name":"Nacho","url":"https:\/\/feda.org\/feda2k16\/author\/nacho\/"}]}},"_links":{"self":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts\/14423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/comments?post=14423"}],"version-history":[{"count":4,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts\/14423\/revisions"}],"predecessor-version":[{"id":14426,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts\/14423\/revisions\/14426"}],"wp:attachment":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/media?parent=14423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/categories?post=14423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/tags?post=14423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}