{"id":1448,"date":"2015-03-03T10:24:34","date_gmt":"2015-03-03T10:24:34","guid":{"rendered":"http:\/\/localhost:8888\/feda2k16\/?p=1448"},"modified":"2017-12-11T10:58:10","modified_gmt":"2017-12-11T10:58:10","slug":"circular-10-2015-evaluacion-elo-2015","status":"publish","type":"post","link":"https:\/\/feda.org\/feda2k16\/circular-10-2015-evaluacion-elo-2015\/","title":{"rendered":"Circular 10\/2015 &#8211; Evaluaci\u00f3n Elo 2015"},"content":{"rendered":"<p align=\"center\">\n <strong>A TODAS LAS FEDERACIONES AUTON\u00d3MICAS Y \u00c1RBITROS FEDA<\/strong><\/p>\n<p align=\"center\"><strong>Ref.: Informes, Evaluaci\u00f3n de Torneos y Elo 2015.<\/strong><\/p>\n<p><a href=\"http:\/\/feda.org\/feda2k16\/wp-content\/uploads\/C10-Evaluaci\u00f3n-Elo-2015.pdf\">Descargar en PDF<\/a><\/p>\n<p>&nbsp;<\/p>\n<p style=\"margin-left: 40px;\"><strong>A. Elo FEDA:<\/strong><\/p>\n<p style=\"margin-left: 36.0pt;\">El l\u00edmite m\u00ednimo de evaluaci\u00f3n del Elo FEDA seguir\u00e1 en 1000 puntos, y, en todo caso, se variar\u00e1 igual\u00e1ndolo en cada momento al establecido por la FIDE.<\/p>\n<p style=\"margin-left: 36.0pt;\">Se publicar\u00e1 la lista de Elo FEDA el d\u00eda 1 de cada mes, efectuando su cierre 5 d\u00edas antes.<\/p>\n<p style=\"margin-left: 36.0pt;\">A efectos de informes, se requiere lo especificado m\u00e1s adelante para Elo FIDE, salvo reemplazar pa\u00edses por autonom\u00edas.<\/p>\n<p style=\"margin-left: 36.0pt;\">\u00a0<\/p>\n<p style=\"margin-left: 36.0pt;\"><strong>B. Elo FIDE:<\/strong><\/p>\n<ol>\n<li style=\"margin-left: 36pt;\">La FIDE edita sus listas Elo con car\u00e1cter mensual con 12 listas al a\u00f1o, en las mismas fechas mencionadas para el Elo FEDA, siendo los plazos de recepci\u00f3n de pruebas computables hasta 5 d\u00edas antes. El m\u00ednimo de evaluaci\u00f3n Elo se ha fijado en 1000 puntos. La FEDA no se responsabiliza de la evaluaci\u00f3n, dentro de su periodo, de los torneos que se reciban el \u00faltimo d\u00eda de cierre indicado.<\/li>\n<li style=\"margin-left: 36pt;\">Se evaluar\u00e1n para rating FIDE Campeonatos y Torneos de tres especialidades distintas:<\/li>\n<\/ol>\n<p style=\"margin-left: 108.0pt;\"><strong>a)\u00a0<\/strong><strong><u>Ajedrez Tradicional<\/u><\/strong><u>(Standard Chess en FIDE).<\/u><\/p>\n<p style=\"margin-left: 108.0pt;\"><strong>b)\u00a0<\/strong><strong><u>Ajedrez R\u00e1pido<\/u><\/strong><u>, Activo, o de partidas Semirr\u00e1pidas (Rapid Chess en FIDE):<\/u>Cada jugador debe tener por lo menos 10 minutos, pero menos de 60 minutos; o bien que el tiempo asignado m\u00e1s 60 veces cualquier incremento o retardo sea de al menos 10 minutos, pero menos de 60 minutos para cada jugador.<\/p>\n<p style=\"margin-left: 108.0pt;\"><strong>c)\u00a0<\/strong><strong><u>Ajedrez Rel\u00e1mpago,<\/u><\/strong><u>o de partidas r\u00e1pidas (Blitz Chess en FIDE):<\/u>Cada jugador debe tener, despu\u00e9s del ajuste para cualquier incremento o retardo, menos de 10 minutos.<\/p>\n<p style=\"margin-left: 108.0pt;\"><strong>d)\u00a0<\/strong>En todo caso, ambos jugadores deber\u00e1n tener el mismo tiempo asignado<\/p>\n<p style=\"margin-left: 108.0pt;\"><strong>e)<\/strong>\u00a0La FIDE publica una lista mensual por cada una de las especialidades mencionadas.<\/p>\n<p style=\"margin-left: 80px;\">3. Para evaluar un torneo, FIDE o FEDA y de cualquier especialidad de juego, todos los jugadores participantes, con bandera ESP, tienen que estar federados.<\/p>\n<p style=\"margin-left: 80px;\">4. La FEDA podr\u00e1 dar\u00e1 de baja de las listas de rating FEDA y FIDE a los jugadores que no se encuentren federados y al corriente de pago en los plazos establecidos para la tramitaci\u00f3n de licencias.<\/p>\n<p style=\"margin-left: 80px;\">5. En el caso de que un jugador sea dado de baja en alguna de las listas, para volver a ser dado de alta deber\u00e1 abonar, adem\u00e1s de la licencia FEDA, un recargo adicional de 30,00 \u20ac.<\/p>\n<p style=\"margin-left: 80px;\">6. La FEDA podr\u00e1 suspender la tramitaci\u00f3n de informes de torneos a la FIDE celebrados en el territorio de Federaciones Auton\u00f3micas que no se encuentren al corriente de pago, o que no cumplan las condiciones de pago establecidas en los Convenios suscritos con la FEDA.<\/p>\n<p style=\"margin-left: 40px;\">\u00a0<\/p>\n<p style=\"margin-left: 40px;\"><strong>C. Programas de Emparejamiento:<\/strong><\/p>\n<p style=\"margin-left: 80px;\"><strong>1. <\/strong>La FEDA admitir\u00e1 informes con emparejamientos realizados con cualquier programa aceptado por la FIDE.<\/p>\n<p style=\"margin-left: 80px;\"><strong>2. Vega Chess:<\/strong><\/p>\n<p style=\"margin-left: 72.0pt;\">La FEDA gestiona en exclusiva este programa para Espa\u00f1a e Iberoam\u00e9rica, junto con el Orion y VegaTeam (equipos), ambos asociados al servidor de resultados <strong>INFO64.org.<\/strong><\/p>\n<p style=\"margin-left: 72.0pt;\">Toda la informaci\u00f3n sobre los derechosde su uso, condiciones, etc., se encuentra en la Circular 09-215.\u00a0<\/p>\n<p style=\"margin-left: 80px;\"><strong>3. Swiss Manager:<\/strong><\/p>\n<p style=\"margin-left: 72.0pt;\">La FEDA tiene un acuerdo con la propiedad del programa Swiss Manager, asociado al servidor de resultados Chess-Results, mediante el cual los \u00e1rbitros federados pueden disponer de los derechos de uso mediante una cuota anual, en las siguientes condiciones:<\/p>\n<p style=\"margin-left: 108.0pt;\">&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Cuota anual para \u00e1rbitros titulados AN, AF y AI, debidamente federados: <strong>18,00 \u20ac<\/strong><\/p>\n<p style=\"margin-left: 108.0pt;\">&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Cuota anual para \u00e1rbitros auton\u00f3micos, solicitada a trav\u00e9s de su Federaci\u00f3n Auton\u00f3mica: <strong>18,00 \u20ac<\/strong><\/p>\n<p style=\"margin-left: 108.0pt;\">&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Cuota anual para Federaciones Auton\u00f3micas, con Convenio suscrito con la FEDA, y que permite un n\u00famero ilimitado de licencias de uso para sus \u00c1rbitros:<strong>180,00 \u20ac.<\/strong><\/p>\n<p style=\"margin-left: 40px;\"><strong>D. Informes de torneos de Ajedrez Tradicional (Standard Chess en FIDE):<\/strong><\/p>\n<p style=\"margin-left: 40px;\">1. Para poder emitir un informe para rating internacional, todos los \u00e1rbitros que figuren en el mismo, tanto como principal, adjunto o auxiliar, deben tener la cuota FIDE abonada previamente. (Ver circular 31\/2012). Es obligatorio tambi\u00e9n que tengan ID FIDE.<\/p>\n<p style=\"margin-left: 40px;\">2. Los informes de Torneos para su evaluaci\u00f3n y su documentaci\u00f3n complementaria deber\u00e1n ser remitidos <u>\u00fanicamente por e-mail<\/u> a la FEDA, a la direcci\u00f3n <a href=\"mailto:torneos@feda.org\">torneos@feda.org<\/a>\u00a0 M\u00e1s adelante se detalla la informaci\u00f3n a incluir obligatoriamente.<\/p>\n<p style=\"margin-left: 40px;\">3. Para que un informe sea admitido, el Torneo o Campeonato deber\u00e1 haber sido registrado previamente, <strong><u>con 35 d\u00edas de antelaci\u00f3n<\/u><\/strong> a su fecha de inicio.<\/p>\n<p style=\"margin-left: 40px;\">4. Salvo casos excepcionales, los registros previos de torneos y los env\u00edos de informes a la FEDA se realizar\u00e1n a trav\u00e9s de la Federaci\u00f3n Auton\u00f3mica del lugar donde se hayan celebrado.<\/p>\n<p style=\"margin-left: 40px;\">5. Si el env\u00edo del torneo lo realiza directamente el organizador o el \u00e1rbitro principal, deber\u00e1 adjuntar la autorizaci\u00f3n de la Federaci\u00f3n Auton\u00f3mica para que se eval\u00fae el torneo.<\/p>\n<p style=\"margin-left: 40px;\">6. Deber\u00e1 adjuntarse tambi\u00e9n copia escaneada del justificante de pago de los derechos de evaluaci\u00f3n a favor de la FEDA, seg\u00fan importes que se especifican m\u00e1s adelante.<\/p>\n<p style=\"margin-left: 40px;\">7. Todo informe de Torneo o Campeonato remitido a la FEDA constar\u00e1 obligatoriamente de la siguiente documentaci\u00f3n:<\/p>\n<p style=\"margin-left: 108.0pt;\"><strong>a)<\/strong>\u00a0\u00a0Formulario de informe del torneo. IT3.<\/p>\n<p style=\"margin-left: 108.0pt;\"><strong>b)<\/strong>\u00a0\u00a0Fichero que contenga la tabla cruzada seg\u00fan el formato exacto aprobado por la \u00a0\u00a0\u00a0FIDE \u00a0\u00a0\u00a0\u00a0(Krause).<\/p>\n<p style=\"margin-left: 108.0pt;\"><strong>c)<\/strong>\u00a0\u00a0De acuerdo con lo estipulado por la FIDE, en los torneos internacionales es obligatorio remitir las partidas a partir de un determinado Elo, en formato informatizado (generalmente PGN).<\/p>\n<p style=\"margin-left: 108.0pt;\"><strong>d)<\/strong>\u00a0\u00a0\u00a0Los archivos generados por el programa de emparejamientos para su env\u00edo a FIDE.<\/p>\n<p style=\"margin-left: 40px;\">8. Con independencia de todos los requisitos establecidos al efecto por la FIDE, es tambi\u00e9n imprescindible que todo informe que se remita a la FEDA vaya firmado por una persona con licencia de \u00e1rbitro de la FEDA en vigor.<\/p>\n<p style=\"margin-left: 40px;\">9. En el caso de que la persona que firme el informe no sea un \u00e1rbitro con licencia FEDA en vigor, se aplicar\u00e1 lo siguiente:<\/p>\n<p style=\"margin-left: 108.0pt;\"><strong>a)<\/strong>\u00a0Si es un \u00e1rbitro titulado (AN, AF, AI), el organizador deber\u00e1 abonar <strong>105,00<\/strong> \u20ac m\u00e1s para poder tramitar el informe.<\/p>\n<p style=\"margin-left: 108.0pt;\"><strong>b)\u00a0<\/strong>Si es \u00e1rbitro auton\u00f3mico, el informe solamente se tramitar\u00e1 si se cumplen la totalidad de requisitos siguientes:<\/p>\n<p style=\"margin-left: 144.0pt;\"><strong>1.\u00a0\u00a0\u00a0\u00a0 <\/strong>Existencia de acuerdo con la F.A. que contemple expresamente esta posibilidad de tramitaci\u00f3n.<\/p>\n<p style=\"margin-left: 144.0pt;\"><strong>2.\u00a0\u00a0\u00a0\u00a0 <\/strong>El Reglamento del Comit\u00e9 T\u00e9cnico de \u00c1rbitros de la F.A. est\u00e9 homologado por la FEDA, o presentado y en fase de subsanaci\u00f3n.<\/p>\n<p style=\"margin-left: 144.0pt;\"><strong>3.\u00a0\u00a0\u00a0\u00a0 <\/strong>Que, con car\u00e1cter previo al inicio del torneo, no exista la posibilidad de que un jugador, un \u00e1rbitro o un organizador puedan obtener una norma internacional.<\/p>\n<p style=\"margin-left: 144.0pt;\">10. Los torneos que sean para Elo FEDA \u00fanicamente, podr\u00e1n ser firmados por AN, AF, AI y \u00e1rbitros auton\u00f3micos de la Federaci\u00f3n Auton\u00f3mica correspondiente, siempre que exista acuerdo de la FA con la FEDA y tenga su Reglamento del Comit\u00e9 T\u00e9cnico de \u00c1rbitros homologado por la FEDA.<\/p>\n<p style=\"margin-left: 40px;\">11.\u00a0<u>Informes de torneos que contengan Certificados de T\u00edtulos Internacionales (Normas) de Jugadores, \u00c1rbitros y Organizadores:<\/u><\/p>\n<p style=\"margin-left: 108.0pt;\"><strong>a)<\/strong>\u00a0Tendr\u00e1n que cumplir los requisitos mencionados anteriormente y, adem\u00e1s, los apartados siguientes, b), c) y d):<\/p>\n<p style=\"margin-left: 108.0pt;\"><strong>b)<\/strong>\u00a0Deber\u00e1n adjuntar, escaneados,\u00a0 los documentos siguientes, siempre firmados por el \u00e1rbitro principal, que obligatoriamente ser\u00e1 titulado internacional<\/p>\n<p style=\"margin-left: 144.0pt;\"><strong>1.\u00a0\u00a0\u00a0\u00a0 <\/strong>Certificados de resultados para t\u00edtulo de jugador\/a, si los hay. IT1.<\/p>\n<p style=\"margin-left: 144.0pt;\"><strong>2.\u00a0\u00a0\u00a0\u00a0 <\/strong>Informes de Norma de \u00c1rbitro Internacional, si los hay. IA1<\/p>\n<p style=\"margin-left: 144.0pt;\"><strong>3.\u00a0\u00a0\u00a0\u00a0 <\/strong>Informes de Norma de \u00c1rbitro Fide, si los hay. FA1<\/p>\n<p style=\"margin-left: 144.0pt;\"><strong>4.\u00a0\u00a0\u00a0\u00a0 <\/strong>Informes de Norma de Organizador Internacional, si los hay. IO1<\/p>\n<p style=\"margin-left: 108.0pt;\"><strong>c)<\/strong>\u00a0Para que sus Normas sean v\u00e1lidas, los \u00c1rbitros y el Organizador deben constar en el formulario IT3.<\/p>\n<p style=\"margin-left: 108.0pt;\"><strong>d)<\/strong>De acuerdo con lo estipulado por la FIDE y el Reglamento del Comit\u00e9 T\u00e9cnico de \u00c1rbitros de la FEDA, s\u00f3lo se tramitar\u00e1n las normas que, adem\u00e1s de cumplir con todos los dem\u00e1s requisitos reglamentarios, se reciban junto con el informe del torneo.<\/p>\n<p style=\"margin-left: 40px;\">12. Los informes de torneos que contengan \u00fanicamente Normas de Arbitro Nacional, deber\u00e1n cumplir los requisitos del punto anterior, con la salvedad que ser\u00e1 suficiente con que el firmante sea \u00c1rbitro Nacional. En todo caso deber\u00e1 adjuntar la norma junto con el informe del torneo.<\/p>\n<p style=\"margin-left: 72.0pt;\">\u00a0<\/p>\n<p style=\"margin-left: 40px;\"><strong>E. Informes de torneos para Ajedrez R\u00e1pido y Rel\u00e1mpago (Rapid Chess y Blitz Chess en FIDE):<\/strong><\/p>\n<p style=\"margin-left: 40px;\">1. La FEDA tramitar\u00e1 la evaluaci\u00f3n de Elo FIDE de las especialidades de Ajedrez R\u00e1pido y Rel\u00e1mpago, en las condiciones que se establecen.<\/p>\n<p style=\"margin-left: 40px;\">2. Los informes deber\u00e1n cumplir los mismos requisitos establecidos en los puntos del apartado <strong>D<\/strong> anterior, desde el D.<strong>1<\/strong> al D.<strong>9, <\/strong>excepto el plazo para el registro previo, que ser\u00e1 de<strong>15 d\u00edas de antelaci\u00f3n <\/strong>a la fecha de inicio del torneo.<\/p>\n<p style=\"margin-left: 40px;\">\u00a0<\/p>\n<p style=\"margin-left: 40px;\"><strong>F. C\u00f3digos FIDE de los jugadores:<\/strong><\/p>\n<p style=\"margin-left: 40px;\">1. Todos los jugadores que tengan bandera ESP en la FIDE incluidos en el informe del torneo habr\u00e1n de contar con su c\u00f3digo FIDE, tanto aquellos que ya lo tuvieran al comenzar el torneo como los que no. Para ello, el responsable del informe (\u00c1rbitro Principal) tendr\u00e1 que seguir los siguientes pasos:<\/p>\n<p style=\"margin-left: 108.0pt;\"><strong>a)<\/strong>\u00a0Comprobar, antes del comienzo del torneo, los c\u00f3digos de todos los jugadores inscritos. Lo podr\u00e1 hacer mediante consulta en la aplicaci\u00f3n \u201cGesti\u00f3n de Federados-GEFE\u201d en la p\u00e1gina Web de la FEDA <a href=\"http:\/\/www.feda.org\">www.feda.org<\/a><\/p>\n<p style=\"margin-left: 108.0pt;\"><strong>b)\u00a0<\/strong>Antes de la disputa de la segunda ronda, deber\u00e1 enviar a la FEDA (<a href=\"mailto:torneos@feda.org\">torneos@feda.org<\/a>) un mensaje adjuntando el formulario de solicitud de c\u00f3digos con la relaci\u00f3n de los jugadores participantes con bandera ESP que no tengan c\u00f3digo FIDE, si los hubiera.<\/p>\n<p style=\"margin-left: 108.0pt;\">Esta relaci\u00f3n incluir\u00e1 los siguientes datos, con el formato que se detalla:<\/p>\n<p style=\"margin-left: 144.0pt;\"><strong>1.\u00a0\u00a0\u00a0\u00a0 <\/strong>Nombre y apellidos en formato FIDE (Apellido1 Apellido2, Nombre).<\/p>\n<p style=\"margin-left: 144.0pt;\"><strong>2.\u00a0\u00a0\u00a0\u00a0 <\/strong>Fecha de nacimiento completa en formato FIDE (<strong>aaa-mm-dd)<\/strong><\/p>\n<p style=\"margin-left: 144.0pt;\"><strong>3.\u00a0\u00a0\u00a0\u00a0 <\/strong>Sexo (<strong>M <\/strong>\u00f3 <strong>F<\/strong>)<\/p>\n<p style=\"margin-left: 144.0pt;\"><strong>4.\u00a0\u00a0\u00a0\u00a0 <\/strong>C\u00f3digo FEDA (si lo tuviera).<\/p>\n<p style=\"margin-left: 144.0pt;\"><strong>5.\u00a0\u00a0\u00a0\u00a0 <\/strong>Rating FEDA (si lo tuviera).<\/p>\n<p style=\"margin-left: 108.0pt;\"><strong>c)\u00a0<\/strong>Incluir en el informe del torneo los c\u00f3digos que le enviar\u00e1 la FEDA en respuesta a su mensaje.<\/p>\n<p style=\"margin-left: 40px;\">2. La FEDA devolver\u00e1 para su correcci\u00f3n todo aquel informe que incluya a jugadores con bandera ESP sin c\u00f3digo FIDE, aplicando las penalizaciones econ\u00f3micas correspondientes.<\/p>\n<p style=\"margin-left: 40px;\">3. No se admitir\u00e1n solicitudes de c\u00f3digos si no se hacen mediante el formulario oficial.<\/p>\n<p style=\"margin-left: 40px;\">4. Para jugadores extranjeros sin c\u00f3digo y con bandera distinta de ESP, el propio jugador deber\u00e1 ser quien solicite c\u00f3digo a su federaci\u00f3n. En todo caso deber\u00e1 tenerlo antes del inicio del torneo.<\/p>\n<p style=\"margin-left: 40px;\">5. La FEDA no se responsabiliza de los posibles errores que cometan Organizadores o \u00c1rbitros al efectuar los c\u00e1lculos antes mencionados (ratings equivocados, jugadores con rating no incluidos, resultados incorrectos, etc.).<\/p>\n<p style=\"margin-left: 40px;\">6. Por su importancia, reiteramos que debido al sistema de tratamiento de datos en la FIDE, es imprescindible que los nombres de los jugadores figuren exactamente igual que como aparecen en el listado oficial de la FIDE (se recuerda que la letra \u201c\u00f1\u201d debe sustituirse por una \u201cn\u201d, al no tener la FIDE posibilidad por el momento de modificar esta circunstancia. \u00a0Todos los nombres y apellidos deben ir sin acentos).<\/p>\n<p style=\"margin-left: 40px;\">7. El responsable del informe deber\u00e1 notificar a la FEDA (<a href=\"mailto:torneos@feda.org\">torneos@feda.org<\/a>) todos los errores relativos a los participantes del torneo que detecte en las listas de rating FEDA o FIDE (duplicados, errores tipogr\u00e1ficos, a\u00f1o de nacimiento, sexo, etc.), utilizando el formulario al efecto, pero no se puede alterar lo que figure oficialmente en el \u00faltimo listado FIDE.<\/p>\n<p style=\"margin-left: 40px;\">8. En el informe del torneo deber\u00e1 hacerse constar que se han revisado todos los nombres de los participantes y coinciden con la \u00faltima lista Elo FIDE.<\/p>\n<p style=\"margin-left: 40px;\">\u00a0<\/p>\n<p style=\"margin-left: 40px;\"><strong>G. Formulario de Registro Previo de los Torneos y Campeonatos:<\/strong><\/p>\n<p style=\"margin-left: 40px;\">1. Se anexa a esta circular el formulario oficial que deber\u00e1 ser obligatoriamente cumplimentado con car\u00e1cter previo a cualquier competici\u00f3n que se desee evaluar FIDE, en los plazos establecidos.<\/p>\n<p style=\"margin-left: 40px;\">2. Si el Torneo es Internacional, este formulario se utilizar\u00e1 para su registro en la FIDE, solicitud del permiso al C.S.D. en su caso y, si se incluye la opci\u00f3n, registro en el calendario de eventos FIDE y\/o FEDA.<\/p>\n<p style=\"margin-left: 40px;\">3. Cualquier cambio fuera de plazo en los datos facilitados para el registro, puede impedir la valoraci\u00f3n del torneo por parte de la FIDE.<\/p>\n<p style=\"margin-left: 40px;\">4. En especial, el cambio en el informe del nombre exacto que se le haya dado al torneo en el registro previo, o bien sus fechas exactas de inicio y final, pueden ser motivo suficiente para que la FIDE no lo eval\u00fae.<\/p>\n<p style=\"margin-left: 64.35pt;\"><strong>El incumplimiento total o parcial de alguno de los apartados anteriores, <u>motivar\u00e1 la devoluci\u00f3n autom\u00e1tica del torneo<\/u>.<\/strong><\/p>\n<p style=\"margin-left: 64.35pt;\">\u00a0<\/p>\n<p style=\"margin-left: 40px;\"><strong>H. Canon Evaluaci\u00f3n Elo FEDA:<\/strong><\/p>\n<p style=\"margin-left: 40px;\">El canon ser\u00e1 de 46,00 euros por torneo. S\u00f3lo se facturar\u00e1 en el caso de Torneos que se remitan \u00fanicamente para su evaluaci\u00f3n Elo FEDA (sin Elo FIDE) y con las excepciones que se detallan.<\/p>\n<p style=\"margin-left: 40px;\">\u00a0<\/p>\n<p style=\"margin-left: 40px;\"><strong>I.\u00a0Canon Evaluaci\u00f3n Elo FIDE:<\/strong><\/p>\n<p style=\"margin-left: 40px;\"><strong><u>1. Tasas para torneos de Ajedrez Tradicional (Standard):<\/u><\/strong><\/p>\n<p style=\"margin-left: 40px;\">Se facturar\u00e1n al organizador las siguientes tasas de la FIDE, en funci\u00f3n del tipo de torneo y el programa de emparejamiento utilizado:<\/p>\n<p>&nbsp;<\/p>\n<p style=\"margin-left: 103.05pt;\"><strong>1.1\u00a0\u00a0 <\/strong><strong>Torneos realizados con el programa VegaChess + Info64:<\/strong><\/p>\n<p style=\"margin-left: 108.0pt;\"><strong>a)<\/strong><u>\u00a0Torneos cerrados y Matches<\/u>:<\/p>\n<p style=\"margin-left: 144.0pt;\"><strong>1.\u00a0\u00a0\u00a0\u00a0 <\/strong>Tasa de Registro del torneo: 25,00 \u20ac<\/p>\n<p style=\"margin-left: 144.0pt;\"><strong>2.\u00a0\u00a0\u00a0\u00a0 <\/strong>Tasa por Elo Medio del Torneo:<\/p>\n<p>&nbsp;<\/p>\n<table style=\"width: 334px;\" border=\"1\" width=\"250\" cellspacing=\"0\" cellpadding=\"0\" align=\"center\" class=\"mtr-table mtr-tr-td\">\n<tbody>\n<tr>\n<td style=\"width: 176px;\" data-mtr-content=\"\nTramo Elo medio\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p style=\"margin-left: 36.0pt;\">Tramo Elo medio<\/p>\n<\/div><\/td>\n<td style=\"width: 157px;\" data-mtr-content=\"\nImporte tasas \u20ac\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p style=\"margin-left: 36.0pt;\">Importe tasas \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 176px;\" data-mtr-content=\"\nTramo Elo medio\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p style=\"margin-left: 36.0pt;\">0-2300<\/p>\n<\/div><\/td>\n<td style=\"width: 157px;\" data-mtr-content=\"\nImporte tasas \u20ac\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p style=\"margin-left: 36.0pt;\" align=\"center\">60,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 176px;\" data-mtr-content=\"\nTramo Elo medio\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p style=\"margin-left: 36.0pt;\">2301-2400<\/p>\n<\/div><\/td>\n<td style=\"width: 157px;\" data-mtr-content=\"\nImporte tasas \u20ac\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p style=\"margin-left: 36.0pt;\" align=\"center\">110,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 176px;\" data-mtr-content=\"\nTramo Elo medio\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p style=\"margin-left: 36.0pt;\">2401-2500<\/p>\n<\/div><\/td>\n<td style=\"width: 157px;\" data-mtr-content=\"\nImporte tasas \u20ac\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p style=\"margin-left: 36.0pt;\" align=\"center\">160,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 176px;\" data-mtr-content=\"\nTramo Elo medio\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p style=\"margin-left: 36.0pt;\">2501-2600<\/p>\n<\/div><\/td>\n<td style=\"width: 157px;\" data-mtr-content=\"\nImporte tasas \u20ac\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p style=\"margin-left: 36.0pt;\" align=\"center\">210,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 176px;\" data-mtr-content=\"\nTramo Elo medio\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p style=\"margin-left: 36.0pt;\">M\u00e1s de 2600<\/p>\n<\/div><\/td>\n<td style=\"width: 157px;\" data-mtr-content=\"\nImporte tasas \u20ac\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p style=\"margin-left: 36.0pt;\" align=\"center\">310,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div style=\"clear: both;\">\u00a0<\/div>\n<p style=\"margin-left: 108.0pt;\"><strong>b)<\/strong><u>Torneos por Sistema Suizo:<\/u><\/p>\n<p style=\"margin-left: 144.0pt;\"><strong>1.\u00a0\u00a0\u00a0\u00a0 <\/strong>\u00a0Tasa de registro del torneo: 25,00 \u20ac.<\/p>\n<p style=\"margin-left: 144.0pt;\"><strong>2.\u00a0\u00a0\u00a0\u00a0 <\/strong>\u00a0\u00a01,80 \u20ac por cada jugador participante.<\/p>\n<p style=\"margin-left: 99.0pt;\">\u00a0<\/p>\n<p style=\"margin-left: 108.0pt;\"><strong>c)<\/strong><u>\u00a0\u00a0Torneos por Equipos (incluidos Torneos Schweningen)<\/u>:<\/p>\n<p style=\"margin-left: 144.0pt;\"><strong>1.\u00a0\u00a0\u00a0\u00a0 <\/strong>Tasa de registro del torneo: 25,00 \u20ac<\/p>\n<p style=\"margin-left: 144.0pt;\"><strong>2.\u00a0\u00a0\u00a0\u00a0 <\/strong>1,80 \u20ac por cada jugador participante, independientemente del n\u00famero de equipos.<\/p>\n<p style=\"margin-left: 144.0pt;\">\u00a0<\/p>\n<p style=\"margin-left: 74.7pt;\"><strong>1.2.<\/strong><strong>Torneos realizados con un programa de emparejamiento distinto de Vega Chess. Tasas que se aplicar\u00e1n a torneos que se inicien\u00a0 a partir del 30-06-2015:<\/strong><\/p>\n<p style=\"margin-left: 108.0pt;\"><strong>a)<\/strong><u>\u00a0Torneos cerrados y Matches<\/u>:<\/p>\n<p style=\"margin-left: 144.0pt;\"><strong>1.\u00a0\u00a0\u00a0\u00a0 <\/strong>Tasa de Registro del torneo: 25,00 \u20ac<\/p>\n<p style=\"margin-left: 144.0pt;\"><strong>2.\u00a0\u00a0\u00a0\u00a0 <\/strong>Tasa por Elo Medio del Torneo:<\/p>\n<p>&nbsp;<\/p>\n<table style=\"width: 334px;\" border=\"1\" width=\"250\" cellspacing=\"0\" cellpadding=\"0\" align=\"center\" class=\"mtr-table mtr-tr-td\">\n<tbody>\n<tr>\n<td style=\"width: 176px;\" data-mtr-content=\"\nTramo Elo medio\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p style=\"margin-left: 36.0pt;\">Tramo Elo medio<\/p>\n<\/div><\/td>\n<td style=\"width: 157px;\" data-mtr-content=\"\nImporte tasas \u20ac\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p style=\"margin-left: 36.0pt;\">Importe tasas \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 176px;\" data-mtr-content=\"\nTramo Elo medio\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p style=\"margin-left: 36.0pt;\">0-2300<\/p>\n<\/div><\/td>\n<td style=\"width: 157px;\" data-mtr-content=\"\nImporte tasas \u20ac\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p style=\"margin-left: 36.0pt;\" align=\"center\">70,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 176px;\" data-mtr-content=\"\nTramo Elo medio\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p style=\"margin-left: 36.0pt;\">2301-2400<\/p>\n<\/div><\/td>\n<td style=\"width: 157px;\" data-mtr-content=\"\nImporte tasas \u20ac\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p style=\"margin-left: 36.0pt;\" align=\"center\">120,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 176px;\" data-mtr-content=\"\nTramo Elo medio\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p style=\"margin-left: 36.0pt;\">2401-2500<\/p>\n<\/div><\/td>\n<td style=\"width: 157px;\" data-mtr-content=\"\nImporte tasas \u20ac\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p style=\"margin-left: 36.0pt;\" align=\"center\">170,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 176px;\" data-mtr-content=\"\nTramo Elo medio\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p style=\"margin-left: 36.0pt;\">2501-2600<\/p>\n<\/div><\/td>\n<td style=\"width: 157px;\" data-mtr-content=\"\nImporte tasas \u20ac\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p style=\"margin-left: 36.0pt;\" align=\"center\">220,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 176px;\" data-mtr-content=\"\nTramo Elo medio\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p style=\"margin-left: 36.0pt;\">M\u00e1s de 2600<\/p>\n<\/div><\/td>\n<td style=\"width: 157px;\" data-mtr-content=\"\nImporte tasas \u20ac\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p style=\"margin-left: 36.0pt;\" align=\"center\">320,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div style=\"clear: both;\">\u00a0<\/div>\n<p style=\"margin-left: 108.0pt;\"><strong>b)<\/strong><u>Torneos por Sistema Suizo:<\/u><\/p>\n<p style=\"margin-left: 144.0pt;\"><strong>1.\u00a0\u00a0\u00a0\u00a0 <\/strong>\u00a0\u00a0Tasa de registro del torneo: 25,00 \u20ac.<\/p>\n<p style=\"margin-left: 144.0pt;\"><strong>2.\u00a0\u00a0\u00a0\u00a0 <\/strong>\u00a0\u00a02,20 \u20ac por cada jugador participante.<\/p>\n<p style=\"margin-left: 108.0pt;\"><strong>c)<\/strong><u>\u00a0\u00a0Torneos por Equipos (incluidos Torneos Schweningen)<\/u>:<\/p>\n<p style=\"margin-left: 144.0pt;\"><strong>1.\u00a0\u00a0\u00a0\u00a0 <\/strong>Tasa de registro del torneo: 25,00 \u20ac<\/p>\n<p style=\"margin-left: 144.0pt;\"><strong>2.\u00a0\u00a0\u00a0\u00a0 <\/strong>2,20 \u20ac por cada jugador participante, independientemente del n\u00famero de equipos.<\/p>\n<p>Todas las tasas mencionadas se abonar\u00e1n en el momento del env\u00edo del informe.<\/p>\n<p>El ingreso de las tasas se har\u00e1 en la cuenta de la FEDA:<\/p>\n<p>Ibercaja <strong>ES50<\/strong> <strong>2085 8024 9503 0002 5965<\/strong>, poniendo como concepto el nombre del Torneo.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"margin-left: 74.7pt;\"><strong>1.3.<\/strong><strong>Campeonatos Auton\u00f3micos. Ajedrez Tradicional (Standard Chess):<\/strong><\/p>\n<p style=\"margin-left: 149.4pt;\"><strong>a)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong>\u00a0\u00a0\u00a0\u00a0Se aplicar\u00e1n las mismas tasas del apartado anterior, excepto las de registro de los torneos, con un l\u00edmite m\u00e1ximo anual de 1.000,00 \u20ac por Federaci\u00f3n Auton\u00f3mica, o bien 800,00 \u20ac si usan exclusivamente VegaChess, y as\u00ed est\u00e1 establecido en el Convenio suscrito con la FEDA.<\/p>\n<p style=\"margin-left: 149.4pt;\"><strong>b)\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong>\u00a0\u00a0\u00a0Los Campeonatos evaluados solamente para FEDA ser\u00e1n sin cargo, si existe Convenio suscrito con la FEDA, excepto para aquellas federaciones con las que exista acuerdo distinto por ser el Elo FEDA equivalente a su Elo Auton\u00f3mico.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"margin-left: 18.0pt;\"><strong>2.\u00a0\u00a0\u00a0\u00a0 <\/strong><strong><u>Tasas para torneos de Ajedrez R\u00e1pido y Ajedrez Rel\u00e1mpago (Rapid Chess y Blitz Chess)<\/u><\/strong><\/p>\n<p style=\"margin-left: 74.7pt;\"><strong>2.1.<\/strong>\u00a0Tasa de registro del Torneo: 15,00 \u20ac (Excepto Campeonatos Auton\u00f3micos).<\/p>\n<p style=\"margin-left: 74.7pt;\"><strong>2.2.<\/strong>\u00a0\u00a0\u00a0Para torneos realizados con Vega Chess, la tasa ser\u00e1 de 0,90 \u20ac por jugador participante, sean sistema suizo, round robin, equipos, o de cualquier otro tipo, incluidos los Campeonatos Auton\u00f3micos, en este caso sin l\u00edmite m\u00e1ximo anual.<\/p>\n<p style=\"margin-left: 74.7pt;\"><strong>2.3.<\/strong>Para torneos realizados con un programa distinto de Vega Chess, la tasa ser\u00e1 de 1,10 \u20ac por jugador participante, para todo tipo de torneo, incluidos los Campeonatos Auton\u00f3micos, en este caso sin l\u00edmite m\u00e1ximo anual.<\/p>\n<p style=\"margin-left: 74.7pt;\"><strong>2.4.<\/strong>El ingreso de las tasas se har\u00e1 en la cuenta de la FEDA:<\/p>\n<p style=\"margin-left: 72.0pt;\">Ibercaja <strong>ES50<\/strong> <strong>2085 8024 9503 0002 5965<\/strong>, poniendo como concepto el nombre del Torneo.<\/p>\n<p style=\"margin-left: 72.0pt;\">\u00a0<\/p>\n<p style=\"margin-left: 40px;\"><strong>J. Plazos de env\u00edo de Informes. Sanciones:<\/strong><\/p>\n<p style=\"margin-left: 40px;\">1. El plazo m\u00e1ximo para remitir un torneo a la FEDA, solicitando la evaluaci\u00f3n de Elo FIDE, ser\u00e1 de 10 d\u00edas naturales a partir de la fecha de su finalizaci\u00f3n. A estos efectos, la fecha de env\u00edo ser\u00e1 la del e-mail.<\/p>\n<p style=\"margin-left: 40px;\">2. El incumplimiento de este plazo supondr\u00e1 una sanci\u00f3n de 100,00 \u20ac al organizador del torneo.<\/p>\n<p style=\"margin-left: 40px;\">3. Si la FEDA tiene que devolver un torneo por no ajustarse a los requisitos para su evaluaci\u00f3n, se conceder\u00e1 un nuevo plazo de 7 d\u00edas naturales para subsanarlo.<\/p>\n<p style=\"margin-left: 40px;\">4. Independientemente de la multa que pudiera corresponder, la devoluci\u00f3n del torneo o Campeonato por defectos en su cumplimentaci\u00f3n supondr\u00e1 una sanci\u00f3n de 15,00 euros al organizador por indemnizaci\u00f3n de gastos realizados por la FEDA.<\/p>\n<p style=\"margin-left: 40px;\">5. Con independencia de las tasas y sanciones que les sean de aplicaci\u00f3n, por razones obvias puramente t\u00e9cnicas y deportivas, la FEDA podr\u00e1\u00a0 no autorizar la evaluaci\u00f3n de los torneos que le sean\u00a0 remitidos fuera del periodo de Elo en que deber\u00edan haber sido evaluados, impidiendo por lo tanto que los jugadores figuren con un Elo actualizado en la lista correspondiente.<\/p>\n<p style=\"margin-left: 40px;\">6. En todo caso, no se admitir\u00e1 la evaluaci\u00f3n de torneos con una antig\u00fcedad de seis meses o m\u00e1s.<\/p>\n<p style=\"margin-left: 40px;\">\u00a0<\/p>\n<p style=\"margin-left: 40px;\"><strong>K. Administraci\u00f3n Elo. Reclamaciones.<\/strong><\/p>\n<p style=\"margin-left: 40px;\">1. El Administrador de Elo, tanto FIDE como FEDA, supervisar\u00e1 la correcta evaluaci\u00f3n de los jugadores y los torneos, as\u00ed como su correcta tramitaci\u00f3n.<\/p>\n<p style=\"margin-left: 40px;\">2. Para que un torneo pueda ser evaluado, todos los jugadores con bandera ESP ante la FIDE deben estar federados.<\/p>\n<p style=\"margin-left: 40px;\">3. Solamente se pueden tramitar ante la FIDE reclamaciones de jugadores\/as, \u00e1rbitros y organizadores que ostenten bandera ESP.<\/p>\n<p style=\"margin-left: 40px;\">4. Las reclamaciones de jugadores federados en Espa\u00f1a, pero con bandera distinta a la de ESP, se realizar\u00e1n en primer lugar ante su federaci\u00f3n nacional.<\/p>\n<p style=\"margin-left: 40px;\">5. Toda persona o entidad directamente interesada puede reclamar por evaluaciones incorrectas, datos incorrectos, errores en resultados, etc.<\/p>\n<p style=\"margin-left: 40px;\">6. Las reclamaciones deber\u00e1n efectuarse por e-mail, dirigido a <a href=\"mailto:torneos@feda.org\">torneos@feda.org<\/a>indicando lo m\u00e1s claramente posible el motivo de la reclamaci\u00f3n.<\/p>\n<p style=\"margin-left: 40px;\">7. Si se trata de un resultado incorrecto, la FEDA requerir\u00e1 al \u00e1rbitro del torneo para que modifique el informe y lo remita de nuevo con el resultado o los resultados corregidos. Sin este requisito, no se tramitar\u00e1n este tipo de reclamaciones.<\/p>\n<p>&nbsp;<\/p>\n<p>En Madrid, a 2 de marzo de 2015<\/p>\n<p>&nbsp;<\/p>\n<p>Ram\u00f3n Padull\u00e9s Argerich<\/p>\n<p>Secretario General<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Los formularios mencionados en esta circular podr\u00e1n encontrarse tanto en las secciones \u201cDirecci\u00f3n T\u00e9cnica\u201d y \u201cComit\u00e9 T\u00e9cnico de \u00c1rbitros\u201d de la Web <\/strong><a href=\"http:\/\/www.feda.org\"><strong>www.feda.org<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>En el Anexo 1 se resumen las cuotas y tasas aplicables a los distintos servicios y licencias de uso, as\u00ed como las sanciones.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>ANEXO 1<\/strong><\/p>\n<p><strong>Cuotas para el Registro e Informes de Torneos:<\/strong><\/p>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\" align=\"center\" class=\"mtr-table mtr-tr-td\">\n<tbody>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\"><strong>Vega + Info64 (02-03-2015)<\/strong><\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\"><strong>Otros Programas (01-07-2015)<\/strong><\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\"><strong>AJEDREZ TRADICIONAL (Standard)<\/strong><\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p><strong><u>Torneos Cerrados IRT y Match<\/u><\/strong><\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>Registro del Torneo<\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">25,00 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">25,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>Elo Medio del Torneo:<\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>Hasta 2300<\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">60,00\u20ac<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">70,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>2301-2400<\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">110,00 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">120,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>2401-2500<\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">160,00 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">170,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>2501-2600<\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">210,00 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">220,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>M\u00e1s de 2600<\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">310,00 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">320,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p><strong><u>Torneos Abiertos<\/u><\/strong><\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p><strong>Torneos Individuales<\/strong><\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>Registro del Torneo<\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">25,00 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">25,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>Informe<\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">1,80 \u20ac por jugador\/a<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">2,20 \u20ac por jugador\/a<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p><strong>Torneos por Equipos<\/strong><\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>Registro del Torneo<\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">25,00 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">25,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>Informe<\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">1,80 \u20ac por jugador\/a<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">2,20 \u20ac por jugador\/a<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>\u00a0<\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p><strong>Campeonatos Auton\u00f3micos Oficiales<\/strong><\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\"><strong>Convenio: M\u00e1ximo Anual 800 \u20ac<\/strong><\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\"><strong>Convenio: M\u00e1ximo Anual: 1.000 \u20ac<\/strong><\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p><strong><u>Torneos Cerrados IRT y Match<\/u><\/strong><\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>Elo Medio del Torneo:<\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>Hasta 2300<\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">60,00\u20ac<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">70,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>2301-2400<\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">110,00 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">120,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>2401-2500<\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">160,00 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">170,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>2501-2600<\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">210,00 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">220,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>M\u00e1s de 2600<\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">310,00 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">320,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p><strong><u>Torneos Abiertos<\/u><\/strong><\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p><strong>Torneos Individuales<\/strong><\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>Informe<\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">1,80 \u20ac por jugador\/a<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">2,20 \u20ac por jugador\/a<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p><strong>Torneos por Equipos<\/strong><\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>Informe<\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">1,80 \u20ac por jugador\/a<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">2,20 \u20ac por jugador\/a<\/p>\n<\/div><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div style=\"clear: both;\">\u00a0<\/div>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\" align=\"center\" class=\"mtr-table mtr-tr-td\">\n<tbody>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\"><strong>Vega + Info64 (02-03-2015)<\/strong><\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\"><strong>Otros Programas (01-07-2015)<\/strong><\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\"><strong>AJEDREZ R\u00c1PIDO Y REL\u00c1MPAGO<\/strong><\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p><strong><u>Torneos Cerrados IRT y Match<\/u><\/strong><\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>Registro del Torneo<\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">15,00 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">15,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>Elo Medio del Torneo:<\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>Hasta 2300<\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">30,00\u20ac<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">40,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>2301-2400<\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">55,00 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">65,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>2401-2500<\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">80,00 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">90,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>2501-2600<\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">105,00 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">115,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>M\u00e1s de 2600<\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">155,00 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">165,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p><strong><u>Torneos Abiertos<\/u><\/strong><\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p><strong>Torneos Individuales<\/strong><\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>Registro del Torneo<\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">15,00 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">15,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>Informe<\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">0,90 \u20ac por jugador\/a<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">1,10 \u20ac por jugador\/a<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p><strong>Torneos por Equipos<\/strong><\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>Registro del Torneo<\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">25,00 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">25,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>Informe<\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">0,90 \u20ac por jugador\/a<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">1,10 \u20ac por jugador\/a<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p><strong>Campeonatos Auton\u00f3micos Oficiales:<\/strong><\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p><strong><u>Torneos Cerrados IRT y Match<\/u><\/strong><\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>Elo Medio del Torneo:<\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>Hasta 2300<\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">30,00\u20ac<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">40,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>2301-2400<\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">55,00 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">65,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>2401-2500<\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">80,00 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">90,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>2501-2600<\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">105,00 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">115,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>M\u00e1s de 2600<\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">155,00 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">165,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p><strong><u>Torneos Abiertos<\/u><\/strong><\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p><strong>Torneos Individuales<\/strong><\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>Informe<\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">0,90 \u20ac por jugador\/a<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">1,10 \u20ac por jugador\/a<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p><strong>Torneos por Equipos<\/strong><\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>Informe<\/p>\n<\/div><\/td>\n<td style=\"width: 194px;\" data-mtr-content=\"\nVega + Info64 (02-03-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">0,90 \u20ac por jugador\/a<\/p>\n<\/div><\/td>\n<td style=\"width: 208px;\" data-mtr-content=\"\nOtros Programas (01-07-2015)\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">1,10 \u20ac por jugador\/a<\/p>\n<\/div><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div style=\"clear: both;\">\u00a0<\/div>\n<p>&nbsp;<\/p>\n<p><strong>Sanciones:<\/strong><\/p>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\" align=\"center\" class=\"mtr-table mtr-tr-td\">\n<tbody>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00c1rbitro titulado no federado\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>\u00c1rbitro titulado no federado<\/p>\n<\/div><\/td>\n<td style=\"width: 68px;\" data-mtr-content=\"\n105,00 \u20ac\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">105,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00c1rbitro titulado no federado\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>Retraso env\u00edo informe<\/p>\n<\/div><\/td>\n<td style=\"width: 68px;\" data-mtr-content=\"\n105,00 \u20ac\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">100,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 224px;\" data-mtr-content=\"\n\u00c1rbitro titulado no federado\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>Devoluci\u00f3n de Informe<\/p>\n<\/div><\/td>\n<td style=\"width: 68px;\" data-mtr-content=\"\n105,00 \u20ac\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">15,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div style=\"clear: both;\">\u00a0<\/div>\n<p>&nbsp;<\/p>\n<p><strong>Cuotas Licencias de uso de programas de emparejamiento gestionadas por la FEDA:<\/strong><\/p>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\" align=\"center\" class=\"mtr-table mtr-tr-td\">\n<tbody>\n<tr>\n<td style=\"width: 247px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>\u00a0<\/p>\n<\/div><\/td>\n<td style=\"width: 127px;\" data-mtr-content=\"\nVega + Info64 2015\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\"><strong>Vega + Info64 2015<\/strong><\/p>\n<\/div><\/td>\n<td style=\"width: 134px;\" data-mtr-content=\"\nSwiss Manager 2015\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\"><strong>Swiss Manager 2015<\/strong><\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 247px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>\u00c1rbitros AN, AF, AI, Federados<\/p>\n<\/div><\/td>\n<td style=\"width: 127px;\" data-mtr-content=\"\nVega + Info64 2015\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">0,00 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width: 134px;\" data-mtr-content=\"\nSwiss Manager 2015\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">18,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 247px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>\u00c1rbitros Auton\u00f3micos:<\/p>\n<\/div><\/td>\n<td style=\"width: 127px;\" data-mtr-content=\"\nVega + Info64 2015\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">12,00 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width: 134px;\" data-mtr-content=\"\nSwiss Manager 2015\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">18,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 247px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>\u00a0<\/p>\n<\/div><\/td>\n<td style=\"width: 127px;\" data-mtr-content=\"\nVega + Info64 2015\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<td style=\"width: 134px;\" data-mtr-content=\"\nSwiss Manager 2015\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 247px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>Federaciones Auton\u00f3micas con Convenio:<\/p>\n<\/div><\/td>\n<td style=\"width: 127px;\" data-mtr-content=\"\nVega + Info64 2015\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<td style=\"width: 134px;\" data-mtr-content=\"\nSwiss Manager 2015\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">\u00a0<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 247px;\" data-mtr-content=\"\n\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p>N\u00famero ilimitado de licencias<\/p>\n<\/div><\/td>\n<td style=\"width: 127px;\" data-mtr-content=\"\nVega + Info64 2015\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">120,00 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width: 134px;\" data-mtr-content=\"\nSwiss Manager 2015\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\">180,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div style=\"clear: both;\">\u00a0<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A TODAS LAS FEDERACIONES AUTON\u00d3MICAS Y \u00c1RBITROS FEDA Ref.: Informes, Evaluaci\u00f3n de Torneos y Elo 2015. Descargar en PDF &nbsp; A. Elo FEDA: El l\u00edmite m\u00ednimo de evaluaci\u00f3n del Elo FEDA seguir\u00e1 en 1000 puntos, y, en todo caso, se variar\u00e1 igual\u00e1ndolo en cada momento al establecido por la FIDE. Se publicar\u00e1 la lista de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[],"class_list":["post-1448","post","type-post","status-publish","format-standard","hentry","category-41"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Circular 10\/2015 - Evaluaci\u00f3n Elo 2015 - FEDA<\/title>\n<meta name=\"description\" content=\"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/feda.org\/feda2k16\/circular-10-2015-evaluacion-elo-2015\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Circular 10\/2015 - Evaluaci\u00f3n Elo 2015 - FEDA\" \/>\n<meta property=\"og:description\" content=\"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez\" \/>\n<meta property=\"og:url\" content=\"https:\/\/feda.org\/feda2k16\/circular-10-2015-evaluacion-elo-2015\/\" \/>\n<meta property=\"og:site_name\" content=\"FEDA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/federacionespanoladeajedrez\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-03T10:24:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-12-11T10:58:10+00:00\" \/>\n<meta name=\"author\" content=\"feda2k16\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AjedrezEspanola\" \/>\n<meta name=\"twitter:site\" content=\"@AjedrezEspanola\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"feda2k16\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"16 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/circular-10-2015-evaluacion-elo-2015\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/circular-10-2015-evaluacion-elo-2015\\\/\"},\"author\":{\"name\":\"feda2k16\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/person\\\/80aa48a4dc5c6ea03ca1dbf21ce423da\"},\"headline\":\"Circular 10\\\/2015 &#8211; Evaluaci\u00f3n Elo 2015\",\"datePublished\":\"2015-03-03T10:24:34+00:00\",\"dateModified\":\"2017-12-11T10:58:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/circular-10-2015-evaluacion-elo-2015\\\/\"},\"wordCount\":3289,\"publisher\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#organization\"},\"articleSection\":[\"2015\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/circular-10-2015-evaluacion-elo-2015\\\/\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/circular-10-2015-evaluacion-elo-2015\\\/\",\"name\":\"Circular 10\\\/2015 - Evaluaci\u00f3n Elo 2015 - FEDA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#website\"},\"datePublished\":\"2015-03-03T10:24:34+00:00\",\"dateModified\":\"2017-12-11T10:58:10+00:00\",\"description\":\"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/circular-10-2015-evaluacion-elo-2015\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/feda.org\\\/feda2k16\\\/circular-10-2015-evaluacion-elo-2015\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/circular-10-2015-evaluacion-elo-2015\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Circular 10\\\/2015 &#8211; Evaluaci\u00f3n Elo 2015\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#website\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/\",\"name\":\"FEDA\",\"description\":\"Federaci\u00f3n Espa\u00f1ola de Ajedrez\",\"publisher\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#organization\"},\"alternateName\":\"Federaci\u00f3n Espa\u00f1ola de Ajedrez\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#organization\",\"name\":\"FEDA\",\"alternateName\":\"Federaci\u00f3n Espa\u00f1ola de Ajedrez\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/NuevoLogo_FEDA_2016.png\",\"contentUrl\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/NuevoLogo_FEDA_2016.png\",\"width\":600,\"height\":600,\"caption\":\"FEDA\"},\"image\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/federacionespanoladeajedrez\\\/\",\"https:\\\/\\\/x.com\\\/AjedrezEspanola\",\"https:\\\/\\\/www.instagram.com\\\/federacionespanolaajedrez\\\/?hl=es\",\"https:\\\/\\\/www.youtube.com\\\/@FederacionEspanoladeAjedrezFED\\\/featured\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/person\\\/80aa48a4dc5c6ea03ca1dbf21ce423da\",\"name\":\"feda2k16\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/author\\\/feda2k16\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Circular 10\/2015 - Evaluaci\u00f3n Elo 2015 - FEDA","description":"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/feda.org\/feda2k16\/circular-10-2015-evaluacion-elo-2015\/","og_locale":"es_ES","og_type":"article","og_title":"Circular 10\/2015 - Evaluaci\u00f3n Elo 2015 - FEDA","og_description":"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez","og_url":"https:\/\/feda.org\/feda2k16\/circular-10-2015-evaluacion-elo-2015\/","og_site_name":"FEDA","article_publisher":"https:\/\/www.facebook.com\/federacionespanoladeajedrez\/","article_published_time":"2015-03-03T10:24:34+00:00","article_modified_time":"2017-12-11T10:58:10+00:00","author":"feda2k16","twitter_card":"summary_large_image","twitter_creator":"@AjedrezEspanola","twitter_site":"@AjedrezEspanola","twitter_misc":{"Escrito por":"feda2k16","Tiempo de lectura":"16 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/feda.org\/feda2k16\/circular-10-2015-evaluacion-elo-2015\/#article","isPartOf":{"@id":"https:\/\/feda.org\/feda2k16\/circular-10-2015-evaluacion-elo-2015\/"},"author":{"name":"feda2k16","@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/person\/80aa48a4dc5c6ea03ca1dbf21ce423da"},"headline":"Circular 10\/2015 &#8211; Evaluaci\u00f3n Elo 2015","datePublished":"2015-03-03T10:24:34+00:00","dateModified":"2017-12-11T10:58:10+00:00","mainEntityOfPage":{"@id":"https:\/\/feda.org\/feda2k16\/circular-10-2015-evaluacion-elo-2015\/"},"wordCount":3289,"publisher":{"@id":"https:\/\/feda.org\/feda2k16\/#organization"},"articleSection":["2015"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/feda.org\/feda2k16\/circular-10-2015-evaluacion-elo-2015\/","url":"https:\/\/feda.org\/feda2k16\/circular-10-2015-evaluacion-elo-2015\/","name":"Circular 10\/2015 - Evaluaci\u00f3n Elo 2015 - FEDA","isPartOf":{"@id":"https:\/\/feda.org\/feda2k16\/#website"},"datePublished":"2015-03-03T10:24:34+00:00","dateModified":"2017-12-11T10:58:10+00:00","description":"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez","breadcrumb":{"@id":"https:\/\/feda.org\/feda2k16\/circular-10-2015-evaluacion-elo-2015\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/feda.org\/feda2k16\/circular-10-2015-evaluacion-elo-2015\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/feda.org\/feda2k16\/circular-10-2015-evaluacion-elo-2015\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/feda.org\/feda2k16\/"},{"@type":"ListItem","position":2,"name":"Circular 10\/2015 &#8211; Evaluaci\u00f3n Elo 2015"}]},{"@type":"WebSite","@id":"https:\/\/feda.org\/feda2k16\/#website","url":"https:\/\/feda.org\/feda2k16\/","name":"FEDA","description":"Federaci\u00f3n Espa\u00f1ola de Ajedrez","publisher":{"@id":"https:\/\/feda.org\/feda2k16\/#organization"},"alternateName":"Federaci\u00f3n Espa\u00f1ola de Ajedrez","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/feda.org\/feda2k16\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/feda.org\/feda2k16\/#organization","name":"FEDA","alternateName":"Federaci\u00f3n Espa\u00f1ola de Ajedrez","url":"https:\/\/feda.org\/feda2k16\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/logo\/image\/","url":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/NuevoLogo_FEDA_2016.png","contentUrl":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/NuevoLogo_FEDA_2016.png","width":600,"height":600,"caption":"FEDA"},"image":{"@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/federacionespanoladeajedrez\/","https:\/\/x.com\/AjedrezEspanola","https:\/\/www.instagram.com\/federacionespanolaajedrez\/?hl=es","https:\/\/www.youtube.com\/@FederacionEspanoladeAjedrezFED\/featured"]},{"@type":"Person","@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/person\/80aa48a4dc5c6ea03ca1dbf21ce423da","name":"feda2k16","url":"https:\/\/feda.org\/feda2k16\/author\/feda2k16\/"}]}},"_links":{"self":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts\/1448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/comments?post=1448"}],"version-history":[{"count":2,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts\/1448\/revisions"}],"predecessor-version":[{"id":13291,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts\/1448\/revisions\/13291"}],"wp:attachment":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/media?parent=1448"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/categories?post=1448"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/tags?post=1448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}