{"id":15371,"date":"2019-08-02T15:54:28","date_gmt":"2019-08-02T15:54:28","guid":{"rendered":"https:\/\/feda.org\/feda2k16\/?p=15371"},"modified":"2019-08-03T20:25:36","modified_gmt":"2019-08-03T20:25:36","slug":"circular-18-2019-relacion-de-equipos-participantes-en-el-cto-de-espana-de-segunda-division-2019","status":"publish","type":"post","link":"https:\/\/feda.org\/feda2k16\/circular-18-2019-relacion-de-equipos-participantes-en-el-cto-de-espana-de-segunda-division-2019\/","title":{"rendered":"Circular 18\/2019 &#8211;  Equipos Participantes CECLUB 2\u00aa Divisi\u00f3n 2019. ANULADA"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"wp-block-file\"><a href=\"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/C18-EQUIPOS_CECLUB_2\u00aa_Divisi\u00f3n_-ANULADA.pdf\">Descargar en PDF.<\/a><a href=\"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/C18-EQUIPOS_CECLUB_2\u00aa_Divisi\u00f3n_-ANULADA.pdf\" class=\"wp-block-file__button\" download>Descarga<\/a><\/div>\n\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[207],"tags":[],"class_list":["post-15371","post","type-post","status-publish","format-standard","hentry","category-207"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Circular 18\/2019 - Equipos Participantes CECLUB 2\u00aa Divisi\u00f3n 2019. ANULADA - FEDA<\/title>\n<meta name=\"description\" content=\"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/feda.org\/feda2k16\/circular-18-2019-relacion-de-equipos-participantes-en-el-cto-de-espana-de-segunda-division-2019\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Circular 18\/2019 - Equipos Participantes CECLUB 2\u00aa Divisi\u00f3n 2019. ANULADA - FEDA\" \/>\n<meta property=\"og:description\" content=\"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez\" \/>\n<meta property=\"og:url\" content=\"https:\/\/feda.org\/feda2k16\/circular-18-2019-relacion-de-equipos-participantes-en-el-cto-de-espana-de-segunda-division-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"FEDA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/federacionespanoladeajedrez\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-02T15:54:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-08-03T20:25:36+00:00\" \/>\n<meta name=\"author\" content=\"Nacho\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AjedrezEspanola\" \/>\n<meta name=\"twitter:site\" content=\"@AjedrezEspanola\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nacho\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/circular-18-2019-relacion-de-equipos-participantes-en-el-cto-de-espana-de-segunda-division-2019\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/circular-18-2019-relacion-de-equipos-participantes-en-el-cto-de-espana-de-segunda-division-2019\\\/\"},\"author\":{\"name\":\"Nacho\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/person\\\/6f81e48d83f6f1503890fdb658f2ff4e\"},\"headline\":\"Circular 18\\\/2019 &#8211; Equipos Participantes CECLUB 2\u00aa Divisi\u00f3n 2019. ANULADA\",\"datePublished\":\"2019-08-02T15:54:28+00:00\",\"dateModified\":\"2019-08-03T20:25:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/circular-18-2019-relacion-de-equipos-participantes-en-el-cto-de-espana-de-segunda-division-2019\\\/\"},\"wordCount\":12,\"publisher\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#organization\"},\"articleSection\":[\"2019\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/circular-18-2019-relacion-de-equipos-participantes-en-el-cto-de-espana-de-segunda-division-2019\\\/\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/circular-18-2019-relacion-de-equipos-participantes-en-el-cto-de-espana-de-segunda-division-2019\\\/\",\"name\":\"Circular 18\\\/2019 - Equipos Participantes CECLUB 2\u00aa Divisi\u00f3n 2019. ANULADA - FEDA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#website\"},\"datePublished\":\"2019-08-02T15:54:28+00:00\",\"dateModified\":\"2019-08-03T20:25:36+00:00\",\"description\":\"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/circular-18-2019-relacion-de-equipos-participantes-en-el-cto-de-espana-de-segunda-division-2019\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/feda.org\\\/feda2k16\\\/circular-18-2019-relacion-de-equipos-participantes-en-el-cto-de-espana-de-segunda-division-2019\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/circular-18-2019-relacion-de-equipos-participantes-en-el-cto-de-espana-de-segunda-division-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Circular 18\\\/2019 &#8211; Equipos Participantes CECLUB 2\u00aa Divisi\u00f3n 2019. ANULADA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#website\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/\",\"name\":\"FEDA\",\"description\":\"Federaci\u00f3n Espa\u00f1ola de Ajedrez\",\"publisher\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#organization\"},\"alternateName\":\"Federaci\u00f3n Espa\u00f1ola de Ajedrez\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#organization\",\"name\":\"FEDA\",\"alternateName\":\"Federaci\u00f3n Espa\u00f1ola de Ajedrez\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/NuevoLogo_FEDA_2016.png\",\"contentUrl\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/NuevoLogo_FEDA_2016.png\",\"width\":600,\"height\":600,\"caption\":\"FEDA\"},\"image\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/federacionespanoladeajedrez\\\/\",\"https:\\\/\\\/x.com\\\/AjedrezEspanola\",\"https:\\\/\\\/www.instagram.com\\\/federacionespanolaajedrez\\\/?hl=es\",\"https:\\\/\\\/www.youtube.com\\\/@FederacionEspanoladeAjedrezFED\\\/featured\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/person\\\/6f81e48d83f6f1503890fdb658f2ff4e\",\"name\":\"Nacho\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/author\\\/nacho\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Circular 18\/2019 - Equipos Participantes CECLUB 2\u00aa Divisi\u00f3n 2019. ANULADA - FEDA","description":"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/feda.org\/feda2k16\/circular-18-2019-relacion-de-equipos-participantes-en-el-cto-de-espana-de-segunda-division-2019\/","og_locale":"es_ES","og_type":"article","og_title":"Circular 18\/2019 - Equipos Participantes CECLUB 2\u00aa Divisi\u00f3n 2019. ANULADA - FEDA","og_description":"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez","og_url":"https:\/\/feda.org\/feda2k16\/circular-18-2019-relacion-de-equipos-participantes-en-el-cto-de-espana-de-segunda-division-2019\/","og_site_name":"FEDA","article_publisher":"https:\/\/www.facebook.com\/federacionespanoladeajedrez\/","article_published_time":"2019-08-02T15:54:28+00:00","article_modified_time":"2019-08-03T20:25:36+00:00","author":"Nacho","twitter_card":"summary_large_image","twitter_creator":"@AjedrezEspanola","twitter_site":"@AjedrezEspanola","twitter_misc":{"Escrito por":"Nacho"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/feda.org\/feda2k16\/circular-18-2019-relacion-de-equipos-participantes-en-el-cto-de-espana-de-segunda-division-2019\/#article","isPartOf":{"@id":"https:\/\/feda.org\/feda2k16\/circular-18-2019-relacion-de-equipos-participantes-en-el-cto-de-espana-de-segunda-division-2019\/"},"author":{"name":"Nacho","@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/person\/6f81e48d83f6f1503890fdb658f2ff4e"},"headline":"Circular 18\/2019 &#8211; Equipos Participantes CECLUB 2\u00aa Divisi\u00f3n 2019. ANULADA","datePublished":"2019-08-02T15:54:28+00:00","dateModified":"2019-08-03T20:25:36+00:00","mainEntityOfPage":{"@id":"https:\/\/feda.org\/feda2k16\/circular-18-2019-relacion-de-equipos-participantes-en-el-cto-de-espana-de-segunda-division-2019\/"},"wordCount":12,"publisher":{"@id":"https:\/\/feda.org\/feda2k16\/#organization"},"articleSection":["2019"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/feda.org\/feda2k16\/circular-18-2019-relacion-de-equipos-participantes-en-el-cto-de-espana-de-segunda-division-2019\/","url":"https:\/\/feda.org\/feda2k16\/circular-18-2019-relacion-de-equipos-participantes-en-el-cto-de-espana-de-segunda-division-2019\/","name":"Circular 18\/2019 - Equipos Participantes CECLUB 2\u00aa Divisi\u00f3n 2019. ANULADA - FEDA","isPartOf":{"@id":"https:\/\/feda.org\/feda2k16\/#website"},"datePublished":"2019-08-02T15:54:28+00:00","dateModified":"2019-08-03T20:25:36+00:00","description":"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez","breadcrumb":{"@id":"https:\/\/feda.org\/feda2k16\/circular-18-2019-relacion-de-equipos-participantes-en-el-cto-de-espana-de-segunda-division-2019\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/feda.org\/feda2k16\/circular-18-2019-relacion-de-equipos-participantes-en-el-cto-de-espana-de-segunda-division-2019\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/feda.org\/feda2k16\/circular-18-2019-relacion-de-equipos-participantes-en-el-cto-de-espana-de-segunda-division-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/feda.org\/feda2k16\/"},{"@type":"ListItem","position":2,"name":"Circular 18\/2019 &#8211; Equipos Participantes CECLUB 2\u00aa Divisi\u00f3n 2019. ANULADA"}]},{"@type":"WebSite","@id":"https:\/\/feda.org\/feda2k16\/#website","url":"https:\/\/feda.org\/feda2k16\/","name":"FEDA","description":"Federaci\u00f3n Espa\u00f1ola de Ajedrez","publisher":{"@id":"https:\/\/feda.org\/feda2k16\/#organization"},"alternateName":"Federaci\u00f3n Espa\u00f1ola de Ajedrez","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/feda.org\/feda2k16\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/feda.org\/feda2k16\/#organization","name":"FEDA","alternateName":"Federaci\u00f3n Espa\u00f1ola de Ajedrez","url":"https:\/\/feda.org\/feda2k16\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/logo\/image\/","url":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/NuevoLogo_FEDA_2016.png","contentUrl":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/NuevoLogo_FEDA_2016.png","width":600,"height":600,"caption":"FEDA"},"image":{"@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/federacionespanoladeajedrez\/","https:\/\/x.com\/AjedrezEspanola","https:\/\/www.instagram.com\/federacionespanolaajedrez\/?hl=es","https:\/\/www.youtube.com\/@FederacionEspanoladeAjedrezFED\/featured"]},{"@type":"Person","@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/person\/6f81e48d83f6f1503890fdb658f2ff4e","name":"Nacho","url":"https:\/\/feda.org\/feda2k16\/author\/nacho\/"}]}},"_links":{"self":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts\/15371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/comments?post=15371"}],"version-history":[{"count":6,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts\/15371\/revisions"}],"predecessor-version":[{"id":15461,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts\/15371\/revisions\/15461"}],"wp:attachment":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/media?parent=15371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/categories?post=15371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/tags?post=15371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}