{"id":20750,"date":"2022-08-20T01:24:52","date_gmt":"2022-08-20T01:24:52","guid":{"rendered":"https:\/\/feda.org\/feda2k16\/?p=20750"},"modified":"2022-08-21T00:34:11","modified_gmt":"2022-08-21T00:34:11","slug":"campeonato-de-espana-de-ajedrez-relampago-9","status":"publish","type":"post","link":"https:\/\/feda.org\/feda2k16\/campeonato-de-espana-de-ajedrez-relampago-9\/","title":{"rendered":"Campeonato de Espa\u00f1a de Ajedrez Rel\u00e1mpago."},"content":{"rendered":"\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/PAT_8494-scaled.jpg\" alt=\"\" class=\"wp-image-20751\" srcset=\"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/PAT_8494-scaled.jpg 2560w, https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/PAT_8494-768x512.jpg 768w, https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/PAT_8494-1536x1024.jpg 1536w, https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/PAT_8494-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<p>El Campeonato de Espa\u00f1a de Ajedrez Rel\u00e1mpago, con la participaci\u00f3n de 174 jugadores, se ha disputado durante la tarde del d\u00eda 19 de agosto en el Hotel Casa Palacio en Meng\u00edbar. \u00a0<\/p>\n<p>El jugador de la Federaci\u00f3n de Ajedrez de la Regi\u00f3n de Murcia, Eduardo Iturrizaga Bonelli, se ha proclamado campe\u00f3n absoluto con 8 puntos. Daniil Yuffa tambi\u00e9n jugador de la Federaci\u00f3n de Ajedrez de la Regi\u00f3n de Murcia y Jaime Santos Latasa de la Federaci\u00f3n Extreme\u00f1a, empatados a 7,5 puntos, han completado el podio como segundo y tercer clasificado respectivamente.<\/p>\n<p>Rebeca Jim\u00e9nez Fern\u00e1ndez, con 5 puntos, ha ocupado el primer puesto en la clasificaci\u00f3n femenina y Diego Mac\u00edas Pino con 7 puntos se ha alzado con el premio de Juvenil Sub 18. Ambos jugadores son de la Federaci\u00f3n de Ajedrez de la Comunidad Valenciana.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/info64.org\/campeonato-de-espana-absoluto-ajedrez-relampago-2022\/standings\">Clasificaci\u00f3n en Info64<\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.facebook.com\/media\/set\/?set=a.3201593963484954&amp;type=3\">Galer\u00eda de fotos<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Campeonato de Espa\u00f1a de Ajedrez Rel\u00e1mpago, con la participaci\u00f3n de 174 jugadores, se ha disputado durante la tarde del d\u00eda 19 de agosto en el Hotel Casa Palacio en Meng\u00edbar. \u00a0 El jugador de la Federaci\u00f3n de Ajedrez de la Regi\u00f3n de Murcia, Eduardo Iturrizaga Bonelli, se ha proclamado campe\u00f3n absoluto con 8 puntos. [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-20750","post","type-post","status-publish","format-standard","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Campeonato de Espa\u00f1a de Ajedrez Rel\u00e1mpago. - FEDA<\/title>\n<meta name=\"description\" content=\"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/feda.org\/feda2k16\/campeonato-de-espana-de-ajedrez-relampago-9\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Campeonato de Espa\u00f1a de Ajedrez Rel\u00e1mpago. - FEDA\" \/>\n<meta property=\"og:description\" content=\"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez\" \/>\n<meta property=\"og:url\" content=\"https:\/\/feda.org\/feda2k16\/campeonato-de-espana-de-ajedrez-relampago-9\/\" \/>\n<meta property=\"og:site_name\" content=\"FEDA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/federacionespanoladeajedrez\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-20T01:24:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-21T00:34:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/PAT_8494-scaled.jpg\" \/>\n<meta name=\"author\" content=\"elefante66\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AjedrezEspanola\" \/>\n<meta name=\"twitter:site\" content=\"@AjedrezEspanola\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"elefante66\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-de-espana-de-ajedrez-relampago-9\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-de-espana-de-ajedrez-relampago-9\\\/\"},\"author\":{\"name\":\"elefante66\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/person\\\/b39486343e189c77e58d02641385fe29\"},\"headline\":\"Campeonato de Espa\u00f1a de Ajedrez Rel\u00e1mpago.\",\"datePublished\":\"2022-08-20T01:24:52+00:00\",\"dateModified\":\"2022-08-21T00:34:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-de-espana-de-ajedrez-relampago-9\\\/\"},\"wordCount\":161,\"publisher\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-de-espana-de-ajedrez-relampago-9\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/PAT_8494-scaled.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-de-espana-de-ajedrez-relampago-9\\\/\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-de-espana-de-ajedrez-relampago-9\\\/\",\"name\":\"Campeonato de Espa\u00f1a de Ajedrez Rel\u00e1mpago. - FEDA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-de-espana-de-ajedrez-relampago-9\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-de-espana-de-ajedrez-relampago-9\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/PAT_8494-scaled.jpg\",\"datePublished\":\"2022-08-20T01:24:52+00:00\",\"dateModified\":\"2022-08-21T00:34:11+00:00\",\"description\":\"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-de-espana-de-ajedrez-relampago-9\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-de-espana-de-ajedrez-relampago-9\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-de-espana-de-ajedrez-relampago-9\\\/#primaryimage\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/PAT_8494-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/PAT_8494-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-de-espana-de-ajedrez-relampago-9\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Campeonato de Espa\u00f1a de Ajedrez Rel\u00e1mpago.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#website\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/\",\"name\":\"FEDA\",\"description\":\"Federaci\u00f3n Espa\u00f1ola de Ajedrez\",\"publisher\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#organization\"},\"alternateName\":\"Federaci\u00f3n Espa\u00f1ola de Ajedrez\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#organization\",\"name\":\"FEDA\",\"alternateName\":\"Federaci\u00f3n Espa\u00f1ola de Ajedrez\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/NuevoLogo_FEDA_2016.png\",\"contentUrl\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/NuevoLogo_FEDA_2016.png\",\"width\":600,\"height\":600,\"caption\":\"FEDA\"},\"image\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/federacionespanoladeajedrez\\\/\",\"https:\\\/\\\/x.com\\\/AjedrezEspanola\",\"https:\\\/\\\/www.instagram.com\\\/federacionespanolaajedrez\\\/?hl=es\",\"https:\\\/\\\/www.youtube.com\\\/@FederacionEspanoladeAjedrezFED\\\/featured\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/person\\\/b39486343e189c77e58d02641385fe29\",\"name\":\"elefante66\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/author\\\/elefante66\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Campeonato de Espa\u00f1a de Ajedrez Rel\u00e1mpago. - FEDA","description":"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/feda.org\/feda2k16\/campeonato-de-espana-de-ajedrez-relampago-9\/","og_locale":"es_ES","og_type":"article","og_title":"Campeonato de Espa\u00f1a de Ajedrez Rel\u00e1mpago. - FEDA","og_description":"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez","og_url":"https:\/\/feda.org\/feda2k16\/campeonato-de-espana-de-ajedrez-relampago-9\/","og_site_name":"FEDA","article_publisher":"https:\/\/www.facebook.com\/federacionespanoladeajedrez\/","article_published_time":"2022-08-20T01:24:52+00:00","article_modified_time":"2022-08-21T00:34:11+00:00","og_image":[{"url":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/PAT_8494-scaled.jpg","type":"","width":"","height":""}],"author":"elefante66","twitter_card":"summary_large_image","twitter_creator":"@AjedrezEspanola","twitter_site":"@AjedrezEspanola","twitter_misc":{"Escrito por":"elefante66","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/feda.org\/feda2k16\/campeonato-de-espana-de-ajedrez-relampago-9\/#article","isPartOf":{"@id":"https:\/\/feda.org\/feda2k16\/campeonato-de-espana-de-ajedrez-relampago-9\/"},"author":{"name":"elefante66","@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/person\/b39486343e189c77e58d02641385fe29"},"headline":"Campeonato de Espa\u00f1a de Ajedrez Rel\u00e1mpago.","datePublished":"2022-08-20T01:24:52+00:00","dateModified":"2022-08-21T00:34:11+00:00","mainEntityOfPage":{"@id":"https:\/\/feda.org\/feda2k16\/campeonato-de-espana-de-ajedrez-relampago-9\/"},"wordCount":161,"publisher":{"@id":"https:\/\/feda.org\/feda2k16\/#organization"},"image":{"@id":"https:\/\/feda.org\/feda2k16\/campeonato-de-espana-de-ajedrez-relampago-9\/#primaryimage"},"thumbnailUrl":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/PAT_8494-scaled.jpg","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/feda.org\/feda2k16\/campeonato-de-espana-de-ajedrez-relampago-9\/","url":"https:\/\/feda.org\/feda2k16\/campeonato-de-espana-de-ajedrez-relampago-9\/","name":"Campeonato de Espa\u00f1a de Ajedrez Rel\u00e1mpago. - FEDA","isPartOf":{"@id":"https:\/\/feda.org\/feda2k16\/#website"},"primaryImageOfPage":{"@id":"https:\/\/feda.org\/feda2k16\/campeonato-de-espana-de-ajedrez-relampago-9\/#primaryimage"},"image":{"@id":"https:\/\/feda.org\/feda2k16\/campeonato-de-espana-de-ajedrez-relampago-9\/#primaryimage"},"thumbnailUrl":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/PAT_8494-scaled.jpg","datePublished":"2022-08-20T01:24:52+00:00","dateModified":"2022-08-21T00:34:11+00:00","description":"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez","breadcrumb":{"@id":"https:\/\/feda.org\/feda2k16\/campeonato-de-espana-de-ajedrez-relampago-9\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/feda.org\/feda2k16\/campeonato-de-espana-de-ajedrez-relampago-9\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/feda.org\/feda2k16\/campeonato-de-espana-de-ajedrez-relampago-9\/#primaryimage","url":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/PAT_8494-scaled.jpg","contentUrl":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/PAT_8494-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/feda.org\/feda2k16\/campeonato-de-espana-de-ajedrez-relampago-9\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/feda.org\/feda2k16\/"},{"@type":"ListItem","position":2,"name":"Campeonato de Espa\u00f1a de Ajedrez Rel\u00e1mpago."}]},{"@type":"WebSite","@id":"https:\/\/feda.org\/feda2k16\/#website","url":"https:\/\/feda.org\/feda2k16\/","name":"FEDA","description":"Federaci\u00f3n Espa\u00f1ola de Ajedrez","publisher":{"@id":"https:\/\/feda.org\/feda2k16\/#organization"},"alternateName":"Federaci\u00f3n Espa\u00f1ola de Ajedrez","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/feda.org\/feda2k16\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/feda.org\/feda2k16\/#organization","name":"FEDA","alternateName":"Federaci\u00f3n Espa\u00f1ola de Ajedrez","url":"https:\/\/feda.org\/feda2k16\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/logo\/image\/","url":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/NuevoLogo_FEDA_2016.png","contentUrl":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/NuevoLogo_FEDA_2016.png","width":600,"height":600,"caption":"FEDA"},"image":{"@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/federacionespanoladeajedrez\/","https:\/\/x.com\/AjedrezEspanola","https:\/\/www.instagram.com\/federacionespanolaajedrez\/?hl=es","https:\/\/www.youtube.com\/@FederacionEspanoladeAjedrezFED\/featured"]},{"@type":"Person","@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/person\/b39486343e189c77e58d02641385fe29","name":"elefante66","url":"https:\/\/feda.org\/feda2k16\/author\/elefante66\/"}]}},"_links":{"self":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts\/20750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/comments?post=20750"}],"version-history":[{"count":4,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts\/20750\/revisions"}],"predecessor-version":[{"id":20757,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts\/20750\/revisions\/20757"}],"wp:attachment":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/media?parent=20750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/categories?post=20750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/tags?post=20750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}