{"id":22638,"date":"2023-08-05T22:45:02","date_gmt":"2023-08-05T22:45:02","guid":{"rendered":"https:\/\/feda.org\/feda2k16\/?p=22638"},"modified":"2023-08-31T15:40:46","modified_gmt":"2023-08-31T15:40:46","slug":"campeonato-de-espana-por-edades-sub-18-2","status":"publish","type":"post","link":"https:\/\/feda.org\/feda2k16\/campeonato-de-espana-por-edades-sub-18-2\/","title":{"rendered":"Campeonato de Espa\u00f1a por Edades Sub 18."},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/02d836f8-7bd1-4aba-a096-d0239ce8c37f.jpg\" alt=\"\" class=\"wp-image-22637\" width=\"645\" height=\"603\" srcset=\"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/02d836f8-7bd1-4aba-a096-d0239ce8c37f.jpg 900w, https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/02d836f8-7bd1-4aba-a096-d0239ce8c37f-768x719.jpg 768w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/><\/figure>\n<\/div>\n\n\n<p>Javier Habans Aguerrea y Leyre Abrisqueta Zudaire de Navarra se han proclamado Campeones de Espa\u00f1a por Edades Sub 18. Acompa\u00f1an en el podio a Javier, Alex Garrido Out\u00f3n de la Federaci\u00f3n Extreme\u00f1a y en la tercera posici\u00f3n de la Federaci\u00f3n Andaluza de Ajedrez, Bernardo Cesar Maestre.<\/p>\n<p>En el podio Femenino acompa\u00f1an a Leyre, Pilar Diaz Garc\u00eda de Extremadura y Silvia Do\u00f1ate Moreno en tercera posici\u00f3n de la Federaci\u00f3n Valenciana.<\/p>\n<p style=\"text-align: center;\">Clasificaci\u00f3n: <a href=\"https:\/\/info64.org\/ce-sub18-2023\/standings\">INFO64<\/a><\/p>\n<p style=\"text-align: center;\">Galer\u00eda de fotos: <a href=\"https:\/\/www.facebook.com\/media\/set\/?set=a.619519393603867&amp;type=3\">Facebook FEDA<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Javier Habans Aguerrea y Leyre Abrisqueta Zudaire de Navarra se han proclamado Campeones de Espa\u00f1a por Edades Sub 18. Acompa\u00f1an en el podio a Javier, Alex Garrido Out\u00f3n de la Federaci\u00f3n Extreme\u00f1a y en la tercera posici\u00f3n de la Federaci\u00f3n Andaluza de Ajedrez, Bernardo Cesar Maestre. En el podio Femenino acompa\u00f1an a Leyre, Pilar Diaz [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-22638","post","type-post","status-publish","format-standard","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Campeonato de Espa\u00f1a por Edades Sub 18. - FEDA<\/title>\n<meta name=\"description\" content=\"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/feda.org\/feda2k16\/campeonato-de-espana-por-edades-sub-18-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Campeonato de Espa\u00f1a por Edades Sub 18. - FEDA\" \/>\n<meta property=\"og:description\" content=\"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez\" \/>\n<meta property=\"og:url\" content=\"https:\/\/feda.org\/feda2k16\/campeonato-de-espana-por-edades-sub-18-2\/\" \/>\n<meta property=\"og:site_name\" content=\"FEDA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/federacionespanoladeajedrez\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-05T22:45:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-31T15:40:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/02d836f8-7bd1-4aba-a096-d0239ce8c37f.jpg\" \/>\n<meta name=\"author\" content=\"elefante66\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AjedrezEspanola\" \/>\n<meta name=\"twitter:site\" content=\"@AjedrezEspanola\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"elefante66\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-de-espana-por-edades-sub-18-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-de-espana-por-edades-sub-18-2\\\/\"},\"author\":{\"name\":\"elefante66\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/person\\\/b39486343e189c77e58d02641385fe29\"},\"headline\":\"Campeonato de Espa\u00f1a por Edades Sub 18.\",\"datePublished\":\"2023-08-05T22:45:02+00:00\",\"dateModified\":\"2023-08-31T15:40:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-de-espana-por-edades-sub-18-2\\\/\"},\"wordCount\":96,\"publisher\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-de-espana-por-edades-sub-18-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/02d836f8-7bd1-4aba-a096-d0239ce8c37f.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-de-espana-por-edades-sub-18-2\\\/\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-de-espana-por-edades-sub-18-2\\\/\",\"name\":\"Campeonato de Espa\u00f1a por Edades Sub 18. - FEDA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-de-espana-por-edades-sub-18-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-de-espana-por-edades-sub-18-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/02d836f8-7bd1-4aba-a096-d0239ce8c37f.jpg\",\"datePublished\":\"2023-08-05T22:45:02+00:00\",\"dateModified\":\"2023-08-31T15:40:46+00:00\",\"description\":\"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-de-espana-por-edades-sub-18-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-de-espana-por-edades-sub-18-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-de-espana-por-edades-sub-18-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/02d836f8-7bd1-4aba-a096-d0239ce8c37f.jpg\",\"contentUrl\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/02d836f8-7bd1-4aba-a096-d0239ce8c37f.jpg\",\"width\":900,\"height\":842},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonato-de-espana-por-edades-sub-18-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Campeonato de Espa\u00f1a por Edades Sub 18.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#website\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/\",\"name\":\"FEDA\",\"description\":\"Federaci\u00f3n Espa\u00f1ola de Ajedrez\",\"publisher\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#organization\"},\"alternateName\":\"Federaci\u00f3n Espa\u00f1ola de Ajedrez\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#organization\",\"name\":\"FEDA\",\"alternateName\":\"Federaci\u00f3n Espa\u00f1ola de Ajedrez\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/NuevoLogo_FEDA_2016.png\",\"contentUrl\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/NuevoLogo_FEDA_2016.png\",\"width\":600,\"height\":600,\"caption\":\"FEDA\"},\"image\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/federacionespanoladeajedrez\\\/\",\"https:\\\/\\\/x.com\\\/AjedrezEspanola\",\"https:\\\/\\\/www.instagram.com\\\/federacionespanolaajedrez\\\/?hl=es\",\"https:\\\/\\\/www.youtube.com\\\/@FederacionEspanoladeAjedrezFED\\\/featured\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/person\\\/b39486343e189c77e58d02641385fe29\",\"name\":\"elefante66\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/author\\\/elefante66\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Campeonato de Espa\u00f1a por Edades Sub 18. - FEDA","description":"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/feda.org\/feda2k16\/campeonato-de-espana-por-edades-sub-18-2\/","og_locale":"es_ES","og_type":"article","og_title":"Campeonato de Espa\u00f1a por Edades Sub 18. - FEDA","og_description":"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez","og_url":"https:\/\/feda.org\/feda2k16\/campeonato-de-espana-por-edades-sub-18-2\/","og_site_name":"FEDA","article_publisher":"https:\/\/www.facebook.com\/federacionespanoladeajedrez\/","article_published_time":"2023-08-05T22:45:02+00:00","article_modified_time":"2023-08-31T15:40:46+00:00","og_image":[{"url":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/02d836f8-7bd1-4aba-a096-d0239ce8c37f.jpg","type":"","width":"","height":""}],"author":"elefante66","twitter_card":"summary_large_image","twitter_creator":"@AjedrezEspanola","twitter_site":"@AjedrezEspanola","twitter_misc":{"Escrito por":"elefante66"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/feda.org\/feda2k16\/campeonato-de-espana-por-edades-sub-18-2\/#article","isPartOf":{"@id":"https:\/\/feda.org\/feda2k16\/campeonato-de-espana-por-edades-sub-18-2\/"},"author":{"name":"elefante66","@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/person\/b39486343e189c77e58d02641385fe29"},"headline":"Campeonato de Espa\u00f1a por Edades Sub 18.","datePublished":"2023-08-05T22:45:02+00:00","dateModified":"2023-08-31T15:40:46+00:00","mainEntityOfPage":{"@id":"https:\/\/feda.org\/feda2k16\/campeonato-de-espana-por-edades-sub-18-2\/"},"wordCount":96,"publisher":{"@id":"https:\/\/feda.org\/feda2k16\/#organization"},"image":{"@id":"https:\/\/feda.org\/feda2k16\/campeonato-de-espana-por-edades-sub-18-2\/#primaryimage"},"thumbnailUrl":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/02d836f8-7bd1-4aba-a096-d0239ce8c37f.jpg","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/feda.org\/feda2k16\/campeonato-de-espana-por-edades-sub-18-2\/","url":"https:\/\/feda.org\/feda2k16\/campeonato-de-espana-por-edades-sub-18-2\/","name":"Campeonato de Espa\u00f1a por Edades Sub 18. - FEDA","isPartOf":{"@id":"https:\/\/feda.org\/feda2k16\/#website"},"primaryImageOfPage":{"@id":"https:\/\/feda.org\/feda2k16\/campeonato-de-espana-por-edades-sub-18-2\/#primaryimage"},"image":{"@id":"https:\/\/feda.org\/feda2k16\/campeonato-de-espana-por-edades-sub-18-2\/#primaryimage"},"thumbnailUrl":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/02d836f8-7bd1-4aba-a096-d0239ce8c37f.jpg","datePublished":"2023-08-05T22:45:02+00:00","dateModified":"2023-08-31T15:40:46+00:00","description":"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez","breadcrumb":{"@id":"https:\/\/feda.org\/feda2k16\/campeonato-de-espana-por-edades-sub-18-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/feda.org\/feda2k16\/campeonato-de-espana-por-edades-sub-18-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/feda.org\/feda2k16\/campeonato-de-espana-por-edades-sub-18-2\/#primaryimage","url":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/02d836f8-7bd1-4aba-a096-d0239ce8c37f.jpg","contentUrl":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/02d836f8-7bd1-4aba-a096-d0239ce8c37f.jpg","width":900,"height":842},{"@type":"BreadcrumbList","@id":"https:\/\/feda.org\/feda2k16\/campeonato-de-espana-por-edades-sub-18-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/feda.org\/feda2k16\/"},{"@type":"ListItem","position":2,"name":"Campeonato de Espa\u00f1a por Edades Sub 18."}]},{"@type":"WebSite","@id":"https:\/\/feda.org\/feda2k16\/#website","url":"https:\/\/feda.org\/feda2k16\/","name":"FEDA","description":"Federaci\u00f3n Espa\u00f1ola de Ajedrez","publisher":{"@id":"https:\/\/feda.org\/feda2k16\/#organization"},"alternateName":"Federaci\u00f3n Espa\u00f1ola de Ajedrez","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/feda.org\/feda2k16\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/feda.org\/feda2k16\/#organization","name":"FEDA","alternateName":"Federaci\u00f3n Espa\u00f1ola de Ajedrez","url":"https:\/\/feda.org\/feda2k16\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/logo\/image\/","url":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/NuevoLogo_FEDA_2016.png","contentUrl":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/NuevoLogo_FEDA_2016.png","width":600,"height":600,"caption":"FEDA"},"image":{"@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/federacionespanoladeajedrez\/","https:\/\/x.com\/AjedrezEspanola","https:\/\/www.instagram.com\/federacionespanolaajedrez\/?hl=es","https:\/\/www.youtube.com\/@FederacionEspanoladeAjedrezFED\/featured"]},{"@type":"Person","@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/person\/b39486343e189c77e58d02641385fe29","name":"elefante66","url":"https:\/\/feda.org\/feda2k16\/author\/elefante66\/"}]}},"_links":{"self":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts\/22638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/comments?post=22638"}],"version-history":[{"count":2,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts\/22638\/revisions"}],"predecessor-version":[{"id":22716,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts\/22638\/revisions\/22716"}],"wp:attachment":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/media?parent=22638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/categories?post=22638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/tags?post=22638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}