{"id":22684,"date":"2023-08-21T15:45:06","date_gmt":"2023-08-21T15:45:06","guid":{"rendered":"https:\/\/feda.org\/feda2k16\/?p=22684"},"modified":"2023-08-21T15:46:06","modified_gmt":"2023-08-21T15:46:06","slug":"campeonatos-de-espana-de-ajedrez-en-chessbase-es","status":"publish","type":"post","link":"https:\/\/feda.org\/feda2k16\/campeonatos-de-espana-de-ajedrez-en-chessbase-es\/","title":{"rendered":"Campeonatos de Espa\u00f1a de Ajedrez en Chessbase.es"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/es.chessbase.com\/post\/campeonatos-de-espana-de-ajedrez-en-linares-rapido-relampago-ceclub-segunda-division-primera-division\"><img fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"1748\" src=\"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/PAT_9349-scaled.jpg\" alt=\"\" class=\"wp-image-22685\" srcset=\"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/PAT_9349-scaled.jpg 2560w, https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/PAT_9349-768x524.jpg 768w, https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/PAT_9349-1536x1049.jpg 1536w, https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/PAT_9349-2048x1399.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/a><\/figure>\n\n\n\n\n\n<p>Extraordinario reportaje de los diferentes Campeonatos de Espa\u00f1a de Ajedrez: CECLUB Segunda Divisi\u00f3n, r\u00e1pido y rel\u00e1mpago y Primera Divisi\u00f3n, as\u00ed mismo, enlaces a la galer\u00eda de fotos y clasificaci\u00f3n de cada uno de ellos en <a href=\"https:\/\/es.chessbase.com\/post\/campeonatos-de-espana-de-ajedrez-en-linares-rapido-relampago-ceclub-segunda-division-primera-division\">chessbase.es<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Extraordinario reportaje de los diferentes Campeonatos de Espa\u00f1a de Ajedrez: CECLUB Segunda Divisi\u00f3n, r\u00e1pido y rel\u00e1mpago y Primera Divisi\u00f3n, as\u00ed mismo, enlaces a la galer\u00eda de fotos y clasificaci\u00f3n de cada uno de ellos en chessbase.es<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-22684","post","type-post","status-publish","format-standard","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Campeonatos de Espa\u00f1a de Ajedrez en Chessbase.es - FEDA<\/title>\n<meta name=\"description\" content=\"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/feda.org\/feda2k16\/campeonatos-de-espana-de-ajedrez-en-chessbase-es\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Campeonatos de Espa\u00f1a de Ajedrez en Chessbase.es - FEDA\" \/>\n<meta property=\"og:description\" content=\"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez\" \/>\n<meta property=\"og:url\" content=\"https:\/\/feda.org\/feda2k16\/campeonatos-de-espana-de-ajedrez-en-chessbase-es\/\" \/>\n<meta property=\"og:site_name\" content=\"FEDA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/federacionespanoladeajedrez\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-21T15:45:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-21T15:46:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/PAT_9349-scaled.jpg\" \/>\n<meta name=\"author\" content=\"elefante66\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AjedrezEspanola\" \/>\n<meta name=\"twitter:site\" content=\"@AjedrezEspanola\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"elefante66\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonatos-de-espana-de-ajedrez-en-chessbase-es\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonatos-de-espana-de-ajedrez-en-chessbase-es\\\/\"},\"author\":{\"name\":\"elefante66\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/person\\\/b39486343e189c77e58d02641385fe29\"},\"headline\":\"Campeonatos de Espa\u00f1a de Ajedrez en Chessbase.es\",\"datePublished\":\"2023-08-21T15:45:06+00:00\",\"dateModified\":\"2023-08-21T15:46:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonatos-de-espana-de-ajedrez-en-chessbase-es\\\/\"},\"wordCount\":53,\"publisher\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonatos-de-espana-de-ajedrez-en-chessbase-es\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/PAT_9349-scaled.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonatos-de-espana-de-ajedrez-en-chessbase-es\\\/\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonatos-de-espana-de-ajedrez-en-chessbase-es\\\/\",\"name\":\"Campeonatos de Espa\u00f1a de Ajedrez en Chessbase.es - FEDA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonatos-de-espana-de-ajedrez-en-chessbase-es\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonatos-de-espana-de-ajedrez-en-chessbase-es\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/PAT_9349-scaled.jpg\",\"datePublished\":\"2023-08-21T15:45:06+00:00\",\"dateModified\":\"2023-08-21T15:46:06+00:00\",\"description\":\"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonatos-de-espana-de-ajedrez-en-chessbase-es\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonatos-de-espana-de-ajedrez-en-chessbase-es\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonatos-de-espana-de-ajedrez-en-chessbase-es\\\/#primaryimage\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/PAT_9349-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/PAT_9349-scaled.jpg\",\"width\":2560,\"height\":1748},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeonatos-de-espana-de-ajedrez-en-chessbase-es\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Campeonatos de Espa\u00f1a de Ajedrez en Chessbase.es\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#website\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/\",\"name\":\"FEDA\",\"description\":\"Federaci\u00f3n Espa\u00f1ola de Ajedrez\",\"publisher\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#organization\"},\"alternateName\":\"Federaci\u00f3n Espa\u00f1ola de Ajedrez\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#organization\",\"name\":\"FEDA\",\"alternateName\":\"Federaci\u00f3n Espa\u00f1ola de Ajedrez\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/NuevoLogo_FEDA_2016.png\",\"contentUrl\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/NuevoLogo_FEDA_2016.png\",\"width\":600,\"height\":600,\"caption\":\"FEDA\"},\"image\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/federacionespanoladeajedrez\\\/\",\"https:\\\/\\\/x.com\\\/AjedrezEspanola\",\"https:\\\/\\\/www.instagram.com\\\/federacionespanolaajedrez\\\/?hl=es\",\"https:\\\/\\\/www.youtube.com\\\/@FederacionEspanoladeAjedrezFED\\\/featured\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/person\\\/b39486343e189c77e58d02641385fe29\",\"name\":\"elefante66\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/author\\\/elefante66\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Campeonatos de Espa\u00f1a de Ajedrez en Chessbase.es - FEDA","description":"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/feda.org\/feda2k16\/campeonatos-de-espana-de-ajedrez-en-chessbase-es\/","og_locale":"es_ES","og_type":"article","og_title":"Campeonatos de Espa\u00f1a de Ajedrez en Chessbase.es - FEDA","og_description":"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez","og_url":"https:\/\/feda.org\/feda2k16\/campeonatos-de-espana-de-ajedrez-en-chessbase-es\/","og_site_name":"FEDA","article_publisher":"https:\/\/www.facebook.com\/federacionespanoladeajedrez\/","article_published_time":"2023-08-21T15:45:06+00:00","article_modified_time":"2023-08-21T15:46:06+00:00","og_image":[{"url":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/PAT_9349-scaled.jpg","type":"","width":"","height":""}],"author":"elefante66","twitter_card":"summary_large_image","twitter_creator":"@AjedrezEspanola","twitter_site":"@AjedrezEspanola","twitter_misc":{"Escrito por":"elefante66"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/feda.org\/feda2k16\/campeonatos-de-espana-de-ajedrez-en-chessbase-es\/#article","isPartOf":{"@id":"https:\/\/feda.org\/feda2k16\/campeonatos-de-espana-de-ajedrez-en-chessbase-es\/"},"author":{"name":"elefante66","@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/person\/b39486343e189c77e58d02641385fe29"},"headline":"Campeonatos de Espa\u00f1a de Ajedrez en Chessbase.es","datePublished":"2023-08-21T15:45:06+00:00","dateModified":"2023-08-21T15:46:06+00:00","mainEntityOfPage":{"@id":"https:\/\/feda.org\/feda2k16\/campeonatos-de-espana-de-ajedrez-en-chessbase-es\/"},"wordCount":53,"publisher":{"@id":"https:\/\/feda.org\/feda2k16\/#organization"},"image":{"@id":"https:\/\/feda.org\/feda2k16\/campeonatos-de-espana-de-ajedrez-en-chessbase-es\/#primaryimage"},"thumbnailUrl":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/PAT_9349-scaled.jpg","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/feda.org\/feda2k16\/campeonatos-de-espana-de-ajedrez-en-chessbase-es\/","url":"https:\/\/feda.org\/feda2k16\/campeonatos-de-espana-de-ajedrez-en-chessbase-es\/","name":"Campeonatos de Espa\u00f1a de Ajedrez en Chessbase.es - FEDA","isPartOf":{"@id":"https:\/\/feda.org\/feda2k16\/#website"},"primaryImageOfPage":{"@id":"https:\/\/feda.org\/feda2k16\/campeonatos-de-espana-de-ajedrez-en-chessbase-es\/#primaryimage"},"image":{"@id":"https:\/\/feda.org\/feda2k16\/campeonatos-de-espana-de-ajedrez-en-chessbase-es\/#primaryimage"},"thumbnailUrl":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/PAT_9349-scaled.jpg","datePublished":"2023-08-21T15:45:06+00:00","dateModified":"2023-08-21T15:46:06+00:00","description":"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez","breadcrumb":{"@id":"https:\/\/feda.org\/feda2k16\/campeonatos-de-espana-de-ajedrez-en-chessbase-es\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/feda.org\/feda2k16\/campeonatos-de-espana-de-ajedrez-en-chessbase-es\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/feda.org\/feda2k16\/campeonatos-de-espana-de-ajedrez-en-chessbase-es\/#primaryimage","url":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/PAT_9349-scaled.jpg","contentUrl":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/PAT_9349-scaled.jpg","width":2560,"height":1748},{"@type":"BreadcrumbList","@id":"https:\/\/feda.org\/feda2k16\/campeonatos-de-espana-de-ajedrez-en-chessbase-es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/feda.org\/feda2k16\/"},{"@type":"ListItem","position":2,"name":"Campeonatos de Espa\u00f1a de Ajedrez en Chessbase.es"}]},{"@type":"WebSite","@id":"https:\/\/feda.org\/feda2k16\/#website","url":"https:\/\/feda.org\/feda2k16\/","name":"FEDA","description":"Federaci\u00f3n Espa\u00f1ola de Ajedrez","publisher":{"@id":"https:\/\/feda.org\/feda2k16\/#organization"},"alternateName":"Federaci\u00f3n Espa\u00f1ola de Ajedrez","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/feda.org\/feda2k16\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/feda.org\/feda2k16\/#organization","name":"FEDA","alternateName":"Federaci\u00f3n Espa\u00f1ola de Ajedrez","url":"https:\/\/feda.org\/feda2k16\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/logo\/image\/","url":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/NuevoLogo_FEDA_2016.png","contentUrl":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/NuevoLogo_FEDA_2016.png","width":600,"height":600,"caption":"FEDA"},"image":{"@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/federacionespanoladeajedrez\/","https:\/\/x.com\/AjedrezEspanola","https:\/\/www.instagram.com\/federacionespanolaajedrez\/?hl=es","https:\/\/www.youtube.com\/@FederacionEspanoladeAjedrezFED\/featured"]},{"@type":"Person","@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/person\/b39486343e189c77e58d02641385fe29","name":"elefante66","url":"https:\/\/feda.org\/feda2k16\/author\/elefante66\/"}]}},"_links":{"self":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts\/22684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/comments?post=22684"}],"version-history":[{"count":2,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts\/22684\/revisions"}],"predecessor-version":[{"id":22689,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts\/22684\/revisions\/22689"}],"wp:attachment":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/media?parent=22684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/categories?post=22684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/tags?post=22684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}