{"id":22996,"date":"2023-11-01T11:50:59","date_gmt":"2023-11-01T11:50:59","guid":{"rendered":"https:\/\/feda.org\/feda2k16\/?p=22996"},"modified":"2023-11-01T11:52:13","modified_gmt":"2023-11-01T11:52:13","slug":"el-primer-campeonato-iberoamericano-rapido-se-celebrara-en-sant-boi-de-llobregat","status":"publish","type":"post","link":"https:\/\/feda.org\/feda2k16\/el-primer-campeonato-iberoamericano-rapido-se-celebrara-en-sant-boi-de-llobregat\/","title":{"rendered":"El Primer Campeonato Iberoamericano R\u00e1pido se celebrar\u00e1 en Sant Boi de Llobregat."},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1057\" height=\"370\" src=\"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/3-6.jpg\" alt=\"\" class=\"wp-image-22995\" srcset=\"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/3-6.jpg 1057w, https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/3-6-768x269.jpg 768w\" sizes=\"(max-width: 1057px) 100vw, 1057px\" \/><\/figure>\n\n\n\n\n\n<div>La Federaci\u00f3n\u00a0Iberoamericana\u00a0de ajedrez (FIBDA)\u00a0 ha aprobado la realizaci\u00f3n\u00a0del I Campeonato Iberoamericano\u00a0r\u00e1pido en la localidad de Sant Boi de Llobregat, muy pr\u00f3xima\u00a0a la ciudad de Barcelona.<\/div>\n<div>La FEDA ha cedido la organizaci\u00f3n a la Federaci\u00f3 Catalana d&#8217;Escacs quien lo har\u00e1 realidad el pr\u00f3ximo 9 de diciembre en los salones la Massanera en Sant Boi.<\/div>\n<div>\u00a0<\/div>\n<div>El evento repartir\u00e1 4.900\u20ac en premios y aprovechar\u00e1 uno de los d\u00edas libres entre los dos important\u00edsimos openes de LLobregat y Sunway (Sitges).<\/div>\n<div>\u00a0<\/div>\n<div>El Campeonato es abierto para todo\u00a0 jugador federado en cualquiera\u00a0de los 23 pa\u00edses\u00a0que\u00a0integran la FIBDA.<\/div>\n<div><a href=\"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/Bases_Iberoamericano_rapidas-1.pdf\">M\u00e1s\u00a0informaci\u00f3n\u00a0en el pdf adjunto.<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Federaci\u00f3n\u00a0Iberoamericana\u00a0de ajedrez (FIBDA)\u00a0 ha aprobado la realizaci\u00f3n\u00a0del I Campeonato Iberoamericano\u00a0r\u00e1pido en la localidad de Sant Boi de Llobregat, muy pr\u00f3xima\u00a0a la ciudad de Barcelona. La FEDA ha cedido la organizaci\u00f3n a la Federaci\u00f3 Catalana d&#8217;Escacs quien lo har\u00e1 realidad el pr\u00f3ximo 9 de diciembre en los salones la Massanera en Sant Boi. \u00a0 El [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-22996","post","type-post","status-publish","format-standard","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Primer Campeonato Iberoamericano R\u00e1pido se celebrar\u00e1 en Sant Boi de Llobregat. - FEDA<\/title>\n<meta name=\"description\" content=\"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/feda.org\/feda2k16\/el-primer-campeonato-iberoamericano-rapido-se-celebrara-en-sant-boi-de-llobregat\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Primer Campeonato Iberoamericano R\u00e1pido se celebrar\u00e1 en Sant Boi de Llobregat. - FEDA\" \/>\n<meta property=\"og:description\" content=\"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez\" \/>\n<meta property=\"og:url\" content=\"https:\/\/feda.org\/feda2k16\/el-primer-campeonato-iberoamericano-rapido-se-celebrara-en-sant-boi-de-llobregat\/\" \/>\n<meta property=\"og:site_name\" content=\"FEDA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/federacionespanoladeajedrez\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-01T11:50:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-01T11:52:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/3-6.jpg\" \/>\n<meta name=\"author\" content=\"elefante66\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AjedrezEspanola\" \/>\n<meta name=\"twitter:site\" content=\"@AjedrezEspanola\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"elefante66\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/el-primer-campeonato-iberoamericano-rapido-se-celebrara-en-sant-boi-de-llobregat\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/el-primer-campeonato-iberoamericano-rapido-se-celebrara-en-sant-boi-de-llobregat\\\/\"},\"author\":{\"name\":\"elefante66\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/person\\\/b39486343e189c77e58d02641385fe29\"},\"headline\":\"El Primer Campeonato Iberoamericano R\u00e1pido se celebrar\u00e1 en Sant Boi de Llobregat.\",\"datePublished\":\"2023-11-01T11:50:59+00:00\",\"dateModified\":\"2023-11-01T11:52:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/el-primer-campeonato-iberoamericano-rapido-se-celebrara-en-sant-boi-de-llobregat\\\/\"},\"wordCount\":127,\"publisher\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/el-primer-campeonato-iberoamericano-rapido-se-celebrara-en-sant-boi-de-llobregat\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/3-6.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/el-primer-campeonato-iberoamericano-rapido-se-celebrara-en-sant-boi-de-llobregat\\\/\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/el-primer-campeonato-iberoamericano-rapido-se-celebrara-en-sant-boi-de-llobregat\\\/\",\"name\":\"El Primer Campeonato Iberoamericano R\u00e1pido se celebrar\u00e1 en Sant Boi de Llobregat. - FEDA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/el-primer-campeonato-iberoamericano-rapido-se-celebrara-en-sant-boi-de-llobregat\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/el-primer-campeonato-iberoamericano-rapido-se-celebrara-en-sant-boi-de-llobregat\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/3-6.jpg\",\"datePublished\":\"2023-11-01T11:50:59+00:00\",\"dateModified\":\"2023-11-01T11:52:13+00:00\",\"description\":\"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/el-primer-campeonato-iberoamericano-rapido-se-celebrara-en-sant-boi-de-llobregat\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/feda.org\\\/feda2k16\\\/el-primer-campeonato-iberoamericano-rapido-se-celebrara-en-sant-boi-de-llobregat\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/el-primer-campeonato-iberoamericano-rapido-se-celebrara-en-sant-boi-de-llobregat\\\/#primaryimage\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/3-6.jpg\",\"contentUrl\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/3-6.jpg\",\"width\":1057,\"height\":370},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/el-primer-campeonato-iberoamericano-rapido-se-celebrara-en-sant-boi-de-llobregat\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Primer Campeonato Iberoamericano R\u00e1pido se celebrar\u00e1 en Sant Boi de Llobregat.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#website\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/\",\"name\":\"FEDA\",\"description\":\"Federaci\u00f3n Espa\u00f1ola de Ajedrez\",\"publisher\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#organization\"},\"alternateName\":\"Federaci\u00f3n Espa\u00f1ola de Ajedrez\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#organization\",\"name\":\"FEDA\",\"alternateName\":\"Federaci\u00f3n Espa\u00f1ola de Ajedrez\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/NuevoLogo_FEDA_2016.png\",\"contentUrl\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/NuevoLogo_FEDA_2016.png\",\"width\":600,\"height\":600,\"caption\":\"FEDA\"},\"image\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/federacionespanoladeajedrez\\\/\",\"https:\\\/\\\/x.com\\\/AjedrezEspanola\",\"https:\\\/\\\/www.instagram.com\\\/federacionespanolaajedrez\\\/?hl=es\",\"https:\\\/\\\/www.youtube.com\\\/@FederacionEspanoladeAjedrezFED\\\/featured\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/person\\\/b39486343e189c77e58d02641385fe29\",\"name\":\"elefante66\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/author\\\/elefante66\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Primer Campeonato Iberoamericano R\u00e1pido se celebrar\u00e1 en Sant Boi de Llobregat. - FEDA","description":"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/feda.org\/feda2k16\/el-primer-campeonato-iberoamericano-rapido-se-celebrara-en-sant-boi-de-llobregat\/","og_locale":"es_ES","og_type":"article","og_title":"El Primer Campeonato Iberoamericano R\u00e1pido se celebrar\u00e1 en Sant Boi de Llobregat. - FEDA","og_description":"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez","og_url":"https:\/\/feda.org\/feda2k16\/el-primer-campeonato-iberoamericano-rapido-se-celebrara-en-sant-boi-de-llobregat\/","og_site_name":"FEDA","article_publisher":"https:\/\/www.facebook.com\/federacionespanoladeajedrez\/","article_published_time":"2023-11-01T11:50:59+00:00","article_modified_time":"2023-11-01T11:52:13+00:00","og_image":[{"url":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/3-6.jpg","type":"","width":"","height":""}],"author":"elefante66","twitter_card":"summary_large_image","twitter_creator":"@AjedrezEspanola","twitter_site":"@AjedrezEspanola","twitter_misc":{"Escrito por":"elefante66","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/feda.org\/feda2k16\/el-primer-campeonato-iberoamericano-rapido-se-celebrara-en-sant-boi-de-llobregat\/#article","isPartOf":{"@id":"https:\/\/feda.org\/feda2k16\/el-primer-campeonato-iberoamericano-rapido-se-celebrara-en-sant-boi-de-llobregat\/"},"author":{"name":"elefante66","@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/person\/b39486343e189c77e58d02641385fe29"},"headline":"El Primer Campeonato Iberoamericano R\u00e1pido se celebrar\u00e1 en Sant Boi de Llobregat.","datePublished":"2023-11-01T11:50:59+00:00","dateModified":"2023-11-01T11:52:13+00:00","mainEntityOfPage":{"@id":"https:\/\/feda.org\/feda2k16\/el-primer-campeonato-iberoamericano-rapido-se-celebrara-en-sant-boi-de-llobregat\/"},"wordCount":127,"publisher":{"@id":"https:\/\/feda.org\/feda2k16\/#organization"},"image":{"@id":"https:\/\/feda.org\/feda2k16\/el-primer-campeonato-iberoamericano-rapido-se-celebrara-en-sant-boi-de-llobregat\/#primaryimage"},"thumbnailUrl":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/3-6.jpg","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/feda.org\/feda2k16\/el-primer-campeonato-iberoamericano-rapido-se-celebrara-en-sant-boi-de-llobregat\/","url":"https:\/\/feda.org\/feda2k16\/el-primer-campeonato-iberoamericano-rapido-se-celebrara-en-sant-boi-de-llobregat\/","name":"El Primer Campeonato Iberoamericano R\u00e1pido se celebrar\u00e1 en Sant Boi de Llobregat. - FEDA","isPartOf":{"@id":"https:\/\/feda.org\/feda2k16\/#website"},"primaryImageOfPage":{"@id":"https:\/\/feda.org\/feda2k16\/el-primer-campeonato-iberoamericano-rapido-se-celebrara-en-sant-boi-de-llobregat\/#primaryimage"},"image":{"@id":"https:\/\/feda.org\/feda2k16\/el-primer-campeonato-iberoamericano-rapido-se-celebrara-en-sant-boi-de-llobregat\/#primaryimage"},"thumbnailUrl":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/3-6.jpg","datePublished":"2023-11-01T11:50:59+00:00","dateModified":"2023-11-01T11:52:13+00:00","description":"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez","breadcrumb":{"@id":"https:\/\/feda.org\/feda2k16\/el-primer-campeonato-iberoamericano-rapido-se-celebrara-en-sant-boi-de-llobregat\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/feda.org\/feda2k16\/el-primer-campeonato-iberoamericano-rapido-se-celebrara-en-sant-boi-de-llobregat\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/feda.org\/feda2k16\/el-primer-campeonato-iberoamericano-rapido-se-celebrara-en-sant-boi-de-llobregat\/#primaryimage","url":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/3-6.jpg","contentUrl":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/3-6.jpg","width":1057,"height":370},{"@type":"BreadcrumbList","@id":"https:\/\/feda.org\/feda2k16\/el-primer-campeonato-iberoamericano-rapido-se-celebrara-en-sant-boi-de-llobregat\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/feda.org\/feda2k16\/"},{"@type":"ListItem","position":2,"name":"El Primer Campeonato Iberoamericano R\u00e1pido se celebrar\u00e1 en Sant Boi de Llobregat."}]},{"@type":"WebSite","@id":"https:\/\/feda.org\/feda2k16\/#website","url":"https:\/\/feda.org\/feda2k16\/","name":"FEDA","description":"Federaci\u00f3n Espa\u00f1ola de Ajedrez","publisher":{"@id":"https:\/\/feda.org\/feda2k16\/#organization"},"alternateName":"Federaci\u00f3n Espa\u00f1ola de Ajedrez","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/feda.org\/feda2k16\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/feda.org\/feda2k16\/#organization","name":"FEDA","alternateName":"Federaci\u00f3n Espa\u00f1ola de Ajedrez","url":"https:\/\/feda.org\/feda2k16\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/logo\/image\/","url":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/NuevoLogo_FEDA_2016.png","contentUrl":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/NuevoLogo_FEDA_2016.png","width":600,"height":600,"caption":"FEDA"},"image":{"@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/federacionespanoladeajedrez\/","https:\/\/x.com\/AjedrezEspanola","https:\/\/www.instagram.com\/federacionespanolaajedrez\/?hl=es","https:\/\/www.youtube.com\/@FederacionEspanoladeAjedrezFED\/featured"]},{"@type":"Person","@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/person\/b39486343e189c77e58d02641385fe29","name":"elefante66","url":"https:\/\/feda.org\/feda2k16\/author\/elefante66\/"}]}},"_links":{"self":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts\/22996","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/comments?post=22996"}],"version-history":[{"count":2,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts\/22996\/revisions"}],"predecessor-version":[{"id":22998,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts\/22996\/revisions\/22998"}],"wp:attachment":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/media?parent=22996"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/categories?post=22996"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/tags?post=22996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}