{"id":2324,"date":"2016-07-15T13:15:42","date_gmt":"2016-07-15T13:15:42","guid":{"rendered":"http:\/\/localhost:8888\/feda2k16\/?p=2324"},"modified":"2016-08-06T08:34:02","modified_gmt":"2016-08-06T08:34:02","slug":"circular-25-2016-convocatoria-ceclub-segunda-division","status":"publish","type":"post","link":"https:\/\/feda.org\/feda2k16\/circular-25-2016-convocatoria-ceclub-segunda-division\/","title":{"rendered":"Circular 25\/2016 &#8211; Convocatoria CECLUB Segunda Divisi\u00f3n"},"content":{"rendered":"<p align=\"center\"> \t<strong>A TODAS LAS FEDERACIONES AUTONOMICAS<\/strong><\/p>\n<p align=\"center\"> \t<strong>Ref.: Convocatoria del Campeonato de Espa\u00f1a por Equipos de Club 2016<\/strong><\/p>\n<p align=\"center\"> \t&nbsp;<strong>SEGUNDA DIVISI\u00d3N<\/strong><\/p>\n<p> \t<a href=\"http:\/\/feda.org\/feda2k16\/wp-content\/uploads\/files\/Circulares\/C25-Conv_CECLUB_2D_2016.pdf\">Descargar en PDF<\/a>.<\/p>\n<p> \t<a href=\"http:\/\/feda.org\/feda2k16\/wp-content\/uploads\/files\/Circulares\/C25-Anexo1_Formulario_Inscripcin_2div.xlsx\">Anexo: Formulario de Inscripci\u00f3n<\/a>.<\/p>\n<p> \t&nbsp;<\/p>\n<p> \t<strong>ORGANIZACI\u00d3N<\/strong><\/p>\n<p style=\"text-align: justify;\"> \tOrganiza la Federaci\u00f3n Espa\u00f1ola de Ajedrez, con la colaboraci\u00f3n del Ayuntamiento de Linares y la Federaci\u00f3n Andaluza de Ajedrez.<\/p>\n<p style=\"text-align: justify;\"> \tEl Director del Campeonato ser\u00e1 D. Francisco Fern\u00e1ndez Albalate<\/p>\n<p> \t&nbsp;<\/p>\n<p> \t<strong>PATROCINAN<\/strong><\/p>\n<p> \t<strong>Diputaci\u00f3n de Ja\u00e9n<\/strong>. <a href=\"http:\/\/www.dipujaen.es\/\">www.dipujaen.es<\/a><\/p>\n<p> \t<strong>Ayuntamiento de Linares<\/strong>. <a href=\"http:\/\/www.ciudaddelinares.es\/\">www.ciudaddelinares.es<\/a><\/p>\n<p> \t&nbsp;<\/p>\n<p> \t<strong>COLABORAN<\/strong><\/p>\n<p> \t<strong>Hotel RL An\u00edbal de Linares<\/strong><\/p>\n<p> \tHotel Victoria de Linares<\/p>\n<p> \tHotel Cervantes de Linares<\/p>\n<p> \tHotel Baviera de Linares<\/p>\n<p> \tHotel Santiago de Linares<\/p>\n<p> \tAsociaci\u00f3n de Comerciantes e Industriales de Linares &#8211; ACIL<\/p>\n<p> \t&nbsp;<\/p>\n<p> \t<strong>SISTEMA Y CALENDARIO DE JUEGO<\/strong><\/p>\n<p style=\"text-align: justify;\"> \tSe jugar\u00e1 por Sistema Suizo aplicado a equipos, a 6 rondas y seg\u00fan lo establecido en el Reglamento General de Competiciones de la FEDA, que se resume a continuaci\u00f3n:<\/p>\n<p style=\"text-align: justify;\"> \tCada Equipo estar\u00e1 formado por cuatro tableros.<\/p>\n<p style=\"text-align: justify;\"> \tLa puntuaci\u00f3n ser\u00e1 por encuentros (2 puntos ganado, 1 punto empatado, 0 perdido).<\/p>\n<p style=\"text-align: justify;\"> \tLa velocidad de juego ser\u00e1 de 90 minutos para toda la partida, con incremento de 30 segundos por jugada.<\/p>\n<p style=\"text-align: justify;\"> \tDesempates: Se aplicar\u00e1 la Circular 12\/2016<\/p>\n<p> \t<strong>Calendario<\/strong><\/p>\n<table align=\"center\" border=\"1\" cellpadding=\"0\" cellspacing=\"0\" class=\"mtr-table mtr-tr-td\">\n<tbody>\n<tr>\n<td style=\"width:90px;\" data-mtr-content=\"\n \t\t\t\t\t16-08-2016\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p> \t\t\t\t\t16-08-2016<\/p>\n<\/div><\/td>\n<td style=\"width:59px;\" data-mtr-content=\"\n \t\t\t\t\t\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p> \t\t\t\t\t\u00a0<\/p>\n<\/div><\/td>\n<td style=\"width:312px;\" data-mtr-content=\"\n \t\t\t\t\tAcreditaciones hasta las 13:00 h. Hotel An\u00edbal\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p> \t\t\t\t\tAcreditaciones hasta las 13:00 h. Hotel An\u00edbal<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width:90px;\" data-mtr-content=\"\n \t\t\t\t\t16-08-2016\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p> \t\t\t\t\t16-08-2016<\/p>\n<\/div><\/td>\n<td style=\"width:59px;\" data-mtr-content=\"\n \t\t\t\t\t\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p> \t\t\t\t\t13:30<\/p>\n<\/div><\/td>\n<td style=\"width:312px;\" data-mtr-content=\"\n \t\t\t\t\tAcreditaciones hasta las 13:00 h. Hotel An\u00edbal\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p> \t\t\t\t\tReuni\u00f3n de Delegados. Hotel An\u00edbal<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width:90px;\" data-mtr-content=\"\n \t\t\t\t\t16-08-2016\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p> \t\t\t\t\t16-08-2016<\/p>\n<\/div><\/td>\n<td style=\"width:59px;\" data-mtr-content=\"\n \t\t\t\t\t\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p> \t\t\t\t\t17:00<\/p>\n<\/div><\/td>\n<td style=\"width:312px;\" data-mtr-content=\"\n \t\t\t\t\tAcreditaciones hasta las 13:00 h. Hotel An\u00edbal\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p> \t\t\t\t\tPrimera Ronda<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width:90px;\" data-mtr-content=\"\n \t\t\t\t\t16-08-2016\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p> \t\t\t\t\t17-08-2016<\/p>\n<\/div><\/td>\n<td style=\"width:59px;\" data-mtr-content=\"\n \t\t\t\t\t\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p> \t\t\t\t\t10:00<\/p>\n<\/div><\/td>\n<td style=\"width:312px;\" data-mtr-content=\"\n \t\t\t\t\tAcreditaciones hasta las 13:00 h. Hotel An\u00edbal\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p> \t\t\t\t\tSegunda Ronda<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width:90px;\" data-mtr-content=\"\n \t\t\t\t\t16-08-2016\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p> \t\t\t\t\t17-08-2016<\/p>\n<\/div><\/td>\n<td style=\"width:59px;\" data-mtr-content=\"\n \t\t\t\t\t\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p> \t\t\t\t\t17:00<\/p>\n<\/div><\/td>\n<td style=\"width:312px;\" data-mtr-content=\"\n \t\t\t\t\tAcreditaciones hasta las 13:00 h. Hotel An\u00edbal\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p> \t\t\t\t\tTercera Ronda<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width:90px;\" data-mtr-content=\"\n \t\t\t\t\t16-08-2016\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p> \t\t\t\t\t18-08-2016<\/p>\n<\/div><\/td>\n<td style=\"width:59px;\" data-mtr-content=\"\n \t\t\t\t\t\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p> \t\t\t\t\t17:00<\/p>\n<\/div><\/td>\n<td style=\"width:312px;\" data-mtr-content=\"\n \t\t\t\t\tAcreditaciones hasta las 13:00 h. Hotel An\u00edbal\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p> \t\t\t\t\tCuarta Ronda<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width:90px;\" data-mtr-content=\"\n \t\t\t\t\t16-08-2016\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p> \t\t\t\t\t19-08-2016<\/p>\n<\/div><\/td>\n<td style=\"width:59px;\" data-mtr-content=\"\n \t\t\t\t\t\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p> \t\t\t\t\t17:00<\/p>\n<\/div><\/td>\n<td style=\"width:312px;\" data-mtr-content=\"\n \t\t\t\t\tAcreditaciones hasta las 13:00 h. Hotel An\u00edbal\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p> \t\t\t\t\tQuinta Ronda<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width:90px;\" data-mtr-content=\"\n \t\t\t\t\t16-08-2016\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p> \t\t\t\t\t20-08-2016<\/p>\n<\/div><\/td>\n<td style=\"width:59px;\" data-mtr-content=\"\n \t\t\t\t\t\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p> \t\t\t\t\t10:00<\/p>\n<\/div><\/td>\n<td style=\"width:312px;\" data-mtr-content=\"\n \t\t\t\t\tAcreditaciones hasta las 13:00 h. Hotel An\u00edbal\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p> \t\t\t\t\tSexta Ronda<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width:90px;\" data-mtr-content=\"\n \t\t\t\t\t16-08-2016\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p> \t\t\t\t\t20-08-2016<\/p>\n<\/div><\/td>\n<td style=\"width:59px;\" data-mtr-content=\"\n \t\t\t\t\t\u00a0\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p> \t\t\t\t\t14:00<\/p>\n<\/div><\/td>\n<td style=\"width:312px;\" data-mtr-content=\"\n \t\t\t\t\tAcreditaciones hasta las 13:00 h. Hotel An\u00edbal\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p> \t\t\t\t\tClausura y Entrega de Premios<\/p>\n<\/div><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div style=\"clear:both;\"> \t&nbsp;<\/div>\n<p style=\"text-align: justify;\"> \tSi fuera necesario jugar a 7 rondas, se habilitar\u00e1 el d\u00eda 18-08-2016 a las 10:00 h de la ma\u00f1ana.<\/p>\n<p style=\"text-align: justify;\"> \tLa modificaci\u00f3n del calendario, en su caso, se comunicar\u00e1 en la reuni\u00f3n de Delegados.<\/p>\n<p style=\"text-align: justify;\"> \tLos \u00e1rbitros y T\u00e9cnicos FEDA estar\u00e1n alojados en el hotel Oficial.<\/p>\n<p style=\"text-align: justify;\"> \tLa entrega de alineaciones y cualquier documentaci\u00f3n relacionada con el Campeonato ser\u00e1 obligatorio realizarla en el Hotel Oficial, con el horario que se establezca en la reuni\u00f3n de Delegados.<\/p>\n<p style=\"text-align: justify;\"> \tEl Campeonato se jugar\u00e1 en el <strong>Auditorio El P\u00f3sito Linares, <\/strong>c\/. Iglesia, 8 LINARES (Ja\u00e9n)<\/p>\n<p style=\"text-align: justify;\"> \t&nbsp;<\/p>\n<p style=\"text-align: justify;\"> \t<strong>2.&nbsp;&nbsp;&nbsp;&nbsp; <\/strong><strong>PARTICIPACI\u00d3N<\/strong><\/p>\n<p style=\"margin-left:36.0pt;\"> \t2.1.<u>Equipos Clasificados:<\/u><\/p>\n<table align=\"center\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" style=\"width:299px;\" width=\"374\" class=\"mtr-table mtr-tr-td\">\n<tbody>\n<tr>\n<td style=\"width:57px;\" data-mtr-content=\"\n \t\t\t\t\tORDEN\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p> \t\t\t\t\t<strong>ORDEN<\/strong><\/p>\n<\/div><\/td>\n<td style=\"width:202px;\" data-mtr-content=\"\n \t\t\t\t\tEQUIPO\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\"> \t\t\t\t\t<strong>EQUIPO<\/strong><\/p>\n<\/div><\/td>\n<td style=\"width:40px;\" data-mtr-content=\"\n \t\t\t\t\tFA\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\"> \t\t\t\t\t<strong>FA<\/strong><\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width:57px;\" data-mtr-content=\"\n \t\t\t\t\tORDEN\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\"> \t\t\t\t\t1<\/p>\n<\/div><\/td>\n<td style=\"width:202px;\" data-mtr-content=\"\n \t\t\t\t\tEQUIPO\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p> \t\t\t\t\tC.A. ALEKHINE-ESPARTINAS<\/p>\n<\/div><\/td>\n<td style=\"width:40px;\" data-mtr-content=\"\n \t\t\t\t\tFA\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\"> \t\t\t\t\tAND<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width:57px;\" data-mtr-content=\"\n \t\t\t\t\tORDEN\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\"> \t\t\t\t\t2<\/p>\n<\/div><\/td>\n<td style=\"width:202px;\" data-mtr-content=\"\n \t\t\t\t\tEQUIPO\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p> \t\t\t\t\tC.A. EVA \u2013 MANISES<\/p>\n<\/div><\/td>\n<td style=\"width:40px;\" data-mtr-content=\"\n \t\t\t\t\tFA\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\"> \t\t\t\t\tVAL<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width:57px;\" data-mtr-content=\"\n \t\t\t\t\tORDEN\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\"> \t\t\t\t\t3<\/p>\n<\/div><\/td>\n<td style=\"width:202px;\" data-mtr-content=\"\n \t\t\t\t\tEQUIPO\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p> \t\t\t\t\tC.A. 64 VILLALBA<\/p>\n<\/div><\/td>\n<td style=\"width:40px;\" data-mtr-content=\"\n \t\t\t\t\tFA\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\"> \t\t\t\t\tMAD<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width:57px;\" data-mtr-content=\"\n \t\t\t\t\tORDEN\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\"> \t\t\t\t\t4<\/p>\n<\/div><\/td>\n<td style=\"width:202px;\" data-mtr-content=\"\n \t\t\t\t\tEQUIPO\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p> \t\t\t\t\tC.A. EL PRAT LLIRIA BENIMACLET<\/p>\n<\/div><\/td>\n<td style=\"width:40px;\" data-mtr-content=\"\n \t\t\t\t\tFA\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\"> \t\t\t\t\tVAL<\/p>\n<\/div><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"margin-left: 36pt; text-align: justify;\"> \t2.2.<u>Equipos Representantes de las Federaciones Auton\u00f3micas:<\/u><\/p>\n<p style=\"text-align: justify;\"> \tUn equipo representante de cada Federaci\u00f3n Auton\u00f3mica, m\u00e1s los equipos adicionales que se establezcan en los convenios suscritos entre la FEDA y cada Federaci\u00f3n.<\/p>\n<p style=\"margin-left:36.0pt;\"> \t2.3.El Campeonato estar\u00e1 abierto adem\u00e1s a todos los equipos federados.<\/p>\n<p> \tLas condiciones de participaci\u00f3n son las siguientes:<\/p>\n<p style=\"margin-left: 36pt; text-align: justify;\"> \t&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Que cada uno de los primeros cuatro tableros del orden de fuerzas haya disputado al menos dos partidas en el Campeonato Auton\u00f3mico por Equipos o bienhaya estado federado en el mismo Club que propone su inscripci\u00f3n durante las tres \u00faltimas temporadas(excepto en los equipos nombrados como clasificados).<\/p>\n<p style=\"margin-left: 36pt; text-align: justify;\"> \t&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <strong>Licencias de los Jugadores<\/strong><\/p>\n<p style=\"margin-left: 35.45pt; text-align: justify;\"> \tLos integrantes de los equipos deber\u00e1n estar en posesi\u00f3n de licencia FEDA en vigor, tramitada a trav\u00e9s de su Federaci\u00f3n Auton\u00f3mica hasta el d\u00eda 31 de marzo de 2016.<\/p>\n<p style=\"margin-left: 36pt; text-align: justify;\"> \t<strong>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/strong><strong>Alineaci\u00f3n de jugadores:<\/strong><\/p>\n<p style=\"text-align: justify;\"> \tSer\u00e1 obligatoria la alineaci\u00f3n en cada encuentro de dos jugadores seleccionables por la FEDA.<\/p>\n<p style=\"text-align: justify;\"> \t&nbsp;<\/p>\n<p style=\"text-align: justify;\"> \t<strong>3.&nbsp;&nbsp;&nbsp;&nbsp; <\/strong><strong>CLASIFICACION FINAL. ASCENSOS<\/strong><\/p>\n<p> \tPrimer y Segundo clasificados: Ascienden a Primera Divisi\u00f3n 2017.<\/p>\n<p> \tTercer y Cuarto clasificados: Mantienen la categor\u00eda de Segunda Divisi\u00f3n 2017.<\/p>\n<p> \t&nbsp;<\/p>\n<p> \t<strong>4.&nbsp;&nbsp;&nbsp;&nbsp; <\/strong><strong>INSCRIPCIONES Y PLAZOS<\/strong><\/p>\n<p style=\"text-align: justify;\"> \tHasta el d\u00eda <strong><u>3 de agosto de 2016<\/u><\/strong>.<\/p>\n<p style=\"text-align: justify;\"> \tAntes de este plazo, deber\u00e1 presentarse, a trav\u00e9s de su Federaci\u00f3n Auton\u00f3mica, por email a <a href=\"mailto:administracion@feda.org\"><strong>administracion@feda.org<\/strong><\/a>la siguiente documentaci\u00f3n cumplimentando el <strong>Anexo 1<\/strong>:<\/p>\n<p style=\"text-align: justify;\"> \t&#8211; Nombre, direcci\u00f3n, n\u00famero de tel\u00e9fono y n\u00famero de fax del Club, Delegado y\/o Capit\u00e1n responsable del equipo y Federaci\u00f3n Auton\u00f3mica a la que pertenece.<\/p>\n<p style=\"text-align: justify;\"> \t&#8211; Orden de Fuerza compuesto por un m\u00e1ximo de diez participantes por orden de ELO, indicando nombre, nacionalidad, fecha de nacimiento, t\u00edtulos, ELO FIDE y ELO FEDA. En la citada relaci\u00f3n no podr\u00e1n figurar personas que hayan jugado una partida con otro club espa\u00f1ol en la misma temporada.<\/p>\n<p style=\"text-align: justify;\"> \tLa cuota de inscripci\u00f3n es de <strong>150<\/strong> euros, para los equipos clasificados y representantes de Federaciones Auton\u00f3micas, y de <strong>300<\/strong> euros para los equipos inscritos por Open, que deber\u00e1n ingresarse en la cuenta de la FEDA antes del d\u00eda 3 de agosto de 2016, IBAN: <strong>ES50<\/strong> <strong>2085 8024 9503 0002 5965.<\/strong><\/p>\n<p style=\"text-align: justify;\"> \t&nbsp;<\/p>\n<p style=\"text-align: justify;\"> \t<strong>5.&nbsp;&nbsp;&nbsp;&nbsp; <\/strong><strong>INSCRIPCIONES FUERA DE PLAZO<\/strong><\/p>\n<p style=\"text-align: justify;\"> \tLa FEDA, de acuerdo con el organizador, podr\u00e1 admitir inscripciones fuera del plazo ordinario y, en todo caso, hasta el d\u00eda 12 de agosto de 2016. En este caso, la inscripci\u00f3n ser\u00e1 de 225 euros para los equipos clasificados y representantes, y de 450 euros para los Open.<\/p>\n<p> \t&nbsp;<\/p>\n<p> \t<strong>6.&nbsp;&nbsp;&nbsp;&nbsp; <\/strong><strong>ORDEN DE FUERZA DEFINITIVO<\/strong><\/p>\n<p style=\"text-align: justify;\"> \tSe podr\u00e1 presentar un Orden de Fuerza definitivo, que podr\u00e1 contener un m\u00e1ximo de dos cambios con respecto al presentado al formalizar la inscripci\u00f3n.<\/p>\n<p style=\"text-align: justify;\"> \tA los efectos de ordenaci\u00f3n por Elo de los tableros, se variar\u00e1 el orden presentado de acuerdo con las listas de Elo FIDE y FEDA de 1 de agosto de 2016, respetando en todo caso la regla de los 50 puntos establecida en el Reglamento General de Competiciones.<\/p>\n<p style=\"text-align: justify;\"> \tPara que sea v\u00e1lido, deber\u00e1 tener entrada en la FEDA hasta el <u>13 de agosto de 2016 a las 13.00 h.<\/u><\/p>\n<p style=\"text-align: justify;\"> \t&nbsp;<\/p>\n<p style=\"text-align: justify;\"> \t<strong>7.&nbsp;&nbsp;&nbsp;&nbsp; <\/strong><strong>AYUDAS A EQUIPOS PARTICIPANTES<\/strong><\/p>\n<p style=\"text-align: justify;\"> \tUn m\u00e1ximo de 470,00 \u20ac por equipo clasificado y para representantes de la Federaciones Auton\u00f3micas seg\u00fan se haya acordado en los convenios, a justificar con gastos de desplazamiento, estancias y manutenci\u00f3n en el hotel oficial.<\/p>\n<p style=\"text-align: justify;\"> \tEl plazo de env\u00edo a la FEDA de los justificantes para tener derecho a las ayudas mencionadas ser\u00e1 hasta el d\u00eda 20 de septiembre de 2016.<\/p>\n<p style=\"text-align: justify;\"> \tLos equipos deber\u00e1n efectuar las reservas de alojamiento directamente a los hoteles.<\/p>\n<p> \t&nbsp;<\/p>\n<p> \t<strong>8.&nbsp;&nbsp;&nbsp;&nbsp; <\/strong><strong>ACUERDO CON ACIL. Asociaci\u00f3n de Comerciantes e Industriales de Linares<\/strong><\/p>\n<p style=\"text-align: justify;\"> \tLa Organizaci\u00f3n ha acordado con ACIL la emisi\u00f3n de vales para comidas y otras compras, que ser\u00e1n aceptados en m\u00e1s de 60 establecimientos de Linares, en especial restaurantes y bares.<\/p>\n<p style=\"text-align: justify;\"> \tEstos vales se podr\u00e1n adquirir directamente a la Organizaci\u00f3n, que proporcionar\u00e1 adem\u00e1s un listado y un mapa de los establecimientos colaboradores.<\/p>\n<p style=\"text-align: justify;\"> \tPara las personas que acudan a los campeonatos con estancia y manutenci\u00f3n con cargo a la FEDA, se les contratar\u00e1 el Hotel Oficial con media pensi\u00f3n y se les facilitar\u00e1n vales por importe equivalente a una comida por d\u00eda, que podr\u00e1n canjear en cualquiera de los restaurantes y bares colaboradores.<\/p>\n<p style=\"text-align: justify;\"> \t&nbsp;<\/p>\n<p style=\"text-align: justify;\"> \t<strong>9.&nbsp;&nbsp;&nbsp;&nbsp; <\/strong><strong>HOTEL OFICIAL:<\/strong><\/p>\n<p> \tEl Hotel oficial del Campeonato ser\u00e1 el <strong>Hotel RL An\u00edbal de Linares****<\/strong>.&nbsp; <a href=\"http:\/\/www.hotelanibal.com\/\">www.hotelanibal.com<\/a><\/p>\n<p> \tc\/. Cid Campeador, 11<\/p>\n<p> \t23700 LINARES<\/p>\n<p> \tTel&nbsp; 953 65 04 00&nbsp; Fax 953 65 22 04&nbsp; <a href=\"mailto:reservas@hotelanibal.com\">reservas@hotelanibal.com<\/a><\/p>\n<p> \t<strong>PRECIOS: <\/strong>Precios por persona y d\u00eda, IVA incluido: &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n<table align=\"center\" border=\"1\" cellpadding=\"0\" cellspacing=\"0\" style=\"width:560px;\" width=\"700\" class=\"mtr-table mtr-tr-td\">\n<tbody>\n<tr>\n<td style=\"width:242px;\" data-mtr-content=\"\n \t\t\t\t\tTipo de alojamiento\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t<strong>Tipo de alojamiento<\/strong><\/p>\n<\/div><\/td>\n<td style=\"width:104px;\" data-mtr-content=\"\n \t\t\t\t\tAloj. y Desay.\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t<strong>Aloj. y Desay.<\/strong><\/p>\n<\/div><\/td>\n<td style=\"width:97px;\" data-mtr-content=\"\n \t\t\t\t\tMedia Pens.\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t<strong>Media Pens.<\/strong><\/p>\n<\/div><\/td>\n<td style=\"width:117px;\" data-mtr-content=\"\n \t\t\t\t\tPens. Completa\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t<strong>Pens. Completa<\/strong><\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width:242px;\" data-mtr-content=\"\n \t\t\t\t\tTipo de alojamiento\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p style=\"margin-left:18.6pt;\"> \t\t\t\t\t<strong>\u00a0 Habitaci\u00f3n Doble de uso\u00a0 individual<\/strong><\/p>\n<\/div><\/td>\n<td style=\"width:104px;\" data-mtr-content=\"\n \t\t\t\t\tAloj. y Desay.\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t38,50 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width:97px;\" data-mtr-content=\"\n \t\t\t\t\tMedia Pens.\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t44,00 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width:117px;\" data-mtr-content=\"\n \t\t\t\t\tPens. Completa\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t51,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width:242px;\" data-mtr-content=\"\n \t\t\t\t\tTipo de alojamiento\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p style=\"margin-left:18.6pt;\"> \t\t\t\t\t<strong>\u00a0 Habitaci\u00f3n Doble<\/strong><\/p>\n<\/div><\/td>\n<td style=\"width:104px;\" data-mtr-content=\"\n \t\t\t\t\tAloj. y Desay.\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t27,50 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width:97px;\" data-mtr-content=\"\n \t\t\t\t\tMedia Pens.\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t33,00 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width:117px;\" data-mtr-content=\"\n \t\t\t\t\tPens. Completa\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t42,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width:242px;\" data-mtr-content=\"\n \t\t\t\t\tTipo de alojamiento\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p style=\"margin-left:18.6pt;\"> \t\t\t\t\t<strong>\u00a0 Habitaci\u00f3n Triple<\/strong><\/p>\n<\/div><\/td>\n<td style=\"width:104px;\" data-mtr-content=\"\n \t\t\t\t\tAloj. y Desay.\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t26,50 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width:97px;\" data-mtr-content=\"\n \t\t\t\t\tMedia Pens.\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t32,00 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width:117px;\" data-mtr-content=\"\n \t\t\t\t\tPens. Completa\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t37,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"margin-left:36.0pt;\"> \t&nbsp;<\/p>\n<p style=\"margin-left:36.0pt;\"> \t<strong>10.&nbsp; <\/strong><strong>HOTELES ALTERNATIVOS:<\/strong><\/p>\n<p> \t&nbsp;<\/p>\n<p> \t<strong>Hotel Victoria de Linares***<\/strong>.&nbsp; <a href=\"http:\/\/www.hotelvictoria.org\/\">www.hotelvictoria.org<\/a><\/p>\n<p> \tc\/. Cervantes, 7 y 9<\/p>\n<p> \t23700 LINARES<\/p>\n<p> \tTel 953 69 25 00&nbsp; &nbsp;<a href=\"mailto:hotelvictoria@gmx.es\">hotelvictoria@gmx.es<\/a><\/p>\n<p> \t<strong>PRECIOS: <\/strong>Precios por persona y d\u00eda, IVA incluido: &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n<table align=\"center\" border=\"1\" cellpadding=\"0\" cellspacing=\"0\" style=\"width:560px;\" width=\"700\" class=\"mtr-table mtr-tr-td\">\n<tbody>\n<tr>\n<td style=\"width:242px;\" data-mtr-content=\"\n \t\t\t\t\tTipo de alojamiento\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t<strong>Tipo de alojamiento<\/strong><\/p>\n<\/div><\/td>\n<td style=\"width:104px;\" data-mtr-content=\"\n \t\t\t\t\tAloj. y Desay.\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t<strong>Aloj. y Desay.<\/strong><\/p>\n<\/div><\/td>\n<td style=\"width:97px;\" data-mtr-content=\"\n \t\t\t\t\tMedia Pens.\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t<strong>Media Pens.<\/strong><\/p>\n<\/div><\/td>\n<td style=\"width:117px;\" data-mtr-content=\"\n \t\t\t\t\tPens. Completa\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t<strong>Pens. Completa<\/strong><\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width:242px;\" data-mtr-content=\"\n \t\t\t\t\tTipo de alojamiento\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p style=\"margin-left:18.6pt;\"> \t\t\t\t\t<strong>\u00a0 Habitaci\u00f3n Doble de uso\u00a0 individual<\/strong><\/p>\n<\/div><\/td>\n<td style=\"width:104px;\" data-mtr-content=\"\n \t\t\t\t\tAloj. y Desay.\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t30,00 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width:97px;\" data-mtr-content=\"\n \t\t\t\t\tMedia Pens.\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t39,00 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width:117px;\" data-mtr-content=\"\n \t\t\t\t\tPens. Completa\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t49,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width:242px;\" data-mtr-content=\"\n \t\t\t\t\tTipo de alojamiento\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p style=\"margin-left:18.6pt;\"> \t\t\t\t\t<strong>\u00a0 Habitaci\u00f3n Doble<\/strong><\/p>\n<\/div><\/td>\n<td style=\"width:104px;\" data-mtr-content=\"\n \t\t\t\t\tAloj. y Desay.\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t22,00 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width:97px;\" data-mtr-content=\"\n \t\t\t\t\tMedia Pens.\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t31,50 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width:117px;\" data-mtr-content=\"\n \t\t\t\t\tPens. Completa\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t40,50 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width:242px;\" data-mtr-content=\"\n \t\t\t\t\tTipo de alojamiento\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p style=\"margin-left:18.6pt;\"> \t\t\t\t\t<strong>\u00a0 Habitaci\u00f3n Triple<\/strong><\/p>\n<\/div><\/td>\n<td style=\"width:104px;\" data-mtr-content=\"\n \t\t\t\t\tAloj. y Desay.\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t20,80 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width:97px;\" data-mtr-content=\"\n \t\t\t\t\tMedia Pens.\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t29,80 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width:117px;\" data-mtr-content=\"\n \t\t\t\t\tPens. Completa\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t38,80 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div style=\"clear:both;\"> \t&nbsp;<\/div>\n<p> \t<strong>Hotel Cervantes de Linares***<\/strong>.&nbsp; <a href=\"http:\/\/www.hotelcervantes.info\/\">http:\/\/www.hotelcervantes.info<\/a><\/p>\n<p> \tc\/. Cervantes, 23 23700 LINARES<\/p>\n<p> \tTel&nbsp; 953 690 500<\/p>\n<p> \t<strong>PRECIOS: <\/strong>Precios por persona y d\u00eda, IVA incluido: &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n<table align=\"center\" border=\"1\" cellpadding=\"0\" cellspacing=\"0\" style=\"width:560px;\" width=\"700\" class=\"mtr-table mtr-tr-td\">\n<tbody>\n<tr>\n<td style=\"width:242px;\" data-mtr-content=\"\n \t\t\t\t\tTipo de alojamiento\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t<strong>Tipo de alojamiento<\/strong><\/p>\n<\/div><\/td>\n<td style=\"width:104px;\" data-mtr-content=\"\n \t\t\t\t\tAloj. y Desay.\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t<strong>Aloj. y Desay.<\/strong><\/p>\n<\/div><\/td>\n<td style=\"width:97px;\" data-mtr-content=\"\n \t\t\t\t\tMedia Pens.\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t<strong>Media Pens.<\/strong><\/p>\n<\/div><\/td>\n<td style=\"width:117px;\" data-mtr-content=\"\n \t\t\t\t\tPens. Completa\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t<strong>Pens. Completa<\/strong><\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width:242px;\" data-mtr-content=\"\n \t\t\t\t\tTipo de alojamiento\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p style=\"margin-left:18.6pt;\"> \t\t\t\t\t<strong>\u00a0 Habitaci\u00f3n individual<\/strong><\/p>\n<\/div><\/td>\n<td style=\"width:104px;\" data-mtr-content=\"\n \t\t\t\t\tAloj. y Desay.\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t30,00 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width:97px;\" data-mtr-content=\"\n \t\t\t\t\tMedia Pens.\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t38,00 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width:117px;\" data-mtr-content=\"\n \t\t\t\t\tPens. Completa\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t44,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width:242px;\" data-mtr-content=\"\n \t\t\t\t\tTipo de alojamiento\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p style=\"margin-left:18.6pt;\"> \t\t\t\t\t<strong>\u00a0 Habitaci\u00f3n Doble<\/strong><\/p>\n<\/div><\/td>\n<td style=\"width:104px;\" data-mtr-content=\"\n \t\t\t\t\tAloj. y Desay.\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t22,00 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width:97px;\" data-mtr-content=\"\n \t\t\t\t\tMedia Pens.\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t30,00 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width:117px;\" data-mtr-content=\"\n \t\t\t\t\tPens. Completa\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t36,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width:242px;\" data-mtr-content=\"\n \t\t\t\t\tTipo de alojamiento\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p style=\"margin-left:18.6pt;\"> \t\t\t\t\t<strong>\u00a0 Habitaci\u00f3n Triple*<\/strong><\/p>\n<\/div><\/td>\n<td style=\"width:104px;\" data-mtr-content=\"\n \t\t\t\t\tAloj. y Desay.\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t18,00 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width:97px;\" data-mtr-content=\"\n \t\t\t\t\tMedia Pens.\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t26,00 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width:117px;\" data-mtr-content=\"\n \t\t\t\t\tPens. Completa\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t32,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p align=\"center\"> \t(*Consultar disponibilidad)<\/p>\n<p> \t&nbsp;<\/p>\n<p> \t<strong>Hotel Baviera de Linares*<\/strong>. <a href=\"http:\/\/www.hotelbavieraandalucia.es\/\">http:\/\/www.hotelbavieraandalucia.es<\/a><\/p>\n<p> \tc\/. La Virgen, 25 23700 LINARES<\/p>\n<p> \tTel&nbsp; 953 652 413 <a href=\"mailto:hotelbavieralinares@gmail.com\">hotelbavieralinares@gmail.com<\/a><\/p>\n<p> \t<strong>PRECIOS: <\/strong>Consultar precios y disponibilidad al Hotel<\/p>\n<p> \t&nbsp;<\/p>\n<p> \t<strong>Hotel Santiago de Linares****<\/strong>. <a href=\"http:\/\/www.hotel-santiago.es\/\">www.hotel-santiago.es<\/a><\/p>\n<p> \tc\/. Santiago, 3 23700 LINARES<\/p>\n<p> \tTel&nbsp; 953 69 30 40 <a href=\"mailto:hotel@hotel-santiago.es\">hotel@hotel-santiago.es<\/a><\/p>\n<p> \t<strong>PRECIOS: <\/strong>Precios por persona y d\u00eda, IVA incluido: &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n<table align=\"center\" border=\"1\" cellpadding=\"0\" cellspacing=\"0\" style=\"width:560px;\" width=\"700\" class=\"mtr-table mtr-tr-td\">\n<tbody>\n<tr>\n<td style=\"width:242px;\" data-mtr-content=\"\n \t\t\t\t\tTipo de alojamiento\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t<strong>Tipo de alojamiento<\/strong><\/p>\n<\/div><\/td>\n<td style=\"width:104px;\" data-mtr-content=\"\n \t\t\t\t\tAloj. y Desay.\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t<strong>Aloj. y Desay.<\/strong><\/p>\n<\/div><\/td>\n<td style=\"width:97px;\" data-mtr-content=\"\n \t\t\t\t\tMedia Pens.\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t<strong>Media Pens.<\/strong><\/p>\n<\/div><\/td>\n<td style=\"width:117px;\" data-mtr-content=\"\n \t\t\t\t\tPens. Completa\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t<strong>Pens. Completa<\/strong><\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width:242px;\" data-mtr-content=\"\n \t\t\t\t\tTipo de alojamiento\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p style=\"margin-left:18.6pt;\"> \t\t\t\t\t<strong>\u00a0 Habitaci\u00f3n doble de uso individual<\/strong><\/p>\n<\/div><\/td>\n<td style=\"width:104px;\" data-mtr-content=\"\n \t\t\t\t\tAloj. y Desay.\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t42,00 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width:97px;\" data-mtr-content=\"\n \t\t\t\t\tMedia Pens.\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t47,00 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width:117px;\" data-mtr-content=\"\n \t\t\t\t\tPens. Completa\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t52,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width:242px;\" data-mtr-content=\"\n \t\t\t\t\tTipo de alojamiento\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p style=\"margin-left:18.6pt;\"> \t\t\t\t\t<strong>\u00a0 Habitaci\u00f3n Doble<\/strong><\/p>\n<\/div><\/td>\n<td style=\"width:104px;\" data-mtr-content=\"\n \t\t\t\t\tAloj. y Desay.\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t32,00 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width:97px;\" data-mtr-content=\"\n \t\t\t\t\tMedia Pens.\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t40,00 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width:117px;\" data-mtr-content=\"\n \t\t\t\t\tPens. Completa\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t46,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<tr>\n<td style=\"width:242px;\" data-mtr-content=\"\n \t\t\t\t\tTipo de alojamiento\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p style=\"margin-left:18.6pt;\"> \t\t\t\t\t<strong>\u00a0 Habitaci\u00f3n Triple*<\/strong><\/p>\n<\/div><\/td>\n<td style=\"width:104px;\" data-mtr-content=\"\n \t\t\t\t\tAloj. y Desay.\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t29,00 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width:97px;\" data-mtr-content=\"\n \t\t\t\t\tMedia Pens.\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t37,00 \u20ac<\/p>\n<\/div><\/td>\n<td style=\"width:117px;\" data-mtr-content=\"\n \t\t\t\t\tPens. Completa\n\" class=\"mtr-td-tag\"><div class=\"mtr-cell-content\">\n<p align=\"center\" style=\"margin-left:18.6pt;\"> \t\t\t\t\t40,00 \u20ac<\/p>\n<\/div><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p align=\"center\"> \t(*Consultar disponibilidad)<\/p>\n<p> \t&nbsp;<\/p>\n<p> \tEn Madrid, a 14 de julio de 2016.<\/p>\n<p> \t&nbsp;<\/p>\n<p> \t&nbsp;<\/p>\n<p> \tRam\u00f3n Padull\u00e9s Argerich<br \/> \tSecretario General<\/p>\n<p> \t&nbsp;<\/p>\n<p> \t&nbsp;<\/p>\n<p> \t&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A TODAS LAS FEDERACIONES AUTONOMICAS Ref.: Convocatoria del Campeonato de Espa\u00f1a por Equipos de Club 2016 &nbsp;SEGUNDA DIVISI\u00d3N Descargar en PDF. Anexo: Formulario de Inscripci\u00f3n. &nbsp; ORGANIZACI\u00d3N Organiza la Federaci\u00f3n Espa\u00f1ola de Ajedrez, con la colaboraci\u00f3n del Ayuntamiento de Linares y la Federaci\u00f3n Andaluza de Ajedrez. El Director del Campeonato ser\u00e1 D. Francisco Fern\u00e1ndez Albalate [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49],"tags":[],"class_list":["post-2324","post","type-post","status-publish","format-standard","hentry","category-49"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Circular 25\/2016 - Convocatoria CECLUB Segunda Divisi\u00f3n - FEDA<\/title>\n<meta name=\"description\" content=\"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/feda.org\/feda2k16\/circular-25-2016-convocatoria-ceclub-segunda-division\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Circular 25\/2016 - Convocatoria CECLUB Segunda Divisi\u00f3n - FEDA\" \/>\n<meta property=\"og:description\" content=\"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez\" \/>\n<meta property=\"og:url\" content=\"https:\/\/feda.org\/feda2k16\/circular-25-2016-convocatoria-ceclub-segunda-division\/\" \/>\n<meta property=\"og:site_name\" content=\"FEDA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/federacionespanoladeajedrez\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-07-15T13:15:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-08-06T08:34:02+00:00\" \/>\n<meta name=\"author\" content=\"feda2k16\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AjedrezEspanola\" \/>\n<meta name=\"twitter:site\" content=\"@AjedrezEspanola\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"feda2k16\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/circular-25-2016-convocatoria-ceclub-segunda-division\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/circular-25-2016-convocatoria-ceclub-segunda-division\\\/\"},\"author\":{\"name\":\"feda2k16\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/person\\\/80aa48a4dc5c6ea03ca1dbf21ce423da\"},\"headline\":\"Circular 25\\\/2016 &#8211; Convocatoria CECLUB Segunda Divisi\u00f3n\",\"datePublished\":\"2016-07-15T13:15:42+00:00\",\"dateModified\":\"2016-08-06T08:34:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/circular-25-2016-convocatoria-ceclub-segunda-division\\\/\"},\"wordCount\":1443,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#organization\"},\"articleSection\":[\"2016\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/feda.org\\\/feda2k16\\\/circular-25-2016-convocatoria-ceclub-segunda-division\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/circular-25-2016-convocatoria-ceclub-segunda-division\\\/\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/circular-25-2016-convocatoria-ceclub-segunda-division\\\/\",\"name\":\"Circular 25\\\/2016 - Convocatoria CECLUB Segunda Divisi\u00f3n - FEDA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#website\"},\"datePublished\":\"2016-07-15T13:15:42+00:00\",\"dateModified\":\"2016-08-06T08:34:02+00:00\",\"description\":\"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/circular-25-2016-convocatoria-ceclub-segunda-division\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/feda.org\\\/feda2k16\\\/circular-25-2016-convocatoria-ceclub-segunda-division\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/circular-25-2016-convocatoria-ceclub-segunda-division\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Circular 25\\\/2016 &#8211; Convocatoria CECLUB Segunda Divisi\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#website\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/\",\"name\":\"FEDA\",\"description\":\"Federaci\u00f3n Espa\u00f1ola de Ajedrez\",\"publisher\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#organization\"},\"alternateName\":\"Federaci\u00f3n Espa\u00f1ola de Ajedrez\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#organization\",\"name\":\"FEDA\",\"alternateName\":\"Federaci\u00f3n Espa\u00f1ola de Ajedrez\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/NuevoLogo_FEDA_2016.png\",\"contentUrl\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/NuevoLogo_FEDA_2016.png\",\"width\":600,\"height\":600,\"caption\":\"FEDA\"},\"image\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/federacionespanoladeajedrez\\\/\",\"https:\\\/\\\/x.com\\\/AjedrezEspanola\",\"https:\\\/\\\/www.instagram.com\\\/federacionespanolaajedrez\\\/?hl=es\",\"https:\\\/\\\/www.youtube.com\\\/@FederacionEspanoladeAjedrezFED\\\/featured\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/person\\\/80aa48a4dc5c6ea03ca1dbf21ce423da\",\"name\":\"feda2k16\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/author\\\/feda2k16\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Circular 25\/2016 - Convocatoria CECLUB Segunda Divisi\u00f3n - FEDA","description":"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/feda.org\/feda2k16\/circular-25-2016-convocatoria-ceclub-segunda-division\/","og_locale":"es_ES","og_type":"article","og_title":"Circular 25\/2016 - Convocatoria CECLUB Segunda Divisi\u00f3n - FEDA","og_description":"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez","og_url":"https:\/\/feda.org\/feda2k16\/circular-25-2016-convocatoria-ceclub-segunda-division\/","og_site_name":"FEDA","article_publisher":"https:\/\/www.facebook.com\/federacionespanoladeajedrez\/","article_published_time":"2016-07-15T13:15:42+00:00","article_modified_time":"2016-08-06T08:34:02+00:00","author":"feda2k16","twitter_card":"summary_large_image","twitter_creator":"@AjedrezEspanola","twitter_site":"@AjedrezEspanola","twitter_misc":{"Escrito por":"feda2k16","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/feda.org\/feda2k16\/circular-25-2016-convocatoria-ceclub-segunda-division\/#article","isPartOf":{"@id":"https:\/\/feda.org\/feda2k16\/circular-25-2016-convocatoria-ceclub-segunda-division\/"},"author":{"name":"feda2k16","@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/person\/80aa48a4dc5c6ea03ca1dbf21ce423da"},"headline":"Circular 25\/2016 &#8211; Convocatoria CECLUB Segunda Divisi\u00f3n","datePublished":"2016-07-15T13:15:42+00:00","dateModified":"2016-08-06T08:34:02+00:00","mainEntityOfPage":{"@id":"https:\/\/feda.org\/feda2k16\/circular-25-2016-convocatoria-ceclub-segunda-division\/"},"wordCount":1443,"commentCount":0,"publisher":{"@id":"https:\/\/feda.org\/feda2k16\/#organization"},"articleSection":["2016"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/feda.org\/feda2k16\/circular-25-2016-convocatoria-ceclub-segunda-division\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/feda.org\/feda2k16\/circular-25-2016-convocatoria-ceclub-segunda-division\/","url":"https:\/\/feda.org\/feda2k16\/circular-25-2016-convocatoria-ceclub-segunda-division\/","name":"Circular 25\/2016 - Convocatoria CECLUB Segunda Divisi\u00f3n - FEDA","isPartOf":{"@id":"https:\/\/feda.org\/feda2k16\/#website"},"datePublished":"2016-07-15T13:15:42+00:00","dateModified":"2016-08-06T08:34:02+00:00","description":"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez","breadcrumb":{"@id":"https:\/\/feda.org\/feda2k16\/circular-25-2016-convocatoria-ceclub-segunda-division\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/feda.org\/feda2k16\/circular-25-2016-convocatoria-ceclub-segunda-division\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/feda.org\/feda2k16\/circular-25-2016-convocatoria-ceclub-segunda-division\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/feda.org\/feda2k16\/"},{"@type":"ListItem","position":2,"name":"Circular 25\/2016 &#8211; Convocatoria CECLUB Segunda Divisi\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/feda.org\/feda2k16\/#website","url":"https:\/\/feda.org\/feda2k16\/","name":"FEDA","description":"Federaci\u00f3n Espa\u00f1ola de Ajedrez","publisher":{"@id":"https:\/\/feda.org\/feda2k16\/#organization"},"alternateName":"Federaci\u00f3n Espa\u00f1ola de Ajedrez","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/feda.org\/feda2k16\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/feda.org\/feda2k16\/#organization","name":"FEDA","alternateName":"Federaci\u00f3n Espa\u00f1ola de Ajedrez","url":"https:\/\/feda.org\/feda2k16\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/logo\/image\/","url":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/NuevoLogo_FEDA_2016.png","contentUrl":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/NuevoLogo_FEDA_2016.png","width":600,"height":600,"caption":"FEDA"},"image":{"@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/federacionespanoladeajedrez\/","https:\/\/x.com\/AjedrezEspanola","https:\/\/www.instagram.com\/federacionespanolaajedrez\/?hl=es","https:\/\/www.youtube.com\/@FederacionEspanoladeAjedrezFED\/featured"]},{"@type":"Person","@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/person\/80aa48a4dc5c6ea03ca1dbf21ce423da","name":"feda2k16","url":"https:\/\/feda.org\/feda2k16\/author\/feda2k16\/"}]}},"_links":{"self":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts\/2324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/comments?post=2324"}],"version-history":[{"count":1,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts\/2324\/revisions"}],"predecessor-version":[{"id":2493,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts\/2324\/revisions\/2493"}],"wp:attachment":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/media?parent=2324"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/categories?post=2324"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/tags?post=2324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}