{"id":24665,"date":"2024-09-01T16:37:00","date_gmt":"2024-09-01T16:37:00","guid":{"rendered":"https:\/\/feda.org\/feda2k16\/?p=24665"},"modified":"2024-09-01T16:37:02","modified_gmt":"2024-09-01T16:37:02","slug":"campeones-de-espana-de-aficionados-2024","status":"publish","type":"post","link":"https:\/\/feda.org\/feda2k16\/campeones-de-espana-de-aficionados-2024\/","title":{"rendered":"Campeones de Espa\u00f1a de Aficionados 2024."},"content":{"rendered":"\n<figure class=\"wp-block-image size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"1419\" src=\"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/PAT_1817-scaled.jpg\" alt=\"\" class=\"wp-image-24664\" style=\"width:846px;height:auto\" srcset=\"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/PAT_1817-scaled.jpg 2560w, https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/PAT_1817-768x426.jpg 768w, https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/PAT_1817-1536x851.jpg 1536w, https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/PAT_1817-2048x1135.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<p>Yassin Jes\u00fas El Ammari Rovira\u00a0 (1700) de Castilla de la Mancha, Pablo T\u00e1rraga Navarro (2000) de Castilla La Mancha y\u00a0 Alejandro Castellanos G\u00f3mez (2300) de Murcia se han proclamado Campeones de Espa\u00f1a de Aficionados por Tramos de Elo. Campeonato Organizado por la Federaci\u00f3n de Ajedrez de Castilla La Mancha en las instalaciones del Hotel Palacio de Albacete. Enhorabuena a Todos los jugadores que participaron en este Campeonato.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/feda.org\/feda2k16\/circular-19-2024-convocatoria-ctos-de-espana-de-aficionados-tramos-1700-200-2300-albacete-2024\/\">Convocatoria<\/a><\/p>\n<div dir=\"auto\" style=\"text-align: center;\">Clasificaci\u00f3n:\u00a0 INFO64<a href=\"https:\/\/info64.org\/ce-aficionados-2024-tramo-2300\/standings\">\u00a0-1700<\/a>\u00a0\/<a href=\"https:\/\/info64.org\/ce-aficionados-2024-tramo-2000\/standings\">\u00a0-2000<\/a>\u00a0\/\u00a0<a href=\"https:\/\/info64.org\/ce-aficionados-2024-tramo-2300\/standings\">-2300<\/a><\/div>\n<div dir=\"auto\" style=\"text-align: center;\">\u00a0<\/div>\n<div dir=\"auto\" style=\"text-align: center;\">Galer\u00eda de fotos:<a href=\"https:\/\/www.facebook.com\/media\/set\/?set=a.837554795133658&amp;type=3\">\u00a0Facebook FEDA<\/a><\/div>\n<div dir=\"auto\" style=\"text-align: center;\">\u00a0<\/div>\n<div dir=\"auto\" style=\"text-align: center;\">Retransmisi\u00f3n:\u00a0<a href=\"https:\/\/sichess.com\/web\/\">SICHESS<\/a><\/div>\n<p style=\"text-align: center;\">\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Yassin Jes\u00fas El Ammari Rovira\u00a0 (1700) de Castilla de la Mancha, Pablo T\u00e1rraga Navarro (2000) de Castilla La Mancha y\u00a0 Alejandro Castellanos G\u00f3mez (2300) de Murcia se han proclamado Campeones de Espa\u00f1a de Aficionados por Tramos de Elo. Campeonato Organizado por la Federaci\u00f3n de Ajedrez de Castilla La Mancha en las instalaciones del Hotel Palacio [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-24665","post","type-post","status-publish","format-standard","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Campeones de Espa\u00f1a de Aficionados 2024. - FEDA<\/title>\n<meta name=\"description\" content=\"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/feda.org\/feda2k16\/campeones-de-espana-de-aficionados-2024\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Campeones de Espa\u00f1a de Aficionados 2024. - FEDA\" \/>\n<meta property=\"og:description\" content=\"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez\" \/>\n<meta property=\"og:url\" content=\"https:\/\/feda.org\/feda2k16\/campeones-de-espana-de-aficionados-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"FEDA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/federacionespanoladeajedrez\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-01T16:37:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-01T16:37:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/PAT_1817-scaled.jpg\" \/>\n<meta name=\"author\" content=\"elefante66\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AjedrezEspanola\" \/>\n<meta name=\"twitter:site\" content=\"@AjedrezEspanola\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"elefante66\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeones-de-espana-de-aficionados-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeones-de-espana-de-aficionados-2024\\\/\"},\"author\":{\"name\":\"elefante66\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/person\\\/b39486343e189c77e58d02641385fe29\"},\"headline\":\"Campeones de Espa\u00f1a de Aficionados 2024.\",\"datePublished\":\"2024-09-01T16:37:00+00:00\",\"dateModified\":\"2024-09-01T16:37:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeones-de-espana-de-aficionados-2024\\\/\"},\"wordCount\":91,\"publisher\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeones-de-espana-de-aficionados-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/PAT_1817-scaled.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeones-de-espana-de-aficionados-2024\\\/\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeones-de-espana-de-aficionados-2024\\\/\",\"name\":\"Campeones de Espa\u00f1a de Aficionados 2024. - FEDA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeones-de-espana-de-aficionados-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeones-de-espana-de-aficionados-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/PAT_1817-scaled.jpg\",\"datePublished\":\"2024-09-01T16:37:00+00:00\",\"dateModified\":\"2024-09-01T16:37:02+00:00\",\"description\":\"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeones-de-espana-de-aficionados-2024\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeones-de-espana-de-aficionados-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeones-de-espana-de-aficionados-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/PAT_1817-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/PAT_1817-scaled.jpg\",\"width\":2560,\"height\":1419},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/campeones-de-espana-de-aficionados-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Campeones de Espa\u00f1a de Aficionados 2024.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#website\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/\",\"name\":\"FEDA\",\"description\":\"Federaci\u00f3n Espa\u00f1ola de Ajedrez\",\"publisher\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#organization\"},\"alternateName\":\"Federaci\u00f3n Espa\u00f1ola de Ajedrez\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#organization\",\"name\":\"FEDA\",\"alternateName\":\"Federaci\u00f3n Espa\u00f1ola de Ajedrez\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/NuevoLogo_FEDA_2016.png\",\"contentUrl\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/NuevoLogo_FEDA_2016.png\",\"width\":600,\"height\":600,\"caption\":\"FEDA\"},\"image\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/federacionespanoladeajedrez\\\/\",\"https:\\\/\\\/x.com\\\/AjedrezEspanola\",\"https:\\\/\\\/www.instagram.com\\\/federacionespanolaajedrez\\\/?hl=es\",\"https:\\\/\\\/www.youtube.com\\\/@FederacionEspanoladeAjedrezFED\\\/featured\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/person\\\/b39486343e189c77e58d02641385fe29\",\"name\":\"elefante66\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/author\\\/elefante66\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Campeones de Espa\u00f1a de Aficionados 2024. - FEDA","description":"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/feda.org\/feda2k16\/campeones-de-espana-de-aficionados-2024\/","og_locale":"es_ES","og_type":"article","og_title":"Campeones de Espa\u00f1a de Aficionados 2024. - FEDA","og_description":"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez","og_url":"https:\/\/feda.org\/feda2k16\/campeones-de-espana-de-aficionados-2024\/","og_site_name":"FEDA","article_publisher":"https:\/\/www.facebook.com\/federacionespanoladeajedrez\/","article_published_time":"2024-09-01T16:37:00+00:00","article_modified_time":"2024-09-01T16:37:02+00:00","og_image":[{"url":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/PAT_1817-scaled.jpg","type":"","width":"","height":""}],"author":"elefante66","twitter_card":"summary_large_image","twitter_creator":"@AjedrezEspanola","twitter_site":"@AjedrezEspanola","twitter_misc":{"Escrito por":"elefante66","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/feda.org\/feda2k16\/campeones-de-espana-de-aficionados-2024\/#article","isPartOf":{"@id":"https:\/\/feda.org\/feda2k16\/campeones-de-espana-de-aficionados-2024\/"},"author":{"name":"elefante66","@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/person\/b39486343e189c77e58d02641385fe29"},"headline":"Campeones de Espa\u00f1a de Aficionados 2024.","datePublished":"2024-09-01T16:37:00+00:00","dateModified":"2024-09-01T16:37:02+00:00","mainEntityOfPage":{"@id":"https:\/\/feda.org\/feda2k16\/campeones-de-espana-de-aficionados-2024\/"},"wordCount":91,"publisher":{"@id":"https:\/\/feda.org\/feda2k16\/#organization"},"image":{"@id":"https:\/\/feda.org\/feda2k16\/campeones-de-espana-de-aficionados-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/PAT_1817-scaled.jpg","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/feda.org\/feda2k16\/campeones-de-espana-de-aficionados-2024\/","url":"https:\/\/feda.org\/feda2k16\/campeones-de-espana-de-aficionados-2024\/","name":"Campeones de Espa\u00f1a de Aficionados 2024. - FEDA","isPartOf":{"@id":"https:\/\/feda.org\/feda2k16\/#website"},"primaryImageOfPage":{"@id":"https:\/\/feda.org\/feda2k16\/campeones-de-espana-de-aficionados-2024\/#primaryimage"},"image":{"@id":"https:\/\/feda.org\/feda2k16\/campeones-de-espana-de-aficionados-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/PAT_1817-scaled.jpg","datePublished":"2024-09-01T16:37:00+00:00","dateModified":"2024-09-01T16:37:02+00:00","description":"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez","breadcrumb":{"@id":"https:\/\/feda.org\/feda2k16\/campeones-de-espana-de-aficionados-2024\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/feda.org\/feda2k16\/campeones-de-espana-de-aficionados-2024\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/feda.org\/feda2k16\/campeones-de-espana-de-aficionados-2024\/#primaryimage","url":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/PAT_1817-scaled.jpg","contentUrl":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/PAT_1817-scaled.jpg","width":2560,"height":1419},{"@type":"BreadcrumbList","@id":"https:\/\/feda.org\/feda2k16\/campeones-de-espana-de-aficionados-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/feda.org\/feda2k16\/"},{"@type":"ListItem","position":2,"name":"Campeones de Espa\u00f1a de Aficionados 2024."}]},{"@type":"WebSite","@id":"https:\/\/feda.org\/feda2k16\/#website","url":"https:\/\/feda.org\/feda2k16\/","name":"FEDA","description":"Federaci\u00f3n Espa\u00f1ola de Ajedrez","publisher":{"@id":"https:\/\/feda.org\/feda2k16\/#organization"},"alternateName":"Federaci\u00f3n Espa\u00f1ola de Ajedrez","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/feda.org\/feda2k16\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/feda.org\/feda2k16\/#organization","name":"FEDA","alternateName":"Federaci\u00f3n Espa\u00f1ola de Ajedrez","url":"https:\/\/feda.org\/feda2k16\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/logo\/image\/","url":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/NuevoLogo_FEDA_2016.png","contentUrl":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/NuevoLogo_FEDA_2016.png","width":600,"height":600,"caption":"FEDA"},"image":{"@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/federacionespanoladeajedrez\/","https:\/\/x.com\/AjedrezEspanola","https:\/\/www.instagram.com\/federacionespanolaajedrez\/?hl=es","https:\/\/www.youtube.com\/@FederacionEspanoladeAjedrezFED\/featured"]},{"@type":"Person","@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/person\/b39486343e189c77e58d02641385fe29","name":"elefante66","url":"https:\/\/feda.org\/feda2k16\/author\/elefante66\/"}]}},"_links":{"self":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts\/24665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/comments?post=24665"}],"version-history":[{"count":1,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts\/24665\/revisions"}],"predecessor-version":[{"id":24666,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts\/24665\/revisions\/24666"}],"wp:attachment":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/media?parent=24665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/categories?post=24665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/tags?post=24665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}