{"id":25306,"date":"2024-12-15T19:40:06","date_gmt":"2024-12-15T19:40:06","guid":{"rendered":"https:\/\/feda.org\/feda2k16\/?p=25306"},"modified":"2024-12-15T19:42:56","modified_gmt":"2024-12-15T19:42:56","slug":"super-blitz-marbella-capital-espanola-del-ajedrez","status":"publish","type":"post","link":"https:\/\/feda.org\/feda2k16\/super-blitz-marbella-capital-espanola-del-ajedrez\/","title":{"rendered":"SUPER BLITZ MARBELLA CAPITAL ESPA\u00d1OLA DEL AJEDREZ."},"content":{"rendered":"\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-25304\" src=\"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/PAT_9074-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1638\" srcset=\"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/PAT_9074-scaled.jpg 2560w, https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/PAT_9074-768x492.jpg 768w, https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/PAT_9074-1536x983.jpg 1536w, https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/PAT_9074-2048x1311.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/p>\n\n\n\n<p>Hoy 15 de Diciembre se a celebrado la I Copa SUPER BLITZ MARBELLA Capital Espa\u00f1ola del Ajedrez en las instalaciones del Hotel Senator Marbella. El IM Enrique Tejedor Fuentes de Cantabria gan\u00f3 esta primera edici\u00f3n, IM Daniel Garc\u00eda Ramos de Catalu\u00f1a quedo en segunda posici\u00f3n y en tercer puesto Andr\u00e9s Merario Alarc\u00f3n de Marbella. La Primera clasificada Femenina fue la IM Marta Garc\u00eda Mart\u00edn de la Comunidad Valenciana. Adjuntamos informaci\u00f3n de la Copa.<\/p>\n<p style=\"text-align: center;\">Clasificaci\u00f3n: <a href=\"https:\/\/info64.org\/i-copa-superblitz-marbella-capital-espanola-del-ajedrez\/standings\">INFO64<\/a><\/p>\n<p style=\"text-align: center;\">Galer\u00eda Fotogr\u00e1fica: <a href=\"https:\/\/www.facebook.com\/media\/set\/?set=a.909926831229787&amp;type=3\">Facebook FEDA<\/a><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-25305\" src=\"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/sb.jpg\" alt=\"\" width=\"1198\" height=\"720\" srcset=\"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/sb.jpg 1198w, https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/sb-768x462.jpg 768w\" sizes=\"(max-width: 1198px) 100vw, 1198px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy 15 de Diciembre se a celebrado la I Copa SUPER BLITZ MARBELLA Capital Espa\u00f1ola del Ajedrez en las instalaciones del Hotel Senator Marbella. El IM Enrique Tejedor Fuentes de Cantabria gan\u00f3 esta primera edici\u00f3n, IM Daniel Garc\u00eda Ramos de Catalu\u00f1a quedo en segunda posici\u00f3n y en tercer puesto Andr\u00e9s Merario Alarc\u00f3n de Marbella. La [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-25306","post","type-post","status-publish","format-standard","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SUPER BLITZ MARBELLA CAPITAL ESPA\u00d1OLA DEL AJEDREZ. - FEDA<\/title>\n<meta name=\"description\" content=\"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/feda.org\/feda2k16\/super-blitz-marbella-capital-espanola-del-ajedrez\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SUPER BLITZ MARBELLA CAPITAL ESPA\u00d1OLA DEL AJEDREZ. - FEDA\" \/>\n<meta property=\"og:description\" content=\"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez\" \/>\n<meta property=\"og:url\" content=\"https:\/\/feda.org\/feda2k16\/super-blitz-marbella-capital-espanola-del-ajedrez\/\" \/>\n<meta property=\"og:site_name\" content=\"FEDA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/federacionespanoladeajedrez\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-15T19:40:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-15T19:42:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/PAT_9074-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1638\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"elefante66\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AjedrezEspanola\" \/>\n<meta name=\"twitter:site\" content=\"@AjedrezEspanola\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"elefante66\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/super-blitz-marbella-capital-espanola-del-ajedrez\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/super-blitz-marbella-capital-espanola-del-ajedrez\\\/\"},\"author\":{\"name\":\"elefante66\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/person\\\/b39486343e189c77e58d02641385fe29\"},\"headline\":\"SUPER BLITZ MARBELLA CAPITAL ESPA\u00d1OLA DEL AJEDREZ.\",\"datePublished\":\"2024-12-15T19:40:06+00:00\",\"dateModified\":\"2024-12-15T19:42:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/super-blitz-marbella-capital-espanola-del-ajedrez\\\/\"},\"wordCount\":99,\"publisher\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/super-blitz-marbella-capital-espanola-del-ajedrez\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/PAT_9074-scaled.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/super-blitz-marbella-capital-espanola-del-ajedrez\\\/\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/super-blitz-marbella-capital-espanola-del-ajedrez\\\/\",\"name\":\"SUPER BLITZ MARBELLA CAPITAL ESPA\u00d1OLA DEL AJEDREZ. - FEDA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/super-blitz-marbella-capital-espanola-del-ajedrez\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/super-blitz-marbella-capital-espanola-del-ajedrez\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/PAT_9074-scaled.jpg\",\"datePublished\":\"2024-12-15T19:40:06+00:00\",\"dateModified\":\"2024-12-15T19:42:56+00:00\",\"description\":\"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/super-blitz-marbella-capital-espanola-del-ajedrez\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/feda.org\\\/feda2k16\\\/super-blitz-marbella-capital-espanola-del-ajedrez\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/super-blitz-marbella-capital-espanola-del-ajedrez\\\/#primaryimage\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/PAT_9074-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/PAT_9074-scaled.jpg\",\"width\":2560,\"height\":1638},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/super-blitz-marbella-capital-espanola-del-ajedrez\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SUPER BLITZ MARBELLA CAPITAL ESPA\u00d1OLA DEL AJEDREZ.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#website\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/\",\"name\":\"FEDA\",\"description\":\"Federaci\u00f3n Espa\u00f1ola de Ajedrez\",\"publisher\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#organization\"},\"alternateName\":\"Federaci\u00f3n Espa\u00f1ola de Ajedrez\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#organization\",\"name\":\"FEDA\",\"alternateName\":\"Federaci\u00f3n Espa\u00f1ola de Ajedrez\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/NuevoLogo_FEDA_2016.png\",\"contentUrl\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/NuevoLogo_FEDA_2016.png\",\"width\":600,\"height\":600,\"caption\":\"FEDA\"},\"image\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/federacionespanoladeajedrez\\\/\",\"https:\\\/\\\/x.com\\\/AjedrezEspanola\",\"https:\\\/\\\/www.instagram.com\\\/federacionespanolaajedrez\\\/?hl=es\",\"https:\\\/\\\/www.youtube.com\\\/@FederacionEspanoladeAjedrezFED\\\/featured\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/person\\\/b39486343e189c77e58d02641385fe29\",\"name\":\"elefante66\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/author\\\/elefante66\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SUPER BLITZ MARBELLA CAPITAL ESPA\u00d1OLA DEL AJEDREZ. - FEDA","description":"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/feda.org\/feda2k16\/super-blitz-marbella-capital-espanola-del-ajedrez\/","og_locale":"es_ES","og_type":"article","og_title":"SUPER BLITZ MARBELLA CAPITAL ESPA\u00d1OLA DEL AJEDREZ. - FEDA","og_description":"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez","og_url":"https:\/\/feda.org\/feda2k16\/super-blitz-marbella-capital-espanola-del-ajedrez\/","og_site_name":"FEDA","article_publisher":"https:\/\/www.facebook.com\/federacionespanoladeajedrez\/","article_published_time":"2024-12-15T19:40:06+00:00","article_modified_time":"2024-12-15T19:42:56+00:00","og_image":[{"width":2560,"height":1638,"url":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/PAT_9074-scaled.jpg","type":"image\/jpeg"}],"author":"elefante66","twitter_card":"summary_large_image","twitter_creator":"@AjedrezEspanola","twitter_site":"@AjedrezEspanola","twitter_misc":{"Escrito por":"elefante66","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/feda.org\/feda2k16\/super-blitz-marbella-capital-espanola-del-ajedrez\/#article","isPartOf":{"@id":"https:\/\/feda.org\/feda2k16\/super-blitz-marbella-capital-espanola-del-ajedrez\/"},"author":{"name":"elefante66","@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/person\/b39486343e189c77e58d02641385fe29"},"headline":"SUPER BLITZ MARBELLA CAPITAL ESPA\u00d1OLA DEL AJEDREZ.","datePublished":"2024-12-15T19:40:06+00:00","dateModified":"2024-12-15T19:42:56+00:00","mainEntityOfPage":{"@id":"https:\/\/feda.org\/feda2k16\/super-blitz-marbella-capital-espanola-del-ajedrez\/"},"wordCount":99,"publisher":{"@id":"https:\/\/feda.org\/feda2k16\/#organization"},"image":{"@id":"https:\/\/feda.org\/feda2k16\/super-blitz-marbella-capital-espanola-del-ajedrez\/#primaryimage"},"thumbnailUrl":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/PAT_9074-scaled.jpg","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/feda.org\/feda2k16\/super-blitz-marbella-capital-espanola-del-ajedrez\/","url":"https:\/\/feda.org\/feda2k16\/super-blitz-marbella-capital-espanola-del-ajedrez\/","name":"SUPER BLITZ MARBELLA CAPITAL ESPA\u00d1OLA DEL AJEDREZ. - FEDA","isPartOf":{"@id":"https:\/\/feda.org\/feda2k16\/#website"},"primaryImageOfPage":{"@id":"https:\/\/feda.org\/feda2k16\/super-blitz-marbella-capital-espanola-del-ajedrez\/#primaryimage"},"image":{"@id":"https:\/\/feda.org\/feda2k16\/super-blitz-marbella-capital-espanola-del-ajedrez\/#primaryimage"},"thumbnailUrl":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/PAT_9074-scaled.jpg","datePublished":"2024-12-15T19:40:06+00:00","dateModified":"2024-12-15T19:42:56+00:00","description":"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez","breadcrumb":{"@id":"https:\/\/feda.org\/feda2k16\/super-blitz-marbella-capital-espanola-del-ajedrez\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/feda.org\/feda2k16\/super-blitz-marbella-capital-espanola-del-ajedrez\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/feda.org\/feda2k16\/super-blitz-marbella-capital-espanola-del-ajedrez\/#primaryimage","url":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/PAT_9074-scaled.jpg","contentUrl":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/PAT_9074-scaled.jpg","width":2560,"height":1638},{"@type":"BreadcrumbList","@id":"https:\/\/feda.org\/feda2k16\/super-blitz-marbella-capital-espanola-del-ajedrez\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/feda.org\/feda2k16\/"},{"@type":"ListItem","position":2,"name":"SUPER BLITZ MARBELLA CAPITAL ESPA\u00d1OLA DEL AJEDREZ."}]},{"@type":"WebSite","@id":"https:\/\/feda.org\/feda2k16\/#website","url":"https:\/\/feda.org\/feda2k16\/","name":"FEDA","description":"Federaci\u00f3n Espa\u00f1ola de Ajedrez","publisher":{"@id":"https:\/\/feda.org\/feda2k16\/#organization"},"alternateName":"Federaci\u00f3n Espa\u00f1ola de Ajedrez","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/feda.org\/feda2k16\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/feda.org\/feda2k16\/#organization","name":"FEDA","alternateName":"Federaci\u00f3n Espa\u00f1ola de Ajedrez","url":"https:\/\/feda.org\/feda2k16\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/logo\/image\/","url":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/NuevoLogo_FEDA_2016.png","contentUrl":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/NuevoLogo_FEDA_2016.png","width":600,"height":600,"caption":"FEDA"},"image":{"@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/federacionespanoladeajedrez\/","https:\/\/x.com\/AjedrezEspanola","https:\/\/www.instagram.com\/federacionespanolaajedrez\/?hl=es","https:\/\/www.youtube.com\/@FederacionEspanoladeAjedrezFED\/featured"]},{"@type":"Person","@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/person\/b39486343e189c77e58d02641385fe29","name":"elefante66","url":"https:\/\/feda.org\/feda2k16\/author\/elefante66\/"}]}},"_links":{"self":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts\/25306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/comments?post=25306"}],"version-history":[{"count":3,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts\/25306\/revisions"}],"predecessor-version":[{"id":25310,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts\/25306\/revisions\/25310"}],"wp:attachment":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/media?parent=25306"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/categories?post=25306"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/tags?post=25306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}