{"id":26990,"date":"2025-09-04T15:20:52","date_gmt":"2025-09-04T15:20:52","guid":{"rendered":"https:\/\/feda.org\/feda2k16\/?p=26990"},"modified":"2025-09-04T15:22:23","modified_gmt":"2025-09-04T15:22:23","slug":"c24-2025-licencias-y-cuotas-de-club-2026","status":"publish","type":"post","link":"https:\/\/feda.org\/feda2k16\/c24-2025-licencias-y-cuotas-de-club-2026\/","title":{"rendered":"C24\/2025. Licencias y Cuotas de Club 2026"},"content":{"rendered":"\n<p>Se ha publicado <a href=\"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/C24-2025_Licencias_2026.pdf\">C24\/2025. Licencias y cuotas de Club 2026.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se ha publicado C24\/2025. Licencias y cuotas de Club 2026.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-26990","post","type-post","status-publish","format-standard","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C24\/2025. Licencias y Cuotas de Club 2026 - FEDA<\/title>\n<meta name=\"description\" content=\"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/feda.org\/feda2k16\/c24-2025-licencias-y-cuotas-de-club-2026\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C24\/2025. Licencias y Cuotas de Club 2026 - FEDA\" \/>\n<meta property=\"og:description\" content=\"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez\" \/>\n<meta property=\"og:url\" content=\"https:\/\/feda.org\/feda2k16\/c24-2025-licencias-y-cuotas-de-club-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"FEDA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/federacionespanoladeajedrez\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-04T15:20:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-04T15:22:23+00:00\" \/>\n<meta name=\"author\" content=\"elefante66\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AjedrezEspanola\" \/>\n<meta name=\"twitter:site\" content=\"@AjedrezEspanola\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"elefante66\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/c24-2025-licencias-y-cuotas-de-club-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/c24-2025-licencias-y-cuotas-de-club-2026\\\/\"},\"author\":{\"name\":\"elefante66\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/person\\\/b39486343e189c77e58d02641385fe29\"},\"headline\":\"C24\\\/2025. Licencias y Cuotas de Club 2026\",\"datePublished\":\"2025-09-04T15:20:52+00:00\",\"dateModified\":\"2025-09-04T15:22:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/c24-2025-licencias-y-cuotas-de-club-2026\\\/\"},\"wordCount\":15,\"publisher\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#organization\"},\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/c24-2025-licencias-y-cuotas-de-club-2026\\\/\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/c24-2025-licencias-y-cuotas-de-club-2026\\\/\",\"name\":\"C24\\\/2025. Licencias y Cuotas de Club 2026 - FEDA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#website\"},\"datePublished\":\"2025-09-04T15:20:52+00:00\",\"dateModified\":\"2025-09-04T15:22:23+00:00\",\"description\":\"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/c24-2025-licencias-y-cuotas-de-club-2026\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/feda.org\\\/feda2k16\\\/c24-2025-licencias-y-cuotas-de-club-2026\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/c24-2025-licencias-y-cuotas-de-club-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C24\\\/2025. Licencias y Cuotas de Club 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#website\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/\",\"name\":\"FEDA\",\"description\":\"Federaci\u00f3n Espa\u00f1ola de Ajedrez\",\"publisher\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#organization\"},\"alternateName\":\"Federaci\u00f3n Espa\u00f1ola de Ajedrez\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#organization\",\"name\":\"FEDA\",\"alternateName\":\"Federaci\u00f3n Espa\u00f1ola de Ajedrez\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/NuevoLogo_FEDA_2016.png\",\"contentUrl\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/NuevoLogo_FEDA_2016.png\",\"width\":600,\"height\":600,\"caption\":\"FEDA\"},\"image\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/federacionespanoladeajedrez\\\/\",\"https:\\\/\\\/x.com\\\/AjedrezEspanola\",\"https:\\\/\\\/www.instagram.com\\\/federacionespanolaajedrez\\\/?hl=es\",\"https:\\\/\\\/www.youtube.com\\\/@FederacionEspanoladeAjedrezFED\\\/featured\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/person\\\/b39486343e189c77e58d02641385fe29\",\"name\":\"elefante66\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/author\\\/elefante66\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C24\/2025. Licencias y Cuotas de Club 2026 - FEDA","description":"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/feda.org\/feda2k16\/c24-2025-licencias-y-cuotas-de-club-2026\/","og_locale":"es_ES","og_type":"article","og_title":"C24\/2025. Licencias y Cuotas de Club 2026 - FEDA","og_description":"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez","og_url":"https:\/\/feda.org\/feda2k16\/c24-2025-licencias-y-cuotas-de-club-2026\/","og_site_name":"FEDA","article_publisher":"https:\/\/www.facebook.com\/federacionespanoladeajedrez\/","article_published_time":"2025-09-04T15:20:52+00:00","article_modified_time":"2025-09-04T15:22:23+00:00","author":"elefante66","twitter_card":"summary_large_image","twitter_creator":"@AjedrezEspanola","twitter_site":"@AjedrezEspanola","twitter_misc":{"Escrito por":"elefante66","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/feda.org\/feda2k16\/c24-2025-licencias-y-cuotas-de-club-2026\/#article","isPartOf":{"@id":"https:\/\/feda.org\/feda2k16\/c24-2025-licencias-y-cuotas-de-club-2026\/"},"author":{"name":"elefante66","@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/person\/b39486343e189c77e58d02641385fe29"},"headline":"C24\/2025. Licencias y Cuotas de Club 2026","datePublished":"2025-09-04T15:20:52+00:00","dateModified":"2025-09-04T15:22:23+00:00","mainEntityOfPage":{"@id":"https:\/\/feda.org\/feda2k16\/c24-2025-licencias-y-cuotas-de-club-2026\/"},"wordCount":15,"publisher":{"@id":"https:\/\/feda.org\/feda2k16\/#organization"},"articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/feda.org\/feda2k16\/c24-2025-licencias-y-cuotas-de-club-2026\/","url":"https:\/\/feda.org\/feda2k16\/c24-2025-licencias-y-cuotas-de-club-2026\/","name":"C24\/2025. Licencias y Cuotas de Club 2026 - FEDA","isPartOf":{"@id":"https:\/\/feda.org\/feda2k16\/#website"},"datePublished":"2025-09-04T15:20:52+00:00","dateModified":"2025-09-04T15:22:23+00:00","description":"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez","breadcrumb":{"@id":"https:\/\/feda.org\/feda2k16\/c24-2025-licencias-y-cuotas-de-club-2026\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/feda.org\/feda2k16\/c24-2025-licencias-y-cuotas-de-club-2026\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/feda.org\/feda2k16\/c24-2025-licencias-y-cuotas-de-club-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/feda.org\/feda2k16\/"},{"@type":"ListItem","position":2,"name":"C24\/2025. Licencias y Cuotas de Club 2026"}]},{"@type":"WebSite","@id":"https:\/\/feda.org\/feda2k16\/#website","url":"https:\/\/feda.org\/feda2k16\/","name":"FEDA","description":"Federaci\u00f3n Espa\u00f1ola de Ajedrez","publisher":{"@id":"https:\/\/feda.org\/feda2k16\/#organization"},"alternateName":"Federaci\u00f3n Espa\u00f1ola de Ajedrez","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/feda.org\/feda2k16\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/feda.org\/feda2k16\/#organization","name":"FEDA","alternateName":"Federaci\u00f3n Espa\u00f1ola de Ajedrez","url":"https:\/\/feda.org\/feda2k16\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/logo\/image\/","url":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/NuevoLogo_FEDA_2016.png","contentUrl":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/NuevoLogo_FEDA_2016.png","width":600,"height":600,"caption":"FEDA"},"image":{"@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/federacionespanoladeajedrez\/","https:\/\/x.com\/AjedrezEspanola","https:\/\/www.instagram.com\/federacionespanolaajedrez\/?hl=es","https:\/\/www.youtube.com\/@FederacionEspanoladeAjedrezFED\/featured"]},{"@type":"Person","@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/person\/b39486343e189c77e58d02641385fe29","name":"elefante66","url":"https:\/\/feda.org\/feda2k16\/author\/elefante66\/"}]}},"_links":{"self":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts\/26990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/comments?post=26990"}],"version-history":[{"count":2,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts\/26990\/revisions"}],"predecessor-version":[{"id":26993,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts\/26990\/revisions\/26993"}],"wp:attachment":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/media?parent=26990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/categories?post=26990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/tags?post=26990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}