{"id":27358,"date":"2025-11-20T18:17:49","date_gmt":"2025-11-20T18:17:49","guid":{"rendered":"https:\/\/feda.org\/feda2k16\/?p=27358"},"modified":"2025-11-20T18:22:15","modified_gmt":"2025-11-20T18:22:15","slug":"mundial-en-linares-ronda-5","status":"publish","type":"post","link":"https:\/\/feda.org\/feda2k16\/mundial-en-linares-ronda-5\/","title":{"rendered":"Mundial en Linares: ronda 5."},"content":{"rendered":"\n\n\n<p>En la quinta ronda, \u00faltima de la fase clasificatoria, Espa\u00f1a se enfrent\u00f3 a Azerbaiy\u00e1n, mientras que Per\u00fa, ya sin opciones de clasificaci\u00f3n, jug\u00f3 contra el Team FIDE. Espa\u00f1a necesitaba ganar el match para asegurarse el pase a la fase eliminatoria.<\/p>\n\n\n\n<p>\u00a0<\/p>\n<p style=\"text-align: center;\"><strong>Azerbaiy\u00e1n 3\u00bd-\u00bd Espa\u00f1a<\/strong><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-27359\" src=\"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/Imagen-de-WhatsApp-2025-11-20-a-las-19.07.38_337da30b.jpg\" alt=\"\" width=\"2048\" height=\"1366\" srcset=\"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/Imagen-de-WhatsApp-2025-11-20-a-las-19.07.38_337da30b.jpg 2048w, https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/Imagen-de-WhatsApp-2025-11-20-a-las-19.07.38_337da30b-768x512.jpg 768w, https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/Imagen-de-WhatsApp-2025-11-20-a-las-19.07.38_337da30b-1536x1025.jpg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/p>\n<p><strong>\u00a0<\/strong>Era un match decisivo para ambos equipos: la victoria les garantizaba la clasificaci\u00f3n, mientras que las tablas lo dejaban todo a merced de los desempates. Lamentablemente, las cosas salieron muy mal para las espa\u00f1olas.<\/p>\n<p>En el primer tablero la MI Sara Khadem escogio la Caro-Kann, una apertura bastante de moda en los \u00faltimos a\u00f1os. La MI Ulviyya Fataliyeva elegio la variante de avance, pero Khadem la sorprendi\u00f3 con una jugada poco com\u00fan en jugada 4. La calidad de la novedad no era muy buena, pero llevo a una posici\u00f3n cerrada y complicada. Con juego agresivo las blancas sacrificaron una pieza en jugada 23 y abrieron el centro donde todav\u00eda se encontraba el rey negro. El ataque era decisivo y las blancas ganaron en 28 jugadas.<\/p>\n<p>En el segundo tablero, la MI Sabrina Vega y la WGM Govhar Beydullayeva demostraron un excelente conocimiento te\u00f3rico en la variante Najdorf de la Siciliana. Jugaron con rapidez y, seg\u00fan el an\u00e1lisis, la partida concluy\u00f3 con repetici\u00f3n de jugadas y jaque perpetuo en la jugada 27.<\/p>\n<p>La MI Ann Matnadze jug\u00f3 su habitual Siciliana cl\u00e1sica contra la MI Khanim Balajayeva, pero muy pronto decidi\u00f3 arriesgar y entr\u00f3 en una posici\u00f3n similar a la variante Sveshnikov, aunque en una versi\u00f3n claramente favorable para las blancas. Con juego incisivo, las blancas aumentaron su ventaja y remataron con un ataque directo contra el rey de Matnadze.<\/p>\n<p>La MI Gulnar Mammadova eligi\u00f3 la Defensa Moderna contra el esquema de fianchetto de la WFM In\u00e9s Prado, alcanzando un mediojuego t\u00edpico de la India de Rey. En la jugada 15, las blancas escogieron un avance central err\u00f3neo que cedi\u00f3 la iniciativa a las negras. Poco despu\u00e9s, esta iniciativa se transform\u00f3 en ventaja material de un pe\u00f3n, sumada a la mayor actividad de las piezas negras, y Mammadova convirti\u00f3 la ventaja en 29 jugadas.<\/p>\n<p>\u00a0<\/p>\n<p style=\"text-align: center;\"><strong>Peru \u00bd-3\u00bd Team FIDE<\/strong><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-27360\" src=\"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/Imagen-de-WhatsApp-2025-11-20-a-las-19.07.38_4d8622b5.jpg\" alt=\"\" width=\"2048\" height=\"1624\" srcset=\"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/Imagen-de-WhatsApp-2025-11-20-a-las-19.07.38_4d8622b5.jpg 2048w, https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/Imagen-de-WhatsApp-2025-11-20-a-las-19.07.38_4d8622b5-768x609.jpg 768w, https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/Imagen-de-WhatsApp-2025-11-20-a-las-19.07.38_4d8622b5-1536x1218.jpg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/p>\n<p>Aunque llevaba blancas, la MI Deisy Cori plante\u00f3 la partida con un esquema tipo Pirc contra la MI Polina Shuvalova. Las negras ocuparon el centro con sus peones mientras las blancas avanzaban el pe\u00f3n \u201ch\u201d. El problema para Cori fue la gesti\u00f3n del tiempo: en la jugada 15 ya solo ten\u00eda 4 minutos frente a los 30 de Shuvalova. En la jugada 20 jugaba pr\u00e1cticamente a la ca\u00edda de bandera y su posici\u00f3n ya era perdedora. La partida termin\u00f3 tres jugadas m\u00e1s tarde, con el mate ya cercano.<\/p>\n<p>La WIM Heidi Garc\u00eda eligi\u00f3 una continuaci\u00f3n sospechosa en la variante Rossolimo de la Siciliana contra la MI Leya Garifullina, pero las blancas no la castigaron de la forma m\u00e1s precisa y las negras alcanzaron una posici\u00f3n aceptable. Como en el caso de Cori, el problema de Garc\u00eda fue la gesti\u00f3n del tiempo: en la jugada 30 jugaba con apenas unos segundos en el reloj frente a los 20 minutos de Garifullina. En el apuro de tiempo, perdi\u00f3 un pe\u00f3n y Garifullina convirti\u00f3 la ventaja material en 46 jugadas.<\/p>\n<p>La MF Fiorella Contreras eligi\u00f3 la Siciliana cerrada contra la WGM Anna Shukhman. Las blancas no lograron generar ataque, pero tras algunas simplificaciones llegaron a un final algo m\u00e1s c\u00f3modo para ellas. Shukhman jug\u00f3 con precisi\u00f3n para que la ventaja no creciera y, con poco tiempo para ambas, las negras encontraron un jaque perpetuo.<\/p>\n<p>La mezcla de la Semi-eslava y la Catalana dio a la GM Olga Girya ventaja de espacio frente a la WIM Mar\u00eda Jim\u00e9nez. En el mediojuego, las negras quedaron adem\u00e1s con un alfil pasivo en b7. Girya organiz\u00f3 un avance en el flanco de dama y, cuando las negras se defendieron all\u00ed, cambi\u00f3 de flanco y lanz\u00f3 un ataque en el flanco de rey. Para rematar, las blancas rompieron en el centro y obtuvieron un pe\u00f3n pasado protegido en d6, ventaja suficiente para ganar la partida en el final.<\/p>\n<p>Posici\u00f3n del d\u00eda:<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-27361 alignleft\" src=\"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/l.jpg\" alt=\"\" width=\"351\" height=\"351\" \/><\/p>\n<p style=\"text-align: right;\">\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>El rey negro (Matnadze) est\u00e1 en peligro. \u00bfC\u00f3mo decidi\u00f3 Balajayeva la partida con un ataque directo?<\/p>\n<p>Las blancas jugaron 20.Th3!, con idea de utilizar la columna \u201cg\u201d con Tg3. Matnadze lo permiti\u00f3 con 20\u2026Td8 y abandon\u00f3 tras 21.Tg3. Lo mismo suceder\u00eda con 20\u2026Axh3 21.gxh3, cuando la otra torre llegar\u00eda a la columna \u201cg\u201d mediante Tg1.<\/p>\n\n\n\n<p>\u00a0<\/p>\n<p>M\u00e1s informaci\u00f3n en los siguientes:<\/p>\n<p style=\"text-align: center;\">Website:\u00a0<a href=\"https:\/\/worldwomenteams2025.fide.com\/\">https:\/\/worldwomenteams2025.fide.com\/<\/a><\/p>\n<p style=\"text-align: center;\">INFO64:\u00a0<a href=\"https:\/\/info64.org\/team\/world-women-team-champ-pool-a\">POOL A<\/a>\u00a0 \u00a0\u2013\u00a0 \u00a0<a href=\"https:\/\/info64.org\/team\/world-women-team-champ-pool-b\">POOL B<\/a><\/p>\n<p style=\"text-align: center;\">Galer\u00eda fotogr\u00e1fica: <a href=\"https:\/\/www.facebook.com\/media\/set\/?set=a.1166532055569262&amp;type=3\">Facebook FEDA &#8211; Pavel Dvorkovich<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la quinta ronda, \u00faltima de la fase clasificatoria, Espa\u00f1a se enfrent\u00f3 a Azerbaiy\u00e1n, mientras que Per\u00fa, ya sin opciones de clasificaci\u00f3n, jug\u00f3 contra el Team FIDE. Espa\u00f1a necesitaba ganar el match para asegurarse el pase a la fase eliminatoria. \u00a0 Azerbaiy\u00e1n 3\u00bd-\u00bd Espa\u00f1a \u00a0Era un match decisivo para ambos equipos: la victoria les garantizaba [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-27358","post","type-post","status-publish","format-standard","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mundial en Linares: ronda 5. - FEDA<\/title>\n<meta name=\"description\" content=\"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/feda.org\/feda2k16\/mundial-en-linares-ronda-5\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mundial en Linares: ronda 5. - FEDA\" \/>\n<meta property=\"og:description\" content=\"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez\" \/>\n<meta property=\"og:url\" content=\"https:\/\/feda.org\/feda2k16\/mundial-en-linares-ronda-5\/\" \/>\n<meta property=\"og:site_name\" content=\"FEDA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/federacionespanoladeajedrez\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-20T18:17:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-20T18:22:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/Imagen-de-WhatsApp-2025-11-20-a-las-19.07.38_337da30b.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1366\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"elefante66\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AjedrezEspanola\" \/>\n<meta name=\"twitter:site\" content=\"@AjedrezEspanola\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"elefante66\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/mundial-en-linares-ronda-5\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/mundial-en-linares-ronda-5\\\/\"},\"author\":{\"name\":\"elefante66\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/person\\\/b39486343e189c77e58d02641385fe29\"},\"headline\":\"Mundial en Linares: ronda 5.\",\"datePublished\":\"2025-11-20T18:17:49+00:00\",\"dateModified\":\"2025-11-20T18:22:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/mundial-en-linares-ronda-5\\\/\"},\"wordCount\":794,\"publisher\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/mundial-en-linares-ronda-5\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/Imagen-de-WhatsApp-2025-11-20-a-las-19.07.38_337da30b.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/mundial-en-linares-ronda-5\\\/\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/mundial-en-linares-ronda-5\\\/\",\"name\":\"Mundial en Linares: ronda 5. - FEDA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/mundial-en-linares-ronda-5\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/mundial-en-linares-ronda-5\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/Imagen-de-WhatsApp-2025-11-20-a-las-19.07.38_337da30b.jpg\",\"datePublished\":\"2025-11-20T18:17:49+00:00\",\"dateModified\":\"2025-11-20T18:22:15+00:00\",\"description\":\"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/mundial-en-linares-ronda-5\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/feda.org\\\/feda2k16\\\/mundial-en-linares-ronda-5\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/mundial-en-linares-ronda-5\\\/#primaryimage\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/Imagen-de-WhatsApp-2025-11-20-a-las-19.07.38_337da30b.jpg\",\"contentUrl\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/Imagen-de-WhatsApp-2025-11-20-a-las-19.07.38_337da30b.jpg\",\"width\":2048,\"height\":1366},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/mundial-en-linares-ronda-5\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mundial en Linares: ronda 5.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#website\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/\",\"name\":\"FEDA\",\"description\":\"Federaci\u00f3n Espa\u00f1ola de Ajedrez\",\"publisher\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#organization\"},\"alternateName\":\"Federaci\u00f3n Espa\u00f1ola de Ajedrez\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#organization\",\"name\":\"FEDA\",\"alternateName\":\"Federaci\u00f3n Espa\u00f1ola de Ajedrez\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/NuevoLogo_FEDA_2016.png\",\"contentUrl\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/wp-content\\\/uploads\\\/NuevoLogo_FEDA_2016.png\",\"width\":600,\"height\":600,\"caption\":\"FEDA\"},\"image\":{\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/federacionespanoladeajedrez\\\/\",\"https:\\\/\\\/x.com\\\/AjedrezEspanola\",\"https:\\\/\\\/www.instagram.com\\\/federacionespanolaajedrez\\\/?hl=es\",\"https:\\\/\\\/www.youtube.com\\\/@FederacionEspanoladeAjedrezFED\\\/featured\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/#\\\/schema\\\/person\\\/b39486343e189c77e58d02641385fe29\",\"name\":\"elefante66\",\"url\":\"https:\\\/\\\/feda.org\\\/feda2k16\\\/author\\\/elefante66\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mundial en Linares: ronda 5. - FEDA","description":"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/feda.org\/feda2k16\/mundial-en-linares-ronda-5\/","og_locale":"es_ES","og_type":"article","og_title":"Mundial en Linares: ronda 5. - FEDA","og_description":"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez","og_url":"https:\/\/feda.org\/feda2k16\/mundial-en-linares-ronda-5\/","og_site_name":"FEDA","article_publisher":"https:\/\/www.facebook.com\/federacionespanoladeajedrez\/","article_published_time":"2025-11-20T18:17:49+00:00","article_modified_time":"2025-11-20T18:22:15+00:00","og_image":[{"width":2048,"height":1366,"url":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/Imagen-de-WhatsApp-2025-11-20-a-las-19.07.38_337da30b.jpg","type":"image\/jpeg"}],"author":"elefante66","twitter_card":"summary_large_image","twitter_creator":"@AjedrezEspanola","twitter_site":"@AjedrezEspanola","twitter_misc":{"Escrito por":"elefante66","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/feda.org\/feda2k16\/mundial-en-linares-ronda-5\/#article","isPartOf":{"@id":"https:\/\/feda.org\/feda2k16\/mundial-en-linares-ronda-5\/"},"author":{"name":"elefante66","@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/person\/b39486343e189c77e58d02641385fe29"},"headline":"Mundial en Linares: ronda 5.","datePublished":"2025-11-20T18:17:49+00:00","dateModified":"2025-11-20T18:22:15+00:00","mainEntityOfPage":{"@id":"https:\/\/feda.org\/feda2k16\/mundial-en-linares-ronda-5\/"},"wordCount":794,"publisher":{"@id":"https:\/\/feda.org\/feda2k16\/#organization"},"image":{"@id":"https:\/\/feda.org\/feda2k16\/mundial-en-linares-ronda-5\/#primaryimage"},"thumbnailUrl":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/Imagen-de-WhatsApp-2025-11-20-a-las-19.07.38_337da30b.jpg","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/feda.org\/feda2k16\/mundial-en-linares-ronda-5\/","url":"https:\/\/feda.org\/feda2k16\/mundial-en-linares-ronda-5\/","name":"Mundial en Linares: ronda 5. - FEDA","isPartOf":{"@id":"https:\/\/feda.org\/feda2k16\/#website"},"primaryImageOfPage":{"@id":"https:\/\/feda.org\/feda2k16\/mundial-en-linares-ronda-5\/#primaryimage"},"image":{"@id":"https:\/\/feda.org\/feda2k16\/mundial-en-linares-ronda-5\/#primaryimage"},"thumbnailUrl":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/Imagen-de-WhatsApp-2025-11-20-a-las-19.07.38_337da30b.jpg","datePublished":"2025-11-20T18:17:49+00:00","dateModified":"2025-11-20T18:22:15+00:00","description":"FEDA, Federaci\u00f3n Espa\u00f1ola de Ajedrez, ajedrez madrid, federarse ajedrez, campeonato de Espa\u00f1a de ajedrez, ajedrez","breadcrumb":{"@id":"https:\/\/feda.org\/feda2k16\/mundial-en-linares-ronda-5\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/feda.org\/feda2k16\/mundial-en-linares-ronda-5\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/feda.org\/feda2k16\/mundial-en-linares-ronda-5\/#primaryimage","url":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/Imagen-de-WhatsApp-2025-11-20-a-las-19.07.38_337da30b.jpg","contentUrl":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/Imagen-de-WhatsApp-2025-11-20-a-las-19.07.38_337da30b.jpg","width":2048,"height":1366},{"@type":"BreadcrumbList","@id":"https:\/\/feda.org\/feda2k16\/mundial-en-linares-ronda-5\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/feda.org\/feda2k16\/"},{"@type":"ListItem","position":2,"name":"Mundial en Linares: ronda 5."}]},{"@type":"WebSite","@id":"https:\/\/feda.org\/feda2k16\/#website","url":"https:\/\/feda.org\/feda2k16\/","name":"FEDA","description":"Federaci\u00f3n Espa\u00f1ola de Ajedrez","publisher":{"@id":"https:\/\/feda.org\/feda2k16\/#organization"},"alternateName":"Federaci\u00f3n Espa\u00f1ola de Ajedrez","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/feda.org\/feda2k16\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/feda.org\/feda2k16\/#organization","name":"FEDA","alternateName":"Federaci\u00f3n Espa\u00f1ola de Ajedrez","url":"https:\/\/feda.org\/feda2k16\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/logo\/image\/","url":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/NuevoLogo_FEDA_2016.png","contentUrl":"https:\/\/feda.org\/feda2k16\/wp-content\/uploads\/NuevoLogo_FEDA_2016.png","width":600,"height":600,"caption":"FEDA"},"image":{"@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/federacionespanoladeajedrez\/","https:\/\/x.com\/AjedrezEspanola","https:\/\/www.instagram.com\/federacionespanolaajedrez\/?hl=es","https:\/\/www.youtube.com\/@FederacionEspanoladeAjedrezFED\/featured"]},{"@type":"Person","@id":"https:\/\/feda.org\/feda2k16\/#\/schema\/person\/b39486343e189c77e58d02641385fe29","name":"elefante66","url":"https:\/\/feda.org\/feda2k16\/author\/elefante66\/"}]}},"_links":{"self":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts\/27358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/comments?post=27358"}],"version-history":[{"count":3,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts\/27358\/revisions"}],"predecessor-version":[{"id":27364,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/posts\/27358\/revisions\/27364"}],"wp:attachment":[{"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/media?parent=27358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/categories?post=27358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/feda.org\/feda2k16\/wp-json\/wp\/v2\/tags?post=27358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}